{"id":38115,"date":"2015-02-03T10:43:58","date_gmt":"2015-02-03T14:43:58","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=38115"},"modified":"2015-02-03T10:43:58","modified_gmt":"2015-02-03T14:43:58","slug":"jamaica-y-el-mundo-tienen-dos-visiones-diferentes-de-bob-marley","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/jamaica-y-el-mundo-tienen-dos-visiones-diferentes-de-bob-marley\/","title":{"rendered":"Jamaica y el mundo tienen dos visiones diferentes de Bob Marley"},"content":{"rendered":"<div id=\"attachment_38116\" style=\"width: 358px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-38116\" class=\"wp-image-38116 size-full\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/bob-marley.jpg\" alt=\"bob marley\" width=\"348\" height=\"232\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/bob-marley.jpg 348w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/bob-marley-300x200.jpg 300w\" sizes=\"auto, (max-width: 348px) 100vw, 348px\" \/><p id=\"caption-attachment-38116\" class=\"wp-caption-text\">Bob Marley<\/p><\/div>\n<p>La imagen que se tiene de Bob Marley en su tierra natal dista mucho de la que existe en el resto del mundo, donde no s\u00f3lo es el m\u00e1ximo exponente del reggae, sino tambi\u00e9n del movimiento rastafari, del consumo de marihuana y de Jamaica en s\u00ed.<!--more--><\/p>\n<p>As\u00ed coinciden en apuntar distintos expertos jamaiquinos consultados por Efe, entre ellos Ray Hitchins, profesor de la Unidad de Estudios de Reggae del Instituto de Estudios del Caribe, de la Universidad jamaiquina de West Indies.<\/p>\n<p>\u00abMientras en el extranjero se piensa que Bob Marley es una superestrella, en Jamaica es visto a la par que muchos otros artistas del g\u00e9nero\u00bb, explica en conversaci\u00f3n telef\u00f3nica este experto.<\/p>\n<p>\u00abDebemos entender que los jamaiquinos no tienen la mentalidad de superestrellas. Aqu\u00ed las celebridades no se ponen en un pedestal, como ocurre en otras partes del mundo\u00bb, a\u00f1ade.<\/p>\n<p>Efectivamente, los jamaiquinos son conscientes del tir\u00f3n tur\u00edstico y promocional que tiene la figura del fallecido Bob Marley, que el pr\u00f3ximo viernes hubiera cumplido 70 a\u00f1os, y saben que es su ciudadano m\u00e1s conocido a nivel internacional.<\/p>\n<p>Sin embargo, con ojos extranjeros, resultan escasos los festejos programados en la isla para homenajear el natalicio de Marley, que muri\u00f3 a los 36 a\u00f1os sin haber siquiera publicado a\u00fan \u00abLegend\u00bb (1984), el \u00e1lbum de reggae m\u00e1s vendido de todos los tiempos, con m\u00e1s de 25 millones de copias en todo el mundo.<\/p>\n<p>Un simposio en el Museo de Bob Marley, con presencia de expertos y familiares el mismo d\u00eda 6, fecha de su cumplea\u00f1os, y un multitudinario concierto el d\u00eda 7, son los dos \u00fanicos grandes actos oficiales programados en Jamaica.<\/p>\n<p>Y es que, a nivel nacional, el cantante jamaiquino comparte el reconocimiento de ser un buen exponente del g\u00e9nero junto con otros muchos artistas locales, que trataron temas similares en sus letras, como Dennis Brown, Gregory Isaacs, Peter Tosh -que form\u00f3 parte de Bob Marley &amp; The Wailers- y John Holt.<\/p>\n<p>Sin embargo, la visi\u00f3n del productor brit\u00e1nico Chris Blackwell ayud\u00f3 a catapultar la imagen y m\u00fasica de la leyenda del reggae, al distinguirlo de los dem\u00e1s al comercializar sus temas a nivel internacional.<\/p>\n<p>\u00abUno de los mayores atractivos de la historia de Bob Marley es su propia historia: su origen humilde y c\u00f3mo transmit\u00eda su esencia, porque eso lo hizo conectar con las masas fuera de su pa\u00eds, mientras que en Jamaica no llamaba tanto la atenci\u00f3n\u00bb, expres\u00f3 Hitchins.<\/p>\n<p>El experto en etnomusicolog\u00eda enfatiz\u00f3 que con su primer \u00e1lbum \u00abCatch a Fire\u00bb, Bob Marley y su grupo cobraron notoriedad al presentar canciones que desafiaban el statu quo en tiempos en que se daban m\u00faltiples movimientos de descolonizaci\u00f3n en el mundo.<\/p>\n<p>\u00ab\u00c9l era pol\u00edticamente consciente. Estaba adelantado a su tiempo\u00bb, dijo, tras destacar el hecho de que el m\u00fasico abordara el asunto de la supremac\u00eda blanca a partir de la publicaci\u00f3n de su primer \u00e1lbum en 1972, justo una d\u00e9cada despu\u00e9s de que Jamaica se independizara del Reino Unido.<\/p>\n<p>De hecho, el cantante fue uno de los primeros artistas de reggae en admitir p\u00fablicamente que era rastafari, una religi\u00f3n que promueve la supremac\u00eda negra y las ra\u00edces africanas, y lo dej\u00f3 ver en sus temas.<\/p>\n<p>Ello quiz\u00e1 no le ayud\u00f3 a ganarse a todo el p\u00fablico nacional, donde los rastafaris a\u00fan eran discriminados, pero s\u00ed a nivel internacional, donde se sab\u00eda poco sobre este movimiento.<\/p>\n<p>A juicio del experto, Bob Marley es m\u00e1s famoso ahora que antes de fallecer, en 1981, y ello se debe en gran parte a la comercializaci\u00f3n sistem\u00e1tica -promovida por su propia familia- de su imagen hasta convertirlo en un \u00absin\u00f3nimo de Jamaica\u00bb.<\/p>\n<p>La venta de camisas, \u00e1lbumes y hasta productos como caf\u00e9 y cannabis bajo la marca de Bob Marley son, en opini\u00f3n de Hitchins, un indicio de que su popularidad continuar\u00e1 en ascenso.<\/p>\n<p>\u00abSu legado no est\u00e1 completo. Su influencia a\u00fan crece y se expande. A\u00fan no ha alcanzado su m\u00e1ximo potencial\u00bb, defiende.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La imagen que se tiene de Bob Marley en su tierra natal dista mucho de la que existe en el resto del mundo, donde no s\u00f3lo es el m\u00e1ximo exponente del reggae, sino tambi\u00e9n del movimiento rastafari, del consumo de marihuana y de Jamaica en s\u00ed.<\/p>\n","protected":false},"author":12,"featured_media":38116,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-38115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=38115"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38115\/revisions"}],"predecessor-version":[{"id":38117,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38115\/revisions\/38117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/38116"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=38115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=38115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=38115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}