{"id":38390,"date":"2015-02-09T15:00:29","date_gmt":"2015-02-09T19:00:29","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=38390"},"modified":"2015-02-09T03:57:49","modified_gmt":"2015-02-09T07:57:49","slug":"10-mentiras-que-nadie-deberia-creerse","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/10-mentiras-que-nadie-deberia-creerse\/","title":{"rendered":"10 mentiras que nadie deber\u00eda creerse"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/mentiras_que_nadie_deberia_creerse_ok.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38396 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/mentiras_que_nadie_deberia_creerse_ok.jpg\" alt=\"mentiras_que_nadie_deberia_creerse_ok\" width=\"600\" height=\"352\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/mentiras_que_nadie_deberia_creerse_ok.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/mentiras_que_nadie_deberia_creerse_ok-300x176.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><br \/>\nEn muchas ocasiones cuando te enfrentas a diversas situaciones que sientes que no puedes resolver por otros medios, sueles recurrir a \u201ctergiversar la verdad\u201d, no s\u00f3lo hacia los dem\u00e1s sino, peor, para ti mismo, pero hay mentiras que se dicen que nadie deber\u00eda creer, ya que a la larga afectan.<!--more--><\/p>\n<p>De acuerdo con el psic\u00f3logo Robert Feldeman de la University of Massachusetts\u00a0el mentir est\u00e1 vinculado con la autoestima.<\/p>\n<blockquote><p>Tal parece que en cuanto las personas sienten que su autoestima se ve amenazada, inmediatamente comienzan\u00a0 a mentir en niveles altos\u201d<\/p><\/blockquote>\n<p>Feldeman afirma que los seres humanos est\u00e1n \u201ccableados\u201d para enga\u00f1arse a s\u00ed mismos y a los dem\u00e1s, est\u00e1n tan comprometidas con c\u00f3mo los perciben los dem\u00e1s que a menudo son capaces de separar la verdad de la ficci\u00f3n en sus propias mentes.<\/p>\n<h1>Mentiras que paralizan<\/h1>\n<p>Si bien en ocasiones se \u201ctergiversa la verdad\u201d porque las personas creen que seprotegen a s\u00ed mismas (o a los dem\u00e1s), existen aquellas que corroen la confianza en s\u00ed mismo y que impiden hacer las cosas que se anhelan.<\/p>\n<p>Con base en las aportaciones de Stephen Guise, sic\u00f3logo y escritor de\u00bbMini Habits\u00bb, te compartimos algunas de esas mentiras que se dicen que nadie deber\u00eda creer si no quiere quedarse paralizado.<\/p>\n<p>1. El mundo est\u00e1 contra m\u00ed. Esto en realidad no est\u00e1 ni a favor ni en contra, t\u00fa eres quien ense\u00f1a al mundo c\u00f3mo quieres ser tratado. No te detengas ante esta idea, sigue intent\u00e1ndolo.<\/p>\n<p>2. Soy demasiado viejo (o joven) para hacer algo. La misma historia demuestra que no hay edad determinada para alcanzar lo que realmente se desea, por lo que esta mentira lo \u00fanico que hace es funcionar como excusa.<\/p>\n<p>3. No puedo cambiar. \u201cCambiar es posible si en verdad se desea\u201d, cuando las personas tratan de hacer esto quitando todo a la vez, no funciona, en cambio si se realiza de manera met\u00f3dica, con el tiempo las cosas saldr\u00e1n bien.<\/p>\n<p>4. Necesito motivaci\u00f3n para actuar. Mentira, porque la primera no precede a la segunda; en realidad la motivaci\u00f3n es algo que siempre est\u00e1 presente, aunque en momentos de depresi\u00f3n pueda ser complicado, s\u00f3lo debe reconocerse.<\/p>\n<p>5. Soy una v\u00edctima. El autor explica que decir esto en el momento presente b\u00e1sicamente est\u00e1 mal usado, ya que puedes haber sido una v\u00edctima, s\u00ed, pero en el pasado. Ahora que te encuentras con la total libertad de elegir, es una mentira que lo hagas creer as\u00ed.<\/p>\n<p>6. Intentar es in\u00fatil. Cuando nos sentimos frustrados tendemos a expresar esta mentira, incluso a quienes se las decimos tratamos de convencerlas con argumentosde fracasos pasados, pero la \u00fanica manera de llegar a la meta es intentarlo siempre.<\/p>\n<p>7. Soy mejor (peor) que los dem\u00e1s. Las personas son clasificadas por su altura, peso, raza, entre otras, sin embargo todos somos humanos; contamos con diferentes atributos, habilidades y destrezas que nos hacen \u00fanicos.<\/p>\n<p>8. Lo que necesito para ser feliz. Una de las mentiras m\u00e1s comunes que solemos manejar con nosotros mismos y los dem\u00e1s es que una cierta lista de cosas es lo que puede hacernos felices, el autor apunta que desde su punto de vista la alegr\u00eda es lo \u00fanico que realmente se necesita.<\/p>\n<p>9. Cinco minutos m\u00e1s. En las ma\u00f1anas es com\u00fan pensar que un poco de tiempo m\u00e1s en la cama ayudar\u00e1 a que el d\u00eda sea mejor, esto realmente no es as\u00ed, ya que inclusive investigaciones cient\u00edficas sugieren que esta pr\u00e1ctica hace m\u00e1s da\u00f1o que bien.<\/p>\n<p>10. Todas las personas son iguales. Si eres de los que creen que \u201ctodos los hombres (mujeres) son iguales\u201d u otros ejemplos de este tipo, est\u00e1s creyendo y usando una mentira de estereotipo. De seguir con ella podr\u00edas perderte de conocer a quienes no son como t\u00fa lo expresas.<\/p>\n<p>Todas estas, y otras mentiras que se dicen que nadie deber\u00eda creer, son recurrentes porque siempre ser\u00e1n m\u00e1s f\u00e1cil que luchar con la verdad, para que \u00e9sta se crea se necesitan pruebas y esfuerzo, por lo que es mejor evitarla. Pero al hacerlo puedes estarte causando un gran da\u00f1o, med\u00edtalo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En muchas ocasiones cuando te enfrentas a diversas situaciones que sientes que no puedes resolver por otros medios, sueles recurrir a \u201ctergiversar la verdad\u201d, no s\u00f3lo hacia los dem\u00e1s sino, peor, para ti mismo, pero hay mentiras que se dicen que nadie deber\u00eda creer, ya que a la larga afectan.<\/p>\n","protected":false},"author":12,"featured_media":38396,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-38390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=38390"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38390\/revisions"}],"predecessor-version":[{"id":38397,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38390\/revisions\/38397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/38396"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=38390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=38390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=38390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}