{"id":38405,"date":"2015-02-09T10:56:15","date_gmt":"2015-02-09T14:56:15","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=38405"},"modified":"2015-02-09T10:56:15","modified_gmt":"2015-02-09T14:56:15","slug":"4-razones-que-te-haran-querer-pasar-menos-tiempo-frente-al-televisor","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/4-razones-que-te-haran-querer-pasar-menos-tiempo-frente-al-televisor\/","title":{"rendered":"4 razones que te har\u00e1n querer pasar menos tiempo frente al televisor"},"content":{"rendered":"<header>\n<p class=\"title entry-title\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/mucho-frente-a-la-tv.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38407 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/mucho-frente-a-la-tv.jpg\" alt=\"mucho frente a la tv\" width=\"259\" height=\"194\" \/><\/a>Por a\u00f1os los padres han luchado para que sus hijos pasen menos horas frente al televisor y m\u00e1s tiempo al aire libre. Sin embargo, la tecnolog\u00eda y la gran variedad de producciones audiovisuales han convertido esta batalla en una pelea m\u00e1s que dif\u00edcil.<\/p>\n<\/header>\n<p><!--more--><\/p>\n<section class=\"entry\">Los m\u00e9dicos y especialistas han hecho su parte y se han encargado de descifrar una serie de consecuencias que trae el abusar de la televisi\u00f3n. Seg\u00fan se\u00f1ala el diario electr\u00f3nico The Huffington Post, una persona suele pasar tres horas diarias viendo televisi\u00f3n, lo que incrementa el riesgo de padecer enfermedades del coraz\u00f3n, sobrepeso, diabetes.<\/p>\n<p><strong>\u201cPasar muchas horas viendo televisi\u00f3n provoca casi los mismos efectos en el cuerpo que el tabaquismo, colesterol alto o sufrir de presi\u00f3n arterial. Esto porque fomenta el sedentarismo\u201d, afirma dice Stephen Kopecky, m\u00e9dico cardi\u00f3logo y profesor de medicina en Mayo Clinic,en declaraciones recogidas por el portal especializado Salud 180.<\/strong><\/p>\n<p>Pero no s\u00f3lo consecuencias f\u00edsica trae este h\u00e1bito sino tambi\u00e9n problemas emocionales y mentales. Revisa a continuaci\u00f3n algunas consecuencias de este problema.<\/p>\n<p><strong>Depresi\u00f3n<br \/>\n<\/strong>Pasar mucho tiempo viendo televisi\u00f3n provoca en algunas personas aislamiento y soledad, especialmente en aquellos que tienen una personalidad inestable y de por s\u00ed solitaria.<\/p>\n<p>A esto se suma que tambi\u00e9n existe la posibilidad que algunos programas con temas o personajes con complicaciones emocionales, pueden terminar influyendo negativamente en el \u00e1nimo de uno de sus televidentes, quienes se involucran demasiado en sus historias.<\/p>\n<p>Seg\u00fan un estudio realizado por Yoon Sung, un investigador de la Universidad de Texas, pasar mucho tiempo viendo televisi\u00f3n -o en su defecto Netflix-, podr\u00eda terminar provocando depresi\u00f3n, ya que muchas personas usan estos programas para refugiarse y bloquear sus propios sentimientos y realidad.<\/p>\n<p>\u201cLos adictos a los programas de televisi\u00f3n llegan a descuidar su trabajo y relaciones con familiares o amigos. A pesar de estar conscientes de ello, les es dif\u00edcil resistir el deseo de ver episodios continuamente\u201d, dice Sung.<\/p>\n<p><strong>Obesidad<br \/>\n<\/strong>Uno de los problemas m\u00e1s comunes y conocidos de pasar mucho tiempo frente a la TV es la obesidad, y as\u00ed lo demostr\u00f3 un estudio de realizado por investigadores de la Harvard School of Public Health.<\/p>\n<p>Seg\u00fan la investigaci\u00f3n, los ni\u00f1os tienen m\u00e1s probabilidades de aumentar de peso cuando tienen la televisi\u00f3n en su pieza, ya que no s\u00f3lo no realizan actividad f\u00edsica, sino que tambi\u00e9n tienden a consumir m\u00e1s calor\u00edas de las recomendadas al d\u00eda. Esto \u00faltimo se debe a que al estar desocupado les da m\u00e1s hambre y la publicidad de alimentos poco saludables y bebidas azucaradas los incitan a preferir estos alimentos en lugar de comida saludable.<\/p>\n<p>Por su parte, el art\u00edculo tambi\u00e9n se\u00f1ala que \u201clas mujeres que pasan dos horas al d\u00eda viendo sus programas favoritos tienen 23% m\u00e1s riesgo de sufrir obesidad, comparadas con quienes no lo hacen\u201d.<\/p>\n<p><strong>Diabetes tipo 2<br \/>\n<\/strong>Una de las consecuencias m\u00e1s peligrosas de pasar un tiempo prolongado viendo TV, es que existen m\u00e1s de probabilidades de desarrollar diabetes tipo 2, seg\u00fan consigna un estudio publicado en el Journal of the American Medical Association.<\/p>\n<p>La investigaci\u00f3n afirma que \u201cpor cada dos horas adicionales que se pasa frente al televisor, el riesgo de desarrollar diabetes tipo 2 aumenta un 20%\u201d, consigna la publicaci\u00f3n.<\/p>\n<p>Esto se deber\u00eda a que permanecer sentado por varias generar\u00eda cambios nocivos en la sensibilidad a la insulina y el metabolismo de las grasas. A lo cual se suma que los adictos a la televisi\u00f3n dejan de dar 1500 pasos al d\u00edas.<\/p>\n<p><strong>Vista cansada<br \/>\n<\/strong>Muchas horas de ver televisi\u00f3n generan fatiga visual y dolores de cabeza, as\u00ed lo confirma Norman Saffra, presidente de oftalmolog\u00eda del Centro M\u00e9dico Maimonides en Brooklyn, Nueva York<\/p>\n<p>Estos problemas aumentan cuando se prefiere ver TV con la luz apagada, por lo que la recomendaci\u00f3n es encender la luz y descansar la vista durante los comerciales.<\/p>\n<p><strong>Si bien los m\u00e9dicos no llaman a dejar de ver televisi\u00f3n por completo, s\u00ed recomiendan disminuir a la cuota a dos horas por d\u00eda, aumentar la actividad f\u00edsica y preferir comidas saludables para acompa\u00f1ar un buen programa.<\/strong><\/p>\n<p>Fuente: <strong>BioBioChile<\/strong><\/p>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Por a\u00f1os los padres han luchado para que sus hijos pasen menos horas frente al televisor y m\u00e1s tiempo al aire libre. Sin embargo, la tecnolog\u00eda y la gran variedad de producciones audiovisuales han convertido esta batalla en una pelea m\u00e1s que dif\u00edcil.<\/p>\n","protected":false},"author":12,"featured_media":38407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-38405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=38405"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38405\/revisions"}],"predecessor-version":[{"id":38408,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38405\/revisions\/38408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/38407"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=38405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=38405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=38405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}