{"id":38414,"date":"2015-02-09T23:44:56","date_gmt":"2015-02-10T03:44:56","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=38414"},"modified":"2015-02-10T01:22:51","modified_gmt":"2015-02-10T05:22:51","slug":"jesucristo-cuando-nos-arrebataron-un-sosuense","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/jesucristo-cuando-nos-arrebataron-un-sosuense\/","title":{"rendered":"Jesucristo \u00abcuando nos arrebataron un sosuense\u00bb"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/Jesuscrito-desaparecido-en-la-epoca-de-balaguer1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-38441 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/Jesuscrito-desaparecido-en-la-epoca-de-balaguer1.jpg\" alt=\"Jesuscrito desaparecido en la epoca de balaguer\" width=\"263\" height=\"298\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/Jesuscrito-desaparecido-en-la-epoca-de-balaguer1.jpg 1308w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/Jesuscrito-desaparecido-en-la-epoca-de-balaguer1-264x300.jpg 264w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/Jesuscrito-desaparecido-en-la-epoca-de-balaguer1-903x1024.jpg 903w\" sizes=\"auto, (max-width: 263px) 100vw, 263px\" \/><\/a><br \/>\nAquella calurosa tarde del 23 de agosto de 1971 los mensajeros de la muerte del balaguerato visitaron Sos\u00faa. En aquellos a\u00f1os Sos\u00faa era un caser\u00edo co<span class=\"text_exposed_show\">n m\u00e1s de aldea apacible que de pueblo. Sus callecitas, empedradas y afirmadas con caliche, todav\u00eda no so\u00f1aban siquiera con el privilegio de ser llamadas propiamente calles. <!--more-->La vida de la gente sencilla que por aquel entonces habitaba el poblado depend\u00eda de las dos industrias fundadas por la colonia jud\u00eda en el sector llamado El Batey: la f\u00e1brica de quesos o Cilca y La Industrial Ganadera, dedicada a la elaboraci\u00f3n de productos derivados de la carne. La escuela primaria, el cuartelito de los bomberos, cuya sirena tocada al mediod\u00eda estremec\u00eda el pueblo de punta a punta, la oficina de Educaci\u00f3n y el cuartel de la Polic\u00eda Nacional, ubicado al comenzar la calle Eugenio Kunhartd, al lado de la mata de gu\u00e1sima, la iglesia cat\u00f3lica y el Templo B\u00edblico. Esto era Los Charamicos, el \u201ccasco urbano\u201d y zona m\u00e1s populosa de Sos\u00faa. Del otro lado, hacia el este, estaba El Batey, lugar en el cual se encontraban las dos citadas industrias, el consultorio m\u00e9dico del Dr. Na\u00f3n Garc\u00eda, la \u201cFarmacia de los Jud\u00edos\u201d, el Colegio \u201cCrist\u00f3bal Col\u00f3n\u201d o \u201cEl Colegio de los Jud\u00edos\u201d, y ya. Los caserones de los colonos se encontraban diseminados por las calles, tambi\u00e9n empedradas, del sector El Batey. Un par de autom\u00f3viles hac\u00edan la ruta Sos\u00faa-Santiago y unos pocos m\u00e1s viajaban desde Sos\u00faa hasta la ciudad de Puerto Plata. Aquel fue el Sos\u00faa al que llegaron los esbirros de la \u201cBanda Color\u00e1\u201d aquella bochornosa tarde de agosto.<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>Radham\u00e9s Almonte (Mem\u00e9 o Jesucristo, debido a la barba que le ensuciaba el rostro) era un muchach\u00f3n a quien la izquierda hab\u00eda sonsacado, llegando a formar parte del Movimiento Popular Dominicano (MPD). Vino al mundo como consecuencia de unos amor\u00edos que mi t\u00edo Pedro Llibre hab\u00eda sostenido con una muchacha llamada Isabel Almonte. El muchacho, era, como que se llamaba por aquellos a\u00f1os, un hijo \u201cnatural\u201d y en consecuencia no se cri\u00f3 bajo la tutela de su padre. Claro que t\u00edo Pedro sab\u00eda que \u00e9ste era su hijo.<\/p>\n<p>Jesucristo hab\u00eda sido captado por los emepede\u00edstas mientras estudiaba en el Liceo Jos\u00e9 Dubeau, de Puerto Plata, donde se vio obligado a ir a estudiar debido a la inexistencia de un plantel de educaci\u00f3n media en el Sos\u00faa de aquel entonces. Dicen sus compa\u00f1eros y amigos de generaci\u00f3n que ya hab\u00eda sido advertido para que tomara precauciones, pues se rumoraba que lo estaban vigilando. Los que le conocieron atestiguan que Jesucristo ten\u00eda un defecto que no compaginaba con la actividad pol\u00edtica: la candidez. Quiz\u00e1s no tuvo el alcance para comprender con qui\u00e9n se estaba metiendo: nada m\u00e1s y nada menos que con el heredero del sector m\u00e1s atrasado y recalcitrante de la sociedad dominicana post trujillista; un hombre que no paraba mientes con tal de mantenerse encaramado en el Palacio.<\/p>\n<p>Aquel aciago d\u00eda, un camarada puertoplate\u00f1o, quien seg\u00fan los testigos del suceso hizo de Judas, hab\u00eda venido a Sos\u00faa en diligencias pol\u00edticas. Luego de haber pasado todo el d\u00eda juntos, llegando incluso a comer en la casa de do\u00f1a Isabel, al llegar el atardecer, el traidor le pidi\u00f3 a Mem\u00e9 que fuera a encaminarlo hasta la carretera que conduc\u00eda a Puerto Plata, donde tomar\u00eda un carro. Siempre de acuerdo con los testigos, cuando alcanzaron la carretera, justo donde los carritos que hacen la ruta Sos\u00faa-Puerto Plata toman pasajeros actualmente, el compa\u00f1ero sigui\u00f3 caminando, como al descuido, alej\u00e1ndose de la entrada de Los Charamicos. Estando distantes unos docenas de metros en direcci\u00f3n hacia Puerto Plata, justo enfrente de la entrada a Los Cerros y pr\u00f3ximos a la casa de Rafael Capell\u00e1n, ocurri\u00f3.<\/p>\n<p>Como brotado de la nada apareci\u00f3 un carro con dos individuos a bordo. Se desmontaron los tripulantes, intentando meter a Jesucristo por la fuerza en el auto. El hijo de t\u00edo Pedro se resisti\u00f3, inici\u00e1ndose un forcejeo. Alguien se percat\u00f3 y corri\u00f3 hasta el cercano cuartel de la polic\u00eda. Una vez all\u00ed, alert\u00f3 al comandante del destacamento, el teniente Mart\u00ednez, de lo que estaba ocurriendo. Siempre de acuerdo con los testigos, el teniente sali\u00f3 precipitadamente, acompa\u00f1ado del raso Julio G\u00f3mez quien portaba una carabina \u201cSan Crist\u00f3bal\u201d. Cuando llegaron a la escena, ya uno de los bandoleros le hab\u00eda propinado un maquinazo en la cabeza a Jesucristo, quien sangraba profusamente. Cuando el oficial policial inquiri\u00f3 que \u201cqu\u00e9 pasa aqu\u00ed?\u201d uno de los matones le dijo: \u201cteniente, no se meta en esto!\u201d y dicen que al mostrarle un carn\u00e9, el teniente Mart\u00ednez recul\u00f3. Relatan los testigos que entonces Jesucristo le pidi\u00f3 al oficial: \u201cteniente, no dejen que me lleven!\u201d, y que \u00e9ste repleg\u00e1ndose exclam\u00f3: \u201cyo no puedo hacer nada.. No puedo\u2026\u201d Finalmente, Radham\u00e9s Almonte fue introducido en el carro, el cual parti\u00f3 veloz, en direcci\u00f3n a Puerto Plata.<\/p>\n<p>Es de imaginar el revuelo que causar\u00eda aquel acto en un pueblecito como aquel. Algunos osados, salieron tras el carro de los esbirros en veh\u00edculos y otros, como Rafael Capell\u00e1n \u2013 otro Rafael Capell\u00e1n, compa\u00f1ero de partido de Mem\u00e9 y no el due\u00f1o de la casa frente a la cual se escenific\u00f3 el secuestro-, a bordo de una motocicleta de manufactura italiana tipo \u201cVespa\u201d. Nada lograron. Los familiares del muchacho, con t\u00edo Pedro a la cabeza removieron cielo y tierra en busca del secuestrado sin el m\u00e1s m\u00ednimo resultado. Pareci\u00f3 como si a Jesucristo se lo hubiese tragado la tierra. No se logr\u00f3 la menor informaci\u00f3n sobre su paradero, ni vivo ni muerto. Para los sosuenses viejos aquel acto cobarde y ruin qued\u00f3 como se\u00f1al inequ\u00edvoca de la perversidad de un r\u00e9gimen que practic\u00f3 el m\u00e1s deleznable de los cr\u00edmenes: la desaparici\u00f3n.<\/p>\n<div id=\"attachment_38421\" style=\"width: 264px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/eduardo-llibre.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-38421\" class=\"wp-image-38421\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/eduardo-llibre.jpg\" alt=\"eduardo llibre\" width=\"254\" height=\"222\" \/><\/a><p id=\"caption-attachment-38421\" class=\"wp-caption-text\">Jesucristo \u00abcuando nos arrebataron un sosuense\u00bb Por: Eduardo Llibre<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aquella calurosa tarde del 23 de agosto de 1971 los mensajeros de la muerte del balaguerato visitaron Sos\u00faa. En aquellos a\u00f1os Sos\u00faa era un caser\u00edo con m\u00e1s de aldea apacible que de pueblo. Sus callecitas, empedradas y afirmadas con caliche, todav\u00eda no so\u00f1aban siquiera con el privilegio de ser llamadas propiamente calles.<\/p>\n","protected":false},"author":12,"featured_media":38441,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83,311],"tags":[],"class_list":["post-38414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=38414"}],"version-history":[{"count":4,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38414\/revisions"}],"predecessor-version":[{"id":38443,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38414\/revisions\/38443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/38441"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=38414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=38414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=38414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}