{"id":38626,"date":"2015-02-12T18:39:41","date_gmt":"2015-02-12T22:39:41","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=38626"},"modified":"2015-02-12T18:42:28","modified_gmt":"2015-02-12T22:42:28","slug":"pondran-oscar-de-la-renta-a-calle-de-nueva-york","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/pondran-oscar-de-la-renta-a-calle-de-nueva-york\/","title":{"rendered":"Pondr\u00e1n Oscar de la Renta a calle de Nueva York"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/oscar-de-la-renta.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38632 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/oscar-de-la-renta.jpg\" alt=\"oscar de la renta\" width=\"300\" height=\"226\" \/><\/a>Una de las calles de Nueva York, Estados Unidos, llevar\u00e1 el nombre del dise\u00f1ador dominicano Oscar de la Renta, quien falleci\u00f3 en octubre del a\u00f1o pasado, tras perder su batalla contra el c\u00e1ncer.<!--more--><\/p>\n<p>La informaci\u00f3n\u00a0 la dio a conocer el alcalde de Nueva York, Bill DeBlasio, durante en un evento de prensa realizado para promover la inversi\u00f3n de la ciudad en la industrial fashion local, de acuerdo con una publicaci\u00f3n del portal E! NEWS.<\/p>\n<p>El Boulevard Oscar de la Renta estar\u00e1 localizado en el Bronx, en la intersecci\u00f3n entre East Fordham Road y Creston Avenue, \u00a0seg\u00fan se\u00f1ala el portal, que cita al Women\u2019s Wear Daily.<\/p>\n<p>Tras nacer en Rep\u00fablica Dominicana, de la Renta se mud\u00f3 a la ciudad de Nueva York en la d\u00e9cada de 1960 para trabajar con Elizabeth Arden. Desde entonces, Manhattan se convirti\u00f3 en un su hogar base, pero al momento de su fallecimiento se encontraba en su residencia de Connecticut junto a su familia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una de las calles de Nueva York, Estados Unidos, llevar\u00e1 el nombre del dise\u00f1ador dominicano Oscar de la Renta, quien falleci\u00f3 en octubre del a\u00f1o pasado, tras perder su batalla contra el c\u00e1ncer.<\/p>\n","protected":false},"author":12,"featured_media":38632,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-38626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=38626"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38626\/revisions"}],"predecessor-version":[{"id":38633,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38626\/revisions\/38633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/38632"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=38626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=38626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=38626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}