{"id":38661,"date":"2015-02-12T23:19:53","date_gmt":"2015-02-13T03:19:53","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=38661"},"modified":"2015-02-12T23:19:53","modified_gmt":"2015-02-13T03:19:53","slug":"hachiko-el-perro-mas-fiel-del-mundo-tendra-una-nueva-estatua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/hachiko-el-perro-mas-fiel-del-mundo-tendra-una-nueva-estatua\/","title":{"rendered":"Hachiko, el perro m\u00e1s fiel del mundo, tendr\u00e1 una nueva estatua"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-long field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<div id=\"attachment_38667\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hachiko.3_principal.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-38667\" class=\"size-full wp-image-38667\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hachiko.3_principal.jpg\" alt=\"Foto: sdpnoticias.com\" width=\"600\" height=\"450\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hachiko.3_principal.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hachiko.3_principal-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><p id=\"caption-attachment-38667\" class=\"wp-caption-text\">Foto: sdpnoticias.com<\/p><\/div>\n<p>Todos conocemos la <label>historia<\/label> de Hachiko (Hachi para algunos), el perro m\u00e1s fiel del mundo; quien esperaba que su due\u00f1o regresar\u00e1 del <label>trabajo<\/label>, el japon\u00e9s Hidesaburo Ueno, en la estaci\u00f3n de trenes. Un <label>d\u00eda<\/label> el <label>hombre<\/label> colaps\u00f3 mientras realizaba sus actividades y no regres\u00f3 a <label>casa<\/label>. La mascota, sin saber el destino de su due\u00f1o, lo sigui\u00f3 esperando hasta el d\u00eda de su muerte.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\" data-twttr-id=\"twttr-sandbox-0\">\n<p>Tal fue el impacto de la historia, que se le erigi\u00f3 un estatua al perro en la estaci\u00f3n de Shibuya, lugar donde se sentaba a esperar; esto como s\u00edmbolo de lealtad y fidelidad. Pues bien, despu\u00e9s de 80 a\u00f1os que se diera la singular historia, Hachi tendr\u00e1 una nueva estatua, la cual por fin lo reunir\u00e1 con su due\u00f1o.<\/p>\n<p>Ser\u00e1 instalada en la Universidad de Tokyo, a pedido expreso del Departamento de Agricultura de la instituci\u00f3n; lugar de trabajo de Ueno.<\/p>\n<p>Cuando est\u00e9 instalada la nueva pieza, el muy probable que reciba miles de vistantes, tal y como su hom\u00f3loga de Shibuya; por parte de nacionales y extranjeros que quedaron marcados por el relato de Hachiko.<\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/twitter-del-homenaje.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38669 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/twitter-del-homenaje.png\" alt=\"twitter del homenaje\" width=\"459\" height=\"449\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/twitter-del-homenaje.png 459w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/twitter-del-homenaje-300x293.png 300w\" sizes=\"auto, (max-width: 459px) 100vw, 459px\" \/><\/a><br \/>\nFuente: <a href=\"http:\/\/www.sdpnoticias.com\/sorprendente\/2015\/02\/11\/hachiko-el-perro-mas-fiel-del-mundo-tendra-una-nueva-estatua-en-japon\" target=\"_blank\">SDP Noticias<\/a> \/ VIC<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Todos conocemos la historia de Hachiko (Hachi para algunos), el perro m\u00e1s fiel del mundo; quien esperaba que su due\u00f1o regresar\u00e1 del trabajo, el japon\u00e9s Hidesaburo Ueno, en la estaci\u00f3n de trenes. Un d\u00eda el hombre colaps\u00f3 mientras realizaba sus actividades y no regres\u00f3 a casa. La mascota, sin saber el destino de su due\u00f1o, lo sigui\u00f3 esperando hasta el d\u00eda de su muerte.<\/p>\n","protected":false},"author":12,"featured_media":38667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-38661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=38661"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38661\/revisions"}],"predecessor-version":[{"id":38670,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38661\/revisions\/38670"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/38667"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=38661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=38661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=38661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}