{"id":38719,"date":"2015-02-13T14:43:42","date_gmt":"2015-02-13T18:43:42","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=38719"},"modified":"2015-02-13T14:43:42","modified_gmt":"2015-02-13T18:43:42","slug":"color-vision-forma-parte-del-adn-de-los-dominicanos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/color-vision-forma-parte-del-adn-de-los-dominicanos\/","title":{"rendered":"\u201cColor Visi\u00f3n forma parte del ADN de los dominicanos\u201d"},"content":{"rendered":"<div><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/final-laureano.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38722 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/final-laureano.png\" alt=\"final  laureano\" width=\"341\" height=\"213\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/final-laureano.png 341w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/final-laureano-300x187.png 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/final-laureano-400x250.png 400w\" sizes=\"auto, (max-width: 341px) 100vw, 341px\" \/><\/a>SANTO DOMINGO. \u00c1ngel Laureano lleva desde el 2002 como gerente de Producci\u00f3n del canal Color Visi\u00f3n, y acaba de ser designado director general del mismo. Hab\u00eda comenzado como coordinador de Producci\u00f3n.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<div><b>P. \u00bfQu\u00e9 es en este momento lo m\u00e1s relevante en Color Visi\u00f3n?<\/b><\/div>\n<div><b>R.\u00a0<\/b>Color Visi\u00f3n ha sido uno de los canales de mayor crecimiento hasta el 2014, y nosotros vamos por m\u00e1s. Vamos a seguir creciendo. Somos un canal que contamos con la mayor cantidad de talento dominicano. Vamos a seguir apostando al talento criollo, porque la televisi\u00f3n dominicana si te das cuenta, en los diferentes canales tiene muy poca participaci\u00f3n de producciones locales. Vamos a fortalecer la producci\u00f3n local, porque entendemos que hay mucho talento en el pa\u00eds.<\/p>\n<\/div>\n<div><b>P. \u00bfEn qu\u00e9 punto est\u00e1 la necesaria evoluci\u00f3n tecnol\u00f3gica en el canal?<\/b><\/div>\n<div><b>R.\u00a0<\/b>Te invito a conocer los estudios de Color Visi\u00f3n en cualquier momento. Tenemos instalada tecnolog\u00eda de punta, de primera, y estamos preparados para transmitir digital hasta la salida del transmisor. O sea hemos invertido en alta tecnolog\u00eda. Quiz\u00e1s no es p\u00fablico, porque es algo que cada canal debe hacer privadamente, pero tenemos la mejor calidad. T\u00fa puedes ver la transmisi\u00f3n de Color Visi\u00f3n, y ver\u00e1s que es n\u00edtida, que no tiene nada que envidiarle a ning\u00fan canal nacional, ni siquiera internacional.<\/p>\n<\/div>\n<div><b>P. En cuanto al contenido, la l\u00ednea de Color Visi\u00f3n, \u00bfc\u00f3mo Ud. la proyecta, en su calidad de director del canal?<\/b><\/div>\n<div><b>R.\u00a0<\/b>La l\u00ednea de contenido y la adquisici\u00f3n de programas y eso, la maneja siempre el se\u00f1or Domingo Berm\u00fadez, quien ha estado al frente del canal con esa parte. A esos acuerdos important\u00edsimos como es la adquisici\u00f3n de SIN, se suman movimientos muy importantes en la programaci\u00f3n, que han fortalecido el prime time, como es Mariasela a las 8:00 de la noche, Sigue la noche, a las 11; o sea todos los pasos que se han dado bajo el liderazgo de Domingo Bermudez en esta etapa han servido para seguir posicion\u00e1ndonos en el gusto de los dominicanos. Nunca dejando atr\u00e1s el talento local, como siempre fue el pensamiento de don Popy Berm\u00fadez cuando cre\u00f3 Color Visi\u00f3n con Manuel Quiroz, y con la l\u00ednea que tambi\u00e9n ha seguido Domingo Berm\u00fadez.<\/p>\n<\/div>\n<div><b>P. \u00bfY por qu\u00e9 el canal marca tan poco en el rating?<\/b><\/div>\n<div><b>R.\u00a0<\/b>Ha sido un proceso de crecimiento. No se puede mirar en estos momentos como \u201cque marca tan poco\u201d. Llegamos al 2015 con un crecimiento del 45% de Shart. No creo que sea marcar tan poco. O sea, nuestros horarios con producci\u00f3n local.<\/p>\n<\/div>\n<div><b>P. Recibo a diario los ratings, y no es lo que dicen.<\/b><\/div>\n<div><b>R.\u00a0<\/b>Color Visi\u00f3n es un canal que ha crecido durante el 2014 un 45%, y vamos a seguir creciendo. Eso es lo que te puedo decir. Apuesto a Color Visi\u00f3n, como cada dominicano. Los resultados se van a seguir viendo.<\/p>\n<\/div>\n<div><b>P. \u00bfCu\u00e1l es el target de p\u00fablico en el que m\u00e1s se est\u00e1n enfocando?<\/b><\/div>\n<div><b>R.\u00a0<\/b>La familia dominicana. Lo que ha determinado la audiencia es informaci\u00f3n, entretenimiento, telenovelas, pel\u00edculas. Eso es lo que el p\u00fablico est\u00e1 demandando, y nosotros queremos una programaci\u00f3n balanceada que toque cada uno de los puntos, desde infantil. Hemos analizado bastante bien a nuestra audiencia, y hemos determinado una atenci\u00f3n especial a cada una de esas franjas.<\/p>\n<\/div>\n<div><b>P. \u00bfSe esperan cambios?<\/b><\/div>\n<div><b>R.\u00a0<\/b>La televisi\u00f3n es una constante de cambios. Nosotros abrimos 2014 sin avisos de cambio, y gracias a una alianza estrat\u00e9gica que hizo Domingo Berm\u00fadez con SIN y otros programas, logramos cambiar totalmente la programaci\u00f3n. O sea en la televisi\u00f3n nunca se descartan los cambios para seguir cambiando.<\/div>\n<p>&nbsp;<\/p>\n<div>Color Visi\u00f3n forma parte del ADN de los dominicanos.<\/div>\n<div>(Alfonso Qui\u00f1ones-Diario Libre)<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO. \u00c1ngel Laureano lleva desde el 2002 como gerente de Producci\u00f3n del canal Color Visi\u00f3n, y acaba de ser designado director general del mismo. Hab\u00eda comenzado como coordinador de Producci\u00f3n.<\/p>\n","protected":false},"author":12,"featured_media":38722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-38719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=38719"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38719\/revisions"}],"predecessor-version":[{"id":38723,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38719\/revisions\/38723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/38722"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=38719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=38719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=38719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}