{"id":38780,"date":"2015-02-15T12:31:06","date_gmt":"2015-02-15T16:31:06","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=38780"},"modified":"2015-02-15T12:31:06","modified_gmt":"2015-02-15T16:31:06","slug":"que-tan-bueno-y-saludable-es-desayunar-ligero","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/que-tan-bueno-y-saludable-es-desayunar-ligero\/","title":{"rendered":"\u00bfQu\u00e9 tan bueno y saludable es desayunar ligero?"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-long field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/breakfast.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-38782 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/breakfast.jpg\" alt=\"breakfast\" width=\"312\" height=\"234\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/breakfast.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/breakfast-300x225.jpg 300w\" sizes=\"auto, (max-width: 312px) 100vw, 312px\" \/><\/a>Muchas personas consideran que desayunar ligero es lo m\u00e1s conveniente, sin embargo, alimentarse mal al inicio del <label>d\u00eda<\/label> s\u00f3lo provocar\u00e1 falta de energ\u00eda y hambre.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Quienes prefieren desayunar \u00fanicamente un plato de <label>cereal<\/label> deber\u00edan considerar que probablemente tienen que recurrir a la <label>comida chatarra<\/label> o a lo que tengan a la <label>mano<\/label> para deshacerse del hambre antes del medio d\u00eda.<\/p>\n<p>Las prote\u00ednas se digieren m\u00e1s lento que los carbohidratos por lo que desayunar un plato de cereal es insuficiente, un <label>huevo duro<\/label> podr\u00eda complementar ese desayuno; y no, no es da\u00f1ino al organismo.<\/p>\n<p>Entre m\u00e1s az\u00facar tenga el cereal, m\u00e1s r\u00e1pido se digiere. Es mejor que tenga por lo menos 5 gramos de fibra y que siempre sea m\u00e1s fibra que az\u00facar. Para aumentar el nivel de fibra se puede agregar ch\u00eda.<\/p>\n<p>Una comida sin grasa puede provocar hambre despu\u00e9s de una hora. Aquellos que comen en el desayuno un yogur sin grasa, cereal alto en fibra y fruta estar\u00e1n hambrientos pronto. La soluci\u00f3n a esto puede ser agregar nueces al yogurt.<\/p>\n<p>Aunque una pieza de fruta es rica en fibra, vitaminas y minerales, no es suficiente para el desayuno. Para llegar a la mitad del d\u00eda sin sufrir por el hambre se debe hacer un desayuno de 300 a 400 calor\u00edas.<\/p>\n<p>Lo recomendado es tener lapsos de 4 horas entre comidas. Mientras m\u00e1s largo sea el tiempo entre los alimentos, es m\u00e1s dif\u00edcil quedar satisfecho.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.ecoosfera.com\/2013\/03\/que-tan-bueno-y-saludable-es-desayunar-ligero\/\" target=\"_blank\">Ecosfera<\/a> \/ VIC<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Muchas personas consideran que desayunar ligero es lo m\u00e1s conveniente, sin embargo, alimentarse mal al inicio del d\u00eda s\u00f3lo provocar\u00e1 falta de energ\u00eda y hambre.<\/p>\n","protected":false},"author":12,"featured_media":38782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-38780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=38780"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38780\/revisions"}],"predecessor-version":[{"id":38783,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38780\/revisions\/38783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/38782"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=38780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=38780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=38780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}