{"id":38789,"date":"2015-02-15T14:15:18","date_gmt":"2015-02-15T18:15:18","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=38789"},"modified":"2015-02-15T14:15:18","modified_gmt":"2015-02-15T18:15:18","slug":"onamet-pronostica-lluvias-debiles-para-domingo-este-debido-a-vaguada","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/onamet-pronostica-lluvias-debiles-para-domingo-este-debido-a-vaguada\/","title":{"rendered":"Onamet pronostica lluvias d\u00e9biles para domingo este debido a vaguada"},"content":{"rendered":"<div><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/descarga.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38790 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/descarga.jpg\" alt=\"descarga\" width=\"180\" height=\"180\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/descarga.jpg 180w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/descarga-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/descarga-120x120.jpg 120w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/><\/a>Debido a la formaci\u00f3n de una vaguada colocada sobre Puerto Rico, la Oficina Nacional de Meteorolog\u00eda (Onamet) pronostic\u00f3 lluvias d\u00e9biles sobre y nublados ocasionales y r\u00e1fagas de vientos ocasionales en las principales provias del pa\u00eds.<!--more--><\/p>\n<p>Las provincias afectadas son: La Altagracia, La Romana, El Seibo Hato Mayor, Monte Plata, San Pedro, S\u00e1nchez Ram\u00edrez Duarte, Saman\u00e1, Mar\u00eda Trinidad S\u00e1nchez, Hermanas Mirabal, La Vega, Monse\u00f1or Nouel, Santiago, Puerto Plata, Montecristi, Dajab\u00f3n y Valverde.<\/p><\/div>\n<div><\/div>\n<div>Para el inicio de la semana laboral las lluvias disminuir\u00e1n debido a la incidencia de un sistema de alta presi\u00f3n el cual limitara las precipitaciones, present\u00e1ndose solo algunos chubascos aislados hacia las regiones noreste, sureste y la cordillera Central principalmente en la tarde y noche como consecuencia del viento que estar\u00e1 soplando del este\/noreste.<\/div>\n<div><\/div>\n<div>Las temperaturas se mantendr\u00e1n agradables especialmente en zonas de monta\u00f1as durante la noche y primeras horas del d\u00eda y para el gran Santo Domingo la temperatura m\u00e1xima estar\u00e1 entre 29\u00baC y 31\u00baC y la m\u00ednima entre 20\u00baC y 22\u00baC.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Debido a la formaci\u00f3n de una vaguada colocada sobre Puerto Rico, la Oficina Nacional de Meteorolog\u00eda (Onamet) pronostic\u00f3 lluvias d\u00e9biles sobre y nublados ocasionales y r\u00e1fagas de vientos ocasionales en las principales provias del pa\u00eds.<\/p>\n","protected":false},"author":12,"featured_media":38790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-38789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=38789"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38789\/revisions"}],"predecessor-version":[{"id":38791,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38789\/revisions\/38791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/38790"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=38789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=38789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=38789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}