{"id":38852,"date":"2015-02-16T11:21:01","date_gmt":"2015-02-16T15:21:01","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=38852"},"modified":"2015-02-16T11:22:46","modified_gmt":"2015-02-16T15:22:46","slug":"google-creo-un-equipo-de-hackers-para-amenazar-apple-y-microsoft","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/google-creo-un-equipo-de-hackers-para-amenazar-apple-y-microsoft\/","title":{"rendered":"Google cre\u00f3 un equipo de hackers para amenazar Apple y Microsoft"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hacker-google.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-38853 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hacker-google.jpg\" alt=\"MEMBER EXCHANGE-PEOPLE\" width=\"354\" height=\"213\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hacker-google.jpg 1025w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hacker-google-300x180.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hacker-google-1024x615.jpg 1024w\" sizes=\"auto, (max-width: 354px) 100vw, 354px\" \/><\/a> \u00a0Google les da un ultim\u00e1tum a sus colegas de la tecnolog\u00eda:<\/strong>corrijan las vulnerabilidades de su software en 90 d\u00edas o las daremos a conocer.<!--more--><\/p>\n<p><strong>Un equipo de \u00e9lite formado por hackers y programadores de Google<\/strong> escarba en el software propio y el de sus competidores buscando fallas de seguridad, y emplaza a las empresas para que las solucionen. G<strong>oogle quiere que las compa\u00f1\u00edas de software act\u00faen r\u00e1pido porque los ciberdelincuentes<\/strong> proceden con la velocidad del rayo cuando detectan problemas, dice.<\/p>\n<p>El tema es delicado. <strong>Rivales como Microsoft y Apple se negaron a hablar de la t\u00e1ctica,<\/strong> pero otros en el sector dicen que la ayuda no siempre es bienvenida, usurpa una funci\u00f3n que compete m\u00e1s al Estado y puede debilitar la seguridad.<\/p>\n<p>\u201cNo s\u00e9 qui\u00e9n convirti\u00f3 a Google en el \u00e1rbitro del mercado para la notificaci\u00f3n de vulnerabilidades\u201d, dijo John Dickson, director de la firma de seguridad Denim Group. Presionar a las empresas para que solucionen las fallas es buena idea, dijo, pero \u201cest\u00e1 por verse la nobleza de los motivos de Google, dado que b\u00e1sicamente revelaron vulnerabilidades de sus mayores rivales\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38854 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hackers.png\" alt=\"hackers\" width=\"650\" height=\"433\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hackers.png 650w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hackers-300x199.png 300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>Google cre\u00f3 el equipo en julio, y lo llam\u00f3 <strong>Project Zero<\/strong> por las temidas fallas de seguridad del \u201cd\u00eda cero\u201d que son aprovechadas <b>antes de que los desarrolladores las constaten<\/b>. Dice que se propone ayudar a todos, adem\u00e1s de proteger sus propios productos que funcionan en dispositivos y software de otros.<\/p>\n<p>Es una actividad que, a los ojos de algunos expertos, resulta m\u00e1s apropiada para un organismo p\u00fablico. El propio <strong>presidente Obama<\/strong> se refiri\u00f3 a la cooperaci\u00f3n entre el sector p\u00fablico y el privado en una cumbre sobre ciberseguridad realizada el viernes en Palo Alto, California.<\/p>\n<p>Algunos se preguntan, sin embargo, cu\u00e1nta cooperaci\u00f3n se puede esperar si las mayores empresas de Internet no pueden llevarse bien.<\/p>\n<p>Apple se neg\u00f3 a comentar Project Zero. Microsoft se limit\u00f3 a remitir a un comunicado previo el cual dec\u00eda que la t\u00e1ctica de Google se parece a un juego de <strong>\u201cgotcha<\/strong>\u201d (caracter\u00edstica de un programa que trabaja de un modo que es correcto desde el punto de vista formal pero no es lo que se espera de \u00e9l).<\/p>\n<p>Los detractores de la pr\u00e1ctica de Google dicen que pone en peligro la seguridad revelando grietas antes de que se las pueda tapar.<\/p>\n<p>Cuando se descubren problemas, los hackers se mueven r\u00e1pido para explotarlos. El a\u00f1o pasado, <b>intrusos apoyados por los chinos<\/b>aprovecharon el error de seguridad online conocido como <strong>Heartbleed para atacar el grupo hospitalario Community Health Systems<\/strong> m\u00e1s de una semana despu\u00e9s de que se diera a conocer la falla.<\/p>\n<p>En enero, <strong>Apple le pidi\u00f3 a Google que esperara una semana para que Apple solucionara tres fallas en el sistema operativo Mac OS X,<\/strong> seg\u00fan una fuente con conocimiento.<\/p>\n<p>Google sab\u00eda que la soluci\u00f3n ya llegaba, dijo la fuente. As\u00ed y todo, se neg\u00f3 y divulg\u00f3 detalles de las fallas.<\/p>\n<p>Por su parte <strong>Microsoft pidi\u00f3 dos d\u00edas de pr\u00f3rroga para arreglar una deficiencia en Windows. Google no se los dio y public\u00f3 el error.<\/strong><\/p>\n<p>\u201cLos que pueden salir perjudicados son los clientes\u201d, escribi\u00f3 Chris Betz, director del centro de respuestas a incidentes de seguridad de Microsoft, el 11 de junio en un blog, la \u00fanica referencia p\u00fablica al tema que hizo la firma hasta la fecha. \u201cLo que es bueno para Google no siempre es bueno para los clientes\u201d.<\/p>\n<p>Microsoft pide que los investigadores <b>revelen las fallas en forma privada<\/b> a los proveedores de software, y trabajar con ellos hasta contar con una soluci\u00f3n, dijo Betz.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-38855 alignright\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hacker.jpg\" alt=\"hacker\" width=\"275\" height=\"183\" \/>Los defensores de Google sostienen que el enfoque duro de Google puede alterar sustancialmente las pr\u00e1cticas de la industria del software, cuyas empresas llegan a tardar <b>meses o a\u00f1os<\/b> en encontrar parches para fallas.<\/p>\n<p>Seg\u00fan un an\u00e1lisis de Risk Based Security, Project Zero identific\u00f3 39 vulnerabilidades en productos de Apple y 22 en los de Microsoft. <strong>Tambi\u00e9n detect\u00f3 37 fallas en el software de Adobe.<\/strong>Y divulg\u00f3 detalles antes de que estuviese disponible una soluci\u00f3n <b>16 veces en el caso de Apple, tres con Microsoft y una con Adobe<\/b>.<\/p>\n<p>La \u201cestrictez de Google es buena para el sector\u201d, dijo Tom Gorup, gerente de Rook Security. \u201cUna persona com\u00fan no tiene la influencia de Google: si grandes empresas como Microsoft, Apple y Google pulsean por una mejora de la seguridad, todos salimos ganando\u201d.<\/p>\n<p>Google cre\u00f3 Project Zero despu\u00e9s de conocerse la falla Heartbleed y el espionaje de la Agencia Nacional de Seguridad de EE.UU. \u201cDeber\u00edamos poder usar la Web sin miedo a que un delincuente o alguien de parte de un gobierno aproveche fallas de software para infectar nuestras computadoras o robar secretos\u201d, dec\u00eda la entrada de blog del 15 de julio que anunciaba Project Zero. \u201cNuestra meta es reducir la cantidad de personas perjudicadas por ataques dirigidos\u201d.<\/p>\n<p>\u201cSi bien algunos utilizan ataques de d\u00eda cero para detectar v\u00edctimas, son muchos los atacantes que siguen abordando <b>vulnerabilidades conocidas para las cuales ya se han emitido parches<\/b>, aprovechando lo lento de los procesos de remiendo y las decisiones de riesgo de los due\u00f1os de redes, que no parchean ciertas vulnerabilidades\u201d, dijo el FBI en una alerta de fines de enero.<\/p>\n<p>Un plazo de 90 d\u00edas quiz\u00e1s no sea pr\u00e1ctico para grandes compa\u00f1\u00edas que tienen que examinar miles de l\u00edneas de c\u00f3digo y asegurarse de que los parches no afecten otro software en forma negativa, dijo Craig Young, investigador senior de seguridad de Tripwire.<\/p>\n<p>Pero tambi\u00e9n a veces las empresas son <b>negligentes<\/b>. \u201cHemos tenido muchos casos de proveedores que no parecen preocuparse por algo a menos que salga en los diarios\u201d, concluy\u00f3 Young.<\/p>\n<p><a href=\"http:\/\/www.ieco.clarin.com\/economia\/Google-Apple-Microsoft-exponer-seguridad_0_1304269854.html\" target=\"_blank\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Google les da un ultim\u00e1tum a sus colegas de la tecnolog\u00eda:corrijan las vulnerabilidades de su software en 90 d\u00edas o las daremos a conocer.<\/p>\n","protected":false},"author":12,"featured_media":38854,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-38852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=38852"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38852\/revisions"}],"predecessor-version":[{"id":38856,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38852\/revisions\/38856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/38854"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=38852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=38852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=38852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}