{"id":38880,"date":"2015-02-16T22:43:54","date_gmt":"2015-02-17T02:43:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=38880"},"modified":"2015-02-16T22:43:54","modified_gmt":"2015-02-17T02:43:54","slug":"google-aumenta-14-dias-el-plazo-de-publicacion-de-bugs-en-project-zero","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/google-aumenta-14-dias-el-plazo-de-publicacion-de-bugs-en-project-zero\/","title":{"rendered":"Google aumenta 14 d\u00edas el plazo de publicaci\u00f3n de bugs en Project Zero"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hacker-960x623.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-38893 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hacker-960x623.jpg\" alt=\"hacker-960x623\" width=\"694\" height=\"427\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hacker-960x623.jpg 960w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hacker-960x623-300x184.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/hacker-960x623-440x270.jpg 440w\" sizes=\"auto, (max-width: 694px) 100vw, 694px\" \/><br \/>\n<\/a>Despu\u00e9s de haber escuchado la presi\u00f3n, tanto de las empresas como de los usuarios en s\u00ed, Google decidi\u00f3 modificar el plazo preestablecido de 90 d\u00edas para la publicaci\u00f3n de <em>bugs<\/em> y fallas en sistemas inform\u00e1ticos por parte de su Project Zero, por lo que agreg\u00f3 dos semanas a dicho lapso; con el movimiento pretende suavizar las cr\u00edticas en redes sociales.<!--more--><\/p>\n<p>A la medida se agrega la facilidad de omitir este tipo de publicaciones los d\u00edas festivos en Estados Unidos y fines de semana, acci\u00f3n que agradecen aquellas compa\u00f1\u00edas que s\u00f3lo trabajan de lunes a viernes.<\/p>\n<p>Sin embargo, a pesar del discurso anterior, la firma tambi\u00e9n se reservar\u00e1 el derecho a adelantar o retrasar dicho plazo de gracia de 14 d\u00edas, en caso de que la vulnerabilidad sea extremadamente grave, seg\u00fan dice el comunicado que publicaron en el blog oficial de Project Zero. Agregan tambi\u00e9n que todas las compa\u00f1\u00edas ser\u00e1n tratadas de la misma manera, y que incluso Google ha presentado fallas en Androidy Chrome, las cuales se encuentran en cola para ser publicadas.<\/p>\n<p>A\u00fan cuando las pol\u00edticas de publicaci\u00f3n de fallas se hayan relajado un poco, <strong>Project Zero defiende su plazo inicial de 90 d\u00edas<\/strong>\u00a0justificando que, seg\u00fan sus n\u00fameros, la medida es efectiva por el hecho de que la gran mayor\u00eda de los <em>bugs<\/em> detectados fueron resueltos en menos tiempo que el lapso establecido por Google.<\/p>\n<p>En el comunicado se pone como ejemplo al equipo de Adobe Flash, que ha resuelto 37 errores \u2015equivalentes a 100% de los encontrados por la iniciativa de seguridad\u2015 en menos del plazo establecido. Sin embargo, cuando el error se trata de un sistema operativo, como ocurri\u00f3 en el caso de Microsoft con Windows 8.1, \u00bfes realmente tiempo suficiente para arreglarlo, teniendo en cuenta lo complejo que es, los costos monetarios que esto acarrea y lo que demora la implementaci\u00f3n del nuevo parche en los sistemas del usuario final?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de haber escuchado la presi\u00f3n, tanto de las empresas como de los usuarios en s\u00ed, Google decidi\u00f3 modificar el plazo preestablecido de 90 d\u00edas para la publicaci\u00f3n de bugs y fallas en sistemas inform\u00e1ticos por parte de su Project Zero, por lo que agreg\u00f3 dos semanas a dicho lapso; con el movimiento pretende suavizar las cr\u00edticas en redes sociales.<\/p>\n","protected":false},"author":12,"featured_media":38893,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-38880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=38880"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38880\/revisions"}],"predecessor-version":[{"id":38894,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38880\/revisions\/38894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/38893"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=38880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=38880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=38880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}