{"id":39034,"date":"2015-02-19T14:00:55","date_gmt":"2015-02-19T18:00:55","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=39034"},"modified":"2015-02-19T09:24:09","modified_gmt":"2015-02-19T13:24:09","slug":"10-signos-que-indican-que-vas-a-volver-con-tu-ex","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/10-signos-que-indican-que-vas-a-volver-con-tu-ex\/","title":{"rendered":"10 signos que indican que vas a volver con tu ex"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/corazonroto2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-39035\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/corazonroto2.jpg\" alt=\"corazonroto2\" width=\"652\" height=\"342\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/corazonroto2.jpg 652w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/corazonroto2-300x157.jpg 300w\" sizes=\"auto, (max-width: 652px) 100vw, 652px\" \/><\/a><br \/>\nNo hace falta generalizar: hay veces en que las segundas partes S\u00cd son mejores que las primeras. Quiz\u00e1s tuviste una linda relaci\u00f3n con tu ex pero por distintas circunstancias decidieron dejar de estar juntos. Pero el tiempo pas\u00f3 y volviste a pensar en \u00e9l.<!--more--><\/p>\n<p>1.Duraci\u00f3n de la pareja. Las relaciones que fueron duraderas tienen m\u00e1s posibilidades de volver a reencontrarse por el simple hecho de que crearon un v\u00ednculo m\u00e1s profundo.<\/p>\n<p>2.Seriedad de la relaci\u00f3n. Si ambos conocieron a sus respectivos amigos y familia y estos reaccionaron positivamente en ambos casos, eso es una gran ventaja para que vuelvan. Ojo: si pas\u00f3 lo contrario, hay menos posibilidades.<\/p>\n<p>3.Motivo de la ruptura. Algunas razones por las que cortaron pueden llevar a una f\u00e1cil reconciliaci\u00f3n y otras la hacen imposible. Las del segundo tipo incluyen falta de atracci\u00f3n, sentimientos de que la otra persona no es la correcta y conflictos por diferentes estilos de vida y objetivos de cada uno.<\/p>\n<p>4.C\u00f3mo cortaron. Aquellas relaciones que terminaron amigablemente tienen m\u00e1s posibilidades de volver que aquellas cuyo fin fue sumamente conflictivo.<\/p>\n<p>5.Cambios que ambos hicieron despu\u00e9s de la ruptura. A menos que ambos pienses que la relaci\u00f3n puede ser mejor que antes, no hay motivos para volver.<\/p>\n<p>6. Nuevas parejas. Si alguno de los dos est\u00e1 saliendo con otra persona, puede que no tenga apuro en volver con su ex porque quiere chequear si la nueva pareja puede ofrecer m\u00e1s que la antigua.<\/p>\n<p>7.Cambios que ambos hayan experimentado. Es muy com\u00fan que despu\u00e9s de una ruptura alguno de los dos, o ambos, hayan puesto energ\u00eda en otros intereses. Si estos son muy fuertes, quiz\u00e1s no tengan inter\u00e9s en volver a una vieja rutina.<\/p>\n<p>8.Estrategias para volver. Algunas personas intentan hacer cosas que hacen imposible que el ex quiera volver a tener una relaci\u00f3n: o confirman lo que los separ\u00f3 en un momento o revelan un costado oculto que quisieras nunca haber conocido.<\/p>\n<p>9.Proximidad. Puede que una relaci\u00f3n a distancia agregue un condimento renovador a la relaci\u00f3n o, por lo contrario, que haga imposible que puedan volver a conectarse.<\/p>\n<p>10.Habilidad para manejar la ansiedad. El lapso de tiempo en que ambos se est\u00e1n acercando puede poner de los nervios a alguno de los dos que, ansioso por volver a ser \u201cnovios\u201d, puede reaccionar con acciones negativas que vuelvan a alejarlos. As\u00ed que si tu plan es volver, RELAX, y dej\u00e1 que el tiempo haga lo suyo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No hace falta generalizar: hay veces en que las segundas partes S\u00cd son mejores que las primeras. Quiz\u00e1s tuviste una linda relaci\u00f3n con tu ex pero por distintas circunstancias decidieron dejar de estar juntos. Pero el tiempo pas\u00f3 y volviste a pensar en \u00e9l.<\/p>\n","protected":false},"author":3,"featured_media":39035,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-39034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/39034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=39034"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/39034\/revisions"}],"predecessor-version":[{"id":39036,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/39034\/revisions\/39036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/39035"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=39034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=39034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=39034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}