{"id":39409,"date":"2015-02-25T06:19:40","date_gmt":"2015-02-25T10:19:40","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=39409"},"modified":"2015-02-25T06:19:40","modified_gmt":"2015-02-25T10:19:40","slug":"una-pildora-tomada-antes-y-despues-del-sexo-podria-prevenir-el-sida","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/una-pildora-tomada-antes-y-despues-del-sexo-podria-prevenir-el-sida\/","title":{"rendered":"Una p\u00edldora tomada antes y despu\u00e9s del sexo podr\u00eda prevenir el sida"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/vih_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-39412 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/vih_1.jpg\" alt=\"vih_1\" width=\"424\" height=\"287\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/vih_1.jpg 650w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/vih_1-300x203.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/vih_1-75x52.jpg 75w\" sizes=\"auto, (max-width: 424px) 100vw, 424px\" \/><\/a>LOS ANGELES. AFP.<\/strong> La pastilla Truvada para prevenir el sida, tomada antes y despu\u00e9s de sexo sin protecci\u00f3n, reduce el riesgo de transmisi\u00f3n del virus entre hombres homosexuales en un 86%, seg\u00fan los resultados de un ensayo cl\u00ednico publicado el martes en Estados Unidos. \u00a0<!--more--><\/p>\n<p>Para el estudio, Truvada -una combinaci\u00f3n de los retrovirales tenofovir y emtricitabine- fue tomada un d\u00eda antes y los dos d\u00edas despu\u00e9s de las relaciones sexuales con alto riesgo de contagio del virus del sida.<\/p>\n<p>El estudio, realizado por la Agencia Nacional Francesa especializada en el sida (ANRS), fue presentado durante la Conferencia sobre los retrovirales y las infecciones oportunistas (CROI), que se celebra esta semana en Seattle (noroeste de Estados Unidos).<\/p>\n<p>Hasta ahora, Truvada -como medicamento preventivo- era recetado solo como un r\u00e9gimen de un d\u00eda, no como m\u00e9todo efectivo aplicado en el momento que se tiene la relaci\u00f3n sexual.<\/p>\n<p>Esta \u00faltima evidencia sobre este m\u00e9todo, conocido como pre-exposici\u00f3n profilaxis o PrEP, no es suficiente para cambiar la forma de prescripci\u00f3n, pero fue celebrada como un nuevo acercamiento a la prevenci\u00f3n del sida.<\/p>\n<p>El estudio \u201cprovee la primera evidencia de que un r\u00e9gimen dirigido es efectivo entre homosexuales de alto riesgo con relaciones sexuales frecuentes\u201d, dijo Jonathan Mermin, director del centro de control y prevenci\u00f3n de VIH en Estados Unidos.<\/p>\n<p>Truvada, producida por el laboratorio Gilead Sciences, fue aprobada en 2012 por las autoridades estadounidenses como la primera pastilla en ayudar a prevenir la inmunodeficiencia humana en grupos de alto riesgo.<\/p>\n<p>Denominado Ipergay, este estudio que mezclaba el uso de placebos con dosis controladas del medicamento, comenz\u00f3 en febrero de 2012 y se detuvo en octubre de 2014, cuando una revisi\u00f3n independiente determin\u00f3 que ten\u00eda una alta efectividad.\u00a0\u00a0 Un total de 400 pacientes participaron en el estudio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LOS ANGELES. AFP. La pastilla Truvada para prevenir el sida, tomada antes y despu\u00e9s de sexo sin protecci\u00f3n, reduce el riesgo de transmisi\u00f3n del virus entre hombres homosexuales en un 86%, seg\u00fan los resultados de un ensayo cl\u00ednico publicado el martes en Estados Unidos. \u00a0<\/p>\n","protected":false},"author":12,"featured_media":39412,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-39409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/39409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=39409"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/39409\/revisions"}],"predecessor-version":[{"id":39413,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/39409\/revisions\/39413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/39412"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=39409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=39409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=39409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}