{"id":39834,"date":"2015-03-07T07:55:58","date_gmt":"2015-03-07T11:55:58","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=39834"},"modified":"2015-03-07T02:31:11","modified_gmt":"2015-03-07T06:31:11","slug":"lluvias-debiles-para-el-fin-de-semana-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/lluvias-debiles-para-el-fin-de-semana-2\/","title":{"rendered":"Lluvias d\u00e9biles para el fin de semana"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Lluvias.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-39865 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Lluvias.jpg\" alt=\"Lluvias\" width=\"600\" height=\"340\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Lluvias.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Lluvias-300x170.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><br \/>\nSanto Domingo. La oficina Nacional de Meteorolog\u00eda informa que el territorio dominicano seguir\u00e1 con el mismo patr\u00f3n meteorol\u00f3gico que hemos observado durante toda la semana, arrastre de nubes pasajeras a causa del viento del este<!--more-->, que seguir\u00e1n provocando lluvias d\u00e9biles de corto tiempo durante la tarde hasta las primeras horas de la noche hacia las vecindades de las provincias: Monte Plata, San Crist\u00f3bal, San Jos\u00e9 de Ocoa, Monse\u00f1or Nouel, La Vega, Santiago, Hermanas Mirabal, Espaillat, Puerto Plata, Duarte, Mar\u00eda Trinidad S\u00e1nchez, Saman\u00e1, Hato Mayor, El Seibo, Barahona, San Jos\u00e9 de Ocoa y La Altagracia.<\/p>\n<p>Para ma\u00f1ana destaca la ONAMET que continuaremos con arrastre de nubosidad producto del viento del este, provocando lluvias d\u00e9biles de corta duraci\u00f3n durante la tarde hasta las primeras horas de la noche sobre las regiones noreste, sureste y el centro del pa\u00eds.<\/p>\n<p>Oleaje anormal mar adentro en todas las costas del pa\u00eds, las fr\u00e1giles y peque\u00f1as embarcaciones deben navegar con precauci\u00f3n cerca del per\u00edmetro costero, sin aventurarse mar adentro, debido a olas anormales y en la Bah\u00eda de Saman\u00e1, deben navegar dentro de la misma, sin salir de ella, por olas anormales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. La oficina Nacional de Meteorolog\u00eda informa que el territorio dominicano seguir\u00e1 con el mismo patr\u00f3n meteorol\u00f3gico que hemos observado durante toda la semana, arrastre de nubes pasajeras a causa del viento del este<\/p>\n","protected":false},"author":12,"featured_media":39865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-39834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/39834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=39834"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/39834\/revisions"}],"predecessor-version":[{"id":39866,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/39834\/revisions\/39866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/39865"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=39834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=39834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=39834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}