{"id":40353,"date":"2015-03-16T21:05:52","date_gmt":"2015-03-17T01:05:52","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=40353"},"modified":"2015-03-16T21:05:52","modified_gmt":"2015-03-17T01:05:52","slug":"muere-valiente-dominicano-al-salvar-de-una-balacera-nina-de-4-anos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/muere-valiente-dominicano-al-salvar-de-una-balacera-nina-de-4-anos\/","title":{"rendered":"Muere valiente dominicano al salvar de una balacera ni\u00f1a de 4 a\u00f1os"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Bodeguero-criollo-muere-de-balazo-en-el-pecho.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-40356 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Bodeguero-criollo-muere-de-balazo-en-el-pecho.jpg\" alt=\"Bodeguero criollo muere de balazo en el pecho\" width=\"628\" height=\"521\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Bodeguero-criollo-muere-de-balazo-en-el-pecho.jpg 1300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Bodeguero-criollo-muere-de-balazo-en-el-pecho-300x249.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Bodeguero-criollo-muere-de-balazo-en-el-pecho-1024x850.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Bodeguero-criollo-muere-de-balazo-en-el-pecho-90x75.jpg 90w\" sizes=\"auto, (max-width: 628px) 100vw, 628px\" \/><br \/>\n<\/a>USA._ Wilson Valdez (Miguelo), un trabajador dominicano en una bodega de Planfield en New Jersey, muri\u00f3 de un balazo en el pecho cuando trat\u00f3 de salvar una ni\u00f1a de una balacera, originada frente a la bodega \u201cThe Brothers\u201d (Los Hermanos).<!--more--><\/p>\n<p>La polic\u00eda arrest\u00f3 a Arthur Negr\u00f3n y Abdul Ward de 23 y 24 a\u00f1os de edad respectivamente, como sospechosos en el asesinato de Valdez.<\/p>\n<p>Valdez, quien ten\u00eda 31 a\u00f1os, se abraz\u00f3 a la menor de 4 a\u00f1os, que hab\u00eda ido con su madre embarazada a comprar a la bodega situada en la cuadra 600 de la calle Berckman en Planfield.<\/p>\n<p>La madre de la menor, critic\u00f3 a la polic\u00eda y los param\u00e9dicos quienes dijo, llegaron 10 minutos despu\u00e9s de la llamada al 911 y las atendieron primero a ellas, en vez de ponerle atenci\u00f3n al dominicano que se desangraba agonizante.<\/p>\n<p>La mujer, de origen centro o suramericano declin\u00f3 identificarse por miedo.<\/p>\n<p>El bodeguero fue asesinado por la bala el jueves a las 2:30 de la tarde y los sospechosos arrestados el viernes.<\/p>\n<p>Los disparos fueron hechos por dos bandas rivales de delincuentes en las afueras del negocio y uno de los criminales, entr\u00f3 a la bodega, para protegerse de las balas.<\/p>\n<p>Al escuchar los disparos, la ni\u00f1a de cuatro a\u00f1os de edad, corri\u00f3 hacia la parte delantera de la bodega, presa del p\u00e1nico. El dominicano corri\u00f3 detr\u00e1s de ella y la bala que lo mat\u00f3 penetr\u00f3 por el cristal de una de las ventanas frontales.<\/p>\n<p>Valdez, ten\u00eda un hijo de ocho a\u00f1os y una novia con la que llevaba una relaci\u00f3n desde hac\u00eda algunos a\u00f1os.<\/p>\n<p>Trabaj\u00f3 durante 10 a\u00f1os en la bodega. \u201cEl me llamaba pap\u00e1\u201d, dijo Angel Caba, t\u00edo de Valdez sin poder contener las l\u00e1grimas y quien es el due\u00f1o del establecimiento.<\/p>\n<p>Los sospechosos detenidos intentaron huir, pero se estrellaron contra una camioneta estacionada a pocas cuadras de la bodega.<\/p>\n<p>Ward, es acusado de asesinato, atraco, posesi\u00f3n ilegal de un arma y eludir a la polic\u00eda.<\/p>\n<p>Negr\u00f3n, fue imputado por cargos de posesi\u00f3n ilegal de un arma, atraco y resistencia al arresto.<\/p>\n<p>A ambos se les fijaron fianzas de $1 mill\u00f3n y $500.000 d\u00f3lares en efectivo. En la camioneta chocada por los sospechosos, resultaron heridos los dos ocupantes y un peat\u00f3n que estaba cerca de la escena.<\/p>\n<p>Ileana Caba, una prima de la v\u00edctima, dijo que la captura de los dos sospechosos, da un poco de paz a la familia.<\/p>\n<p>Clientes de la bodega reaccionaron sorprendidos y en shock por el asesinato de Valdez, pero dijeron que no lo estaban por la protecci\u00f3n\u00a0 de la ni\u00f1a, debido al buen coraz\u00f3n del dominicano.<\/p>\n<p>Harry De Cosey Junior, asiduo comprador en la bodega, dijo que Valdez era el primero en llegar al negocio para abrirlo cada ma\u00f1ana y se iba en la noche cuando lo cerraba.<\/p>\n<p>\u201cEra un buen amigo, nunca pens\u00e9 que podr\u00eda morir as\u00ed. Era un hombre muy trabajador y que siempre daba caramelos gratis a los ni\u00f1os\u201d, a\u00f1adi\u00f3 De Cosey.<\/p>\n<p>Un altar improvisado fue levantado frente a la bodega, con fotograf\u00edas, flores, velones y velas en honor a Valdez.<\/p>\n<p>El asesinato del bodeguero dominicano conmocion\u00f3 a todo el vecindario en Planfield.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/laverdadnosenegocia.blogspot.com\/2015\/03\/wilson-valdez-miguelo-corrio-para.html\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>USA._ Wilson Valdez (Miguelo), un trabajador dominicano en una bodega de Planfield en New Jersey, muri\u00f3 de un balazo en el pecho cuando trat\u00f3 de salvar una ni\u00f1a de una balacera, originada frente a la bodega \u201cThe Brothers\u201d (Los Hermanos).<\/p>\n","protected":false},"author":12,"featured_media":40356,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-40353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=40353"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40353\/revisions"}],"predecessor-version":[{"id":40357,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40353\/revisions\/40357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/40356"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=40353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=40353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=40353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}