{"id":40754,"date":"2015-04-06T09:34:26","date_gmt":"2015-04-06T13:34:26","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=40754"},"modified":"2015-03-25T18:37:46","modified_gmt":"2015-03-25T22:37:46","slug":"zumba","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/zumba\/","title":{"rendered":"\u00a1Zumba!"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/pm_zumba_day_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-40755\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/pm_zumba_day_1-1024x685.jpg\" alt=\"pm_zumba_day_1\" width=\"960\" height=\"642\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/pm_zumba_day_1-1024x685.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/pm_zumba_day_1-300x201.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/pm_zumba_day_1-105x70.jpg 105w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a>En los \u00faltimos tiempos, hemos presenciado el furor de una nueva modalidad de ejercicios denominada Zumba. Hoy conoceremos su origen, beneficios y modalidades.<!--more--><\/p>\n<p>La Zumba es una rutina de ejercicios que combina aer\u00f3bicos con baile de diversos g\u00e9neros que incluyen, salsa, merengue, reggaet\u00f3n, cumbia, samba, hip-hop, soca y artes marciales. Tuvo sus or\u00edgenes en Colombia en los a\u00f1os 90\u2019s; su creador fue Alberto \u201cBeto\u201d P\u00e9rez, un instructor de aer\u00f3bicos. Un d\u00eda \u201cBeto\u201d olvid\u00f3 los discos que usaba para sus clases y combin\u00f3 los ritmos de salsa y merengue de los casetes que encontr\u00f3 en su mochila. As\u00ed naci\u00f3 la zumba.<\/p>\n<p>Con el tiempo, \u201cBeto\u201d observ\u00f3 el \u00e9xito de su m\u00e9todo de ejercicios y se traslad\u00f3 a los Estados Unidos, donde se uni\u00f3 a Alberto Pearlman y Alberto Aghion quienes en conjunto produjeron en 2001 un nuevo concepto de ejercicios caseros que se vend\u00edan en v\u00eddeos.<\/p>\n<p>Sin embargo, el \u201cfuror\u201d de la Zumba, es un poco m\u00e1s reciente. Hoy d\u00eda existe una academia de Zumba que certifica instructores y est\u00e1 tambi\u00e9n Zumba Fitness,\u00ae una firma que distribuye videos y tutoriales del novedoso m\u00e9todo. Entre los beneficios registrados para quienes practiquen Zumba, se cuentan poder adelgazar, mejorar la circulaci\u00f3n, aliviar los dolores musculares y otros. Razones estas que han contribuido a una mayor difusi\u00f3n de las clases de Zumba en gimnasios y centros certificados en m\u00e1s de 150 pa\u00edses.<\/p>\n<p>Seg\u00fan los expertos, hay varios niveles de Zumba, concebidos con objetivos diversos, citamos por ejemplo, Zumba Gold para personas mayores, Aqua Zumba, Zumba Fitness Party, Zumbatomic, Zumba Toning, entre otros. La Zumba ha sido adaptada a otros idiomas (no solo m\u00fasica hispana, sino tambi\u00e9n en ingl\u00e9s, portugu\u00e9s,etc) as\u00ed como tambi\u00e9n a m\u00fasica religiosa.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los \u00faltimos tiempos, hemos presenciado el furor de una nueva modalidad de ejercicios denominada Zumba. Hoy conoceremos su origen, beneficios y modalidades.<\/p>\n","protected":false},"author":3,"featured_media":40755,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-40754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=40754"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40754\/revisions"}],"predecessor-version":[{"id":40756,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40754\/revisions\/40756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/40755"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=40754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=40754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=40754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}