{"id":40814,"date":"2015-03-27T17:22:56","date_gmt":"2015-03-27T21:22:56","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=40814"},"modified":"2015-03-27T13:33:40","modified_gmt":"2015-03-27T17:33:40","slug":"dncd-instala-unidad-canina-en-manzanillo-para-combatir-narcotrafico-en-la-frontera","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/dncd-instala-unidad-canina-en-manzanillo-para-combatir-narcotrafico-en-la-frontera\/","title":{"rendered":"DNCD instala unidad canina en Manzanillo para combatir narcotr\u00e1fico en la frontera"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/AB3F7E1B-03AA-476D-8A3F-1496DFC94E96.jpg__270__200__CROPz0x270y200.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-40815 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/AB3F7E1B-03AA-476D-8A3F-1496DFC94E96.jpg__270__200__CROPz0x270y200.jpg\" alt=\"AB3F7E1B-03AA-476D-8A3F-1496DFC94E96.jpg__270__200__CROPz0x270y200\" width=\"234\" height=\"175\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/AB3F7E1B-03AA-476D-8A3F-1496DFC94E96.jpg__270__200__CROPz0x270y200.jpg 267w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/AB3F7E1B-03AA-476D-8A3F-1496DFC94E96.jpg__270__200__CROPz0x270y200-100x75.jpg 100w\" sizes=\"auto, (max-width: 234px) 100vw, 234px\" \/><\/a><\/p>\n<p class=\"not-pspace\">MONTE CRISTY.- La Direcci\u00f3n Nacional de Control de Drogas (DNCD) extendi\u00f3 al puerto fronterizo de manzanillo su proyecto de instalaci\u00f3n de los\u00a0\u00a0servicios permanentes de la Unidad\u00a0\u00a0Canina K-9,\u00a0<!--more--><br \/>\nuna iniciativa que abarcar\u00e1 el territorio nacional, en el marco de la constante renovaci\u00f3n de la lucha contra el narcotr\u00e1fico internacional.<\/p>\n<p class=\"not-pspace\">El presidente de la agencia, Mayor General Julio C\u00e9sar Souffront Vel\u00e1zquez, se traslad\u00f3 este viernes a esta localidad fronteriza junto al Comandante General de la Armada de Rep\u00fablica Dominicana (ARD), al director de Autoridad Portuaria Dominicana y al Director del Cuerpo Especializado de Seguridad Portuaria, adem\u00e1s de una comitiva de la instituci\u00f3n y autoridades locales para dejar instalados estos servicios caninos que accionan contra el tr\u00e1fico de drogas por esta \u00e1rea de la frontera.<\/p>\n<p class=\"not-pspace\">En su discurso, Souffront Vel\u00e1zquez mostr\u00f3 satisfacci\u00f3n por los avances y logros alcanzados por esta unidad canina, al tiempo que agradeci\u00f3 a las autoridades e instituciones que hicieron posible la instalaci\u00f3n de esta unidad K-9, a la vez que exhort\u00f3 a los miembros reci\u00e9n posesionados en tan delicadas funciones a empe\u00f1arse de manera \u00edntegra, profesional y cort\u00e9s, para provecho de una sociedad que conf\u00eda cada d\u00eda m\u00e1s en las ejecutorias llevadas a cabo por esta DNCD con apoyo irrestricto del presidente, Licenciado Danilo Medina S\u00e1nchez.<\/p>\n<p class=\"not-pspace\">Estos galgos tienen la facultad de\u00a0\u00a0detectar todo tipo de sustancias narc\u00f3ticas\u00a0\u00a0o papel moneda que se pretenda introducir a nuestro territorio a trav\u00e9s de embarcaciones, veh\u00edculos de motor o haciendo uso de peatones.<\/p>\n<p class=\"not-pspace\">De ah\u00ed los frecuentes decomisos realizados por la DNCD con sus unidades caninas en diferentes operativos, b\u00e1sicamente en puertos y aeropuertos,\u00a0\u00a0\u00a0\u00a0donde la colaboraci\u00f3n de la DEA y otras agencias internacionales ha sido fundamental.<\/p>\n<p class=\"not-pspace\">Al acto asistieron autoridades civiles, militares, policiales\u00a0\u00a0de la provincia, entre ellas la gobernadora, Zaida Inmaculada Tejeda Acosta; la procuradora fiscal,\u00a0\u00a0Yohanna Isabel Bejar\u00e1n \u00c1lvarez; el\u00a0\u00a0senador Heinz Vieluf\u00a0\u00a0Cabrera; el contralmirante F\u00e9lix Alburquerque director general CESEP; el cura p\u00e1rroco Eduardo Barajas y Felvio Bejar\u00e1n, representante del director general de Aduanas.<\/p>\n<p class=\"not-pspace\">Tambi\u00e9n,\u00a0\u00a0los comandantes locales de Polic\u00eda Nacional,\u00a0\u00a0teniente coronel V\u00edctor Carrasco, y\u00a0\u00a0del Ej\u00e9rcito de la Rep\u00fablica Dominicana,\u00a0\u00a0teniente coronel Porfirio Santana Espinosa; el comandante del puerto,\u00a0\u00a0capit\u00e1n de fragata Nicol\u00e1s Gonz\u00e1lez Zapata,\u00a0\u00a0y el\u00a0\u00a0administrador local de la Autoridad Portuaria Dominicana.<\/p>\n<p class=\"not-pspace\">Adem\u00e1s de Manzanillo,\u00a0\u00a0la DNCD cuenta con los servicios fijos de la Unidad Canina K-9 en los puertos de\u00a0\u00a0Multimodal Caucedo,\u00a0\u00a0Santo Domingo,\u00a0\u00a0Cabo Rojo y tiene programada la instalaci\u00f3n de los binomios caninos en Jiman\u00ed y El\u00edas Pi\u00f1a, para de esta forma contrarrestar todo intento que se pueda producir en la zona terrestre, fronteriza de nuestro pa\u00eds, tambi\u00e9n, en los aeropuertos internacionales como Las Am\u00e9ricas e Isabela,\u00a0\u00a0en el gran Santo Domingo; Punta Cana,\u00a0\u00a0en La Altagracia;\u00a0\u00a0Gregorio Luper\u00f3n\u00a0\u00a0en Puerto Plata, y\u00a0\u00a0Cibao, en Santiago y La Romana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONTE CRISTY.- La Direcci\u00f3n Nacional de Control de Drogas (DNCD) extendi\u00f3 al puerto fronterizo de manzanillo su proyecto de instalaci\u00f3n de los\u00a0\u00a0servicios permanentes de la Unidad\u00a0\u00a0Canina K-9,\u00a0<\/p>\n","protected":false},"author":9,"featured_media":40815,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-40814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=40814"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40814\/revisions"}],"predecessor-version":[{"id":40816,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40814\/revisions\/40816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/40815"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=40814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=40814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=40814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}