{"id":40886,"date":"2015-03-30T00:07:22","date_gmt":"2015-03-30T04:07:22","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=40886"},"modified":"2015-03-30T00:08:25","modified_gmt":"2015-03-30T04:08:25","slug":"inauguran-exposicion-tendederos-blanco-y-negro-a-beneficio-de-mustard-seed-communities-fotos-y-video","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/inauguran-exposicion-tendederos-blanco-y-negro-a-beneficio-de-mustard-seed-communities-fotos-y-video\/","title":{"rendered":"Inauguran exposici\u00f3n \u00abTendederos Blanco y Negro\u00bb a beneficio de Mustard Seed Communities (Fotos y Video)"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/DSCN0323.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-40888 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/DSCN0323.jpg\" alt=\"DSCN0323\" width=\"605\" height=\"453\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/DSCN0323.jpg 4608w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/DSCN0323-300x225.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/DSCN0323-1024x768.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/DSCN0323-100x75.jpg 100w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/><\/a>El Artista pl\u00e1stico sosuense, Adolfo Faringthon dej\u00f3 inaugurado el pasado viernes 27 de marzo,\u00a0su exposici\u00f3n personal bajo el t\u00edtulo \u201cTendederos Blanco y Negro\u201d en una actividad pautada para las 7:30 de la noche en la sala de exposiciones de La Casa de Arte Municipal.<!--more--><\/p>\n<div class=\"text_exposed_show\">\n<p>Faringthon al momento de agradecer a las personalidades presentes manifest\u00f3 su complacencia al poder exponer sus obras en su pueblo natal y en la casa de Arte que el mismo dirige, ya que este municipio hasta hace poco menos de dos a\u00f1os no contaba con instalaciones para este tipo de evento.<br \/>\n<iframe loading=\"lazy\" src=\"http:\/\/files.slidemypics.com\/app\/js\/iframe.html?bg_color=1f1f1f&amp;hash=7c2c637a2217ec5365a8eabaa1543512&amp;r=0.6805732625070959\" width=\"630\" height=\"450\" frameborder=\"0\"><\/iframe><br \/>\nAdolfo Faringthon ha tenido la oportunidad de presentar sus obras en m\u00e1s de treinta exposiciones en el pa\u00eds, adem\u00e1s de Suiza, M\u00e9xico, Estados Unidos y Canad\u00e1. En esta ocasi\u00f3n Adolfo ha decidido donar la colecci\u00f3n completa de su m\u00e1s reciente exposici\u00f3n \u201cTendederos Blanco y Negro\u201d al hogar de ni\u00f1os discapacitados Granito de Mostaza (Mustard Seed Communities), entidad que se dedica al cuidado seres humanos que de otra manera no podr\u00edan existir.Mustard Seed Communities sobrevive precariamente con las donaciones que se reciben localmente y de algunas personas y entidades desde el extranjero.<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/h6j4eUNUo1M\" width=\"630\" height=\"410\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\nLa labor que lleva a cabo Granito de Mostaza con los ni\u00f1os y j\u00f3venes discapacitados toca y sensibiliza el coraz\u00f3n y motiva a colaborar con esta grandiosa causa en nuestra comunidad.<\/p>\n<p>El acto de inauguraci\u00f3n de la exposici\u00f3n m\u00e1s reciente de Adolfo Faringthon estuvo presidido por Ydelqui Brito y cont\u00f3 con la presencia de la alcaldesa Ilana Neumann, los concejales Miguel Fern\u00e1ndez y Johnny Matos, El director provincial de turismo, Lorenzo Sancassani y miembros prominentes de la sociedad sosuense y puertoplate\u00f1a, adem\u00e1s de una nutrida representaci\u00f3n de artistas pl\u00e1sticos locales y los directivos de Mustard Seed Communities.<\/p>\n<p>&nbsp;<\/p>\n<p>Por: F\u00e9lix Corona<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Artista pl\u00e1stico sosuense, Adolfo Faringthon dej\u00f3 inaugurado el pasado viernes 27 de marzo,\u00a0su exposici\u00f3n personal bajo el t\u00edtulo \u201cTendederos Blanco y Negro\u201d en una actividad pautada para las 7:30 de la noche en la sala de exposiciones de La Casa de Arte Municipal.<\/p>\n","protected":false},"author":12,"featured_media":40888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,3],"tags":[],"class_list":["post-40886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=40886"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40886\/revisions"}],"predecessor-version":[{"id":40889,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40886\/revisions\/40889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/40888"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=40886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=40886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=40886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}