{"id":40915,"date":"2015-03-30T22:15:45","date_gmt":"2015-03-31T02:15:45","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=40915"},"modified":"2015-03-30T22:15:45","modified_gmt":"2015-03-31T02:15:45","slug":"la-mama-del-humor-la-mejor-pagada-del-cine-en-rd","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-mama-del-humor-la-mejor-pagada-del-cine-en-rd\/","title":{"rendered":"\u201cLa mam\u00e1 del humor\u201d la mejor pagada del cine en RD"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Cheddy3.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-40918 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Cheddy1.jpeg\" alt=\"Cheddy1\" width=\"247\" height=\"334\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Cheddy1.jpeg 294w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Cheddy1-222x300.jpeg 222w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Cheddy1-56x75.jpeg 56w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/><\/a>\u00a0\u00a0Mercedes Jos\u00e9 Garc\u00eda, a quien la conocen \u00a0como Cheddy Garc\u00eda, \u201cLa Mam\u00e1 del Humor\u201d, nunca plane\u00f3 ser humorista ni imagin\u00f3 vivir del arte. De ni\u00f1a fue una excelente estudiante y gracias a sus altas calificaciones logr\u00f3 ser becada en la Universidad Nacional Pedro Henr\u00edquez Ure\u00f1a (UNPHU), en donde inici\u00f3 la carrera de pedagog\u00eda.<!--more--><\/p>\n<p>Hoy confiesa que vive bien, con inversiones en bienes ra\u00edces (4 apartamentos y una casa) y una carrera prometedora en el cine dominicano, convirti\u00e9ndola en la actriz dominicana mejor pagada del s\u00e9ptimo arte y llegando a cobrar hasta un mill\u00f3n de pesos por pel\u00edcula. Esa es una de las razones por la que ella dijo que nada ni nadie la saca del pa\u00eds.<\/p>\n<p><b>SU PRIMERA PANTALLA<\/b><br \/>\nTras generar buena impresi\u00f3n, sus compa\u00f1eros la animaron para que fuera a un concurso de \u00abtalent show\u00bb que ten\u00eda Freddy Beras Goico en el programa \u201cPunto Final\u201d.<\/p>\n<p><span style=\"color: #ffa500;\"><b>Su real oportunidad<\/b><\/span><br \/>\nFue en el programa meridiano \u201cCaribe Show\u201d (canal 4), \u00a0a principios de la d\u00e9cada del 90, cuando Raymond Pozo y Miguel C\u00e9spedes le dieron una oportunidad.<\/p>\n<p><span style=\"color: #ffa500;\"><b>Familia y amores<\/b><\/span><br \/>\nCheddy es madre de Chelsy, de 14 a\u00f1os, quien tambi\u00e9n es actriz, y de Ian, de 4 a\u00f1os. Actualmente tiene un novio con el que est\u00e1 comenzando una relaci\u00f3n.<\/p>\n<p>La humorista viene de una familia de muy escasos recursos. Naci\u00f3 y creci\u00f3 en La Puya de Arroyo Hondo, con su madre y dos hermanas del lado materno.<\/p>\n<p><b><span style=\"font-size: x-large;\">\u2018Sufr\u00ed rechazo\u2019<br \/>\n<\/span><\/b><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-40916 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Cheddy3.jpeg\" alt=\"Cheddy3\" width=\"274\" height=\"378\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Cheddy3.jpeg 334w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Cheddy3-218x300.jpeg 218w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Cheddy3-54x75.jpeg 54w\" sizes=\"auto, (max-width: 274px) 100vw, 274px\" \/>En estos momentos la vida de Cheddy Garc\u00eda parecer\u00eda un cuento con un final feliz, pero la realidad que vivi\u00f3 desde ni\u00f1a solo la superan las personas con la determinaci\u00f3n de vencer obst\u00e1culos pase lo que pase.<\/p>\n<p>Y es que la humorista viene de una familia de escasos recursos. Naci\u00f3 y creci\u00f3 en La Puya de Arroyo Hondo, junto a su madre y dos hermanas, del lado materno. En la escuela siempre fue muy aplicada y estuvo al frente de las actividades art\u00edsticas escolares, pero esto no le mostraba todav\u00eda el camino por el que se convertir\u00eda en una de las mujeres m\u00e1s queridas y populares del \u00e1mbito art\u00edstico local.<\/p>\n<p>A la Universidad Nacional Pedro Henr\u00edquez Ure\u00f1a (UNPHU) lleg\u00f3 a estudiar pedagog\u00eda, becada. Durante ese tiempo se enamor\u00f3 y se divorci\u00f3. Esto le afect\u00f3 de tal manera que perdi\u00f3 la beca y fue a concluir la carrera a la Universidad Aut\u00f3noma de Santo Domingo (UASD).<\/p>\n<p>En la instituci\u00f3n estatal, entra al movimiento cultural de esa universidad y forma parte del elenco de teatro.<\/p>\n<p>Sus personajes causaron tanta impresi\u00f3n que sus compa\u00f1eros la animaron para que fuera al concurso el Talent Show que realizaba Freddy Beras Goico en el programa \u201cPunto final\u201d (Color Visi\u00f3n).<\/p>\n<p>All\u00ed gan\u00f3 el primer lugar. Entonces es cuando se dio cuenta de que realmente ten\u00eda talento, porque logr\u00f3 impresionar a Beras Goico. \u201cImag\u00ednate eso fue un acontecimiento y una gran felicidad, saber que impresion\u00e9 a Freddy, y eso fue lo que me convenci\u00f3 de que realmente ten\u00eda talento\u201d, revel\u00f3 en visita a LIST\u00cdN DIARIO.<\/p>\n<p>Cheddy esper\u00f3 para entrar a algunos de los programas del afamado productor de televisi\u00f3n, pero eso nunca sucedi\u00f3.<\/p>\n<p>Record\u00f3 que en esos inicios visit\u00f3 todos los canales UHF en busca de una oportunidad, pero fue en el programa meridiano \u201cCaribe Show\u201d (canal 4), a principios de la d\u00e9cada del 90, que Raymond Pozo y Miguel C\u00e9spedes le dieron una oportunidad.<\/p>\n<p>\u201cLlegu\u00e9 a la televisi\u00f3n en la \u00faltima etapa de este programa porque inmediatamente ellos (Raymond y Miguel) se fueron a trabajar por completo a Telemicro, porque ya hac\u00edan \u2018Qu\u00e9date ah\u00ed\u2019, en la noche, pero Juan Ram\u00f3n G\u00f3mez D\u00edaz los llam\u00f3 para \u2018La opci\u00f3n de las 12\u2019 y dejaron a \u2018Caribe Show\u2019 para irse al canal 5\u201d, record\u00f3.<\/p>\n<p>A Cheddy no le qued\u00f3 m\u00e1s remedio que irse a llorar a su casa, pero Miguel la anim\u00f3 para recomendarla a G\u00f3mez D\u00edaz, quien de inmediato la acept\u00f3 para el espacio de humor de la noche.<\/p>\n<p><b>He sido muy discriminada<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-40917 alignright\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Cheddy2.jpeg\" alt=\"Cheddy2\" width=\"331\" height=\"463\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Cheddy2.jpeg 329w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Cheddy2-215x300.jpeg 215w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/03\/Cheddy2-54x75.jpeg 54w\" sizes=\"auto, (max-width: 331px) 100vw, 331px\" \/>Pero al llegar al canal 5 siente la primera discriminaci\u00f3n por parte de sus compa\u00f1eras. \u201cLas mujeres que trabajaban en el programa comenzaron a decir que yo me ve\u00eda muy fea y que no televisaba bien, y el due\u00f1o del canal me sac\u00f3 del programa\u201d.<\/p>\n<p>No obstante, su amigo fiel, Miguel C\u00e9spedes, volvi\u00f3 a hablar con G\u00f3mez D\u00edaz para que le diera otra oportunidad y este termin\u00f3 aceptando. \u201cEntonces fue cuando realmente me prepar\u00e9 y fui a romper y comenc\u00e9 con todos mis personajes. Al due\u00f1o del canal le gust\u00f3 y luego me puso en \u2018La opci\u00f3n de las 12\u201d.<\/p>\n<p>Cheddy se destac\u00f3 all\u00ed con una gran cantidad de personajes muy populares que la convirtieron en una humorista de masa. Tanto as\u00ed que lleg\u00f3 a llenar estadios en El Seibo y en Cotu\u00ed con su espect\u00e1culo. Crucita, La Desesperada del Amargue, Manolito, La Evang\u00e9lica y Alondra eran personajes esperados.<\/p>\n<p><b>Lo social<\/b><br \/>\nSus or\u00edgenes no le permit\u00edan conquistar a un p\u00fablico que no terminaba de aceptarla. \u201cEn mis inicios tuve que luchar con muchas barreras y lidiar con muchas humillaciones. Sufr\u00ed la discriminaci\u00f3n en carne viva, porque comenc\u00e9 haciendo un humor muy popular y la gente pens\u00f3 que yo era solo eso. Yo no sab\u00eda lo que era una tela buena, no sab\u00eda lo que significaba vestir bien en esta sociedad. Recuerdo que en un Casandra un peri\u00f3dico public\u00f3 que si iba para la Duarte, porque me aparec\u00ed en la alfombra roja con una falda corta. Cuando inici\u00e9 en Telemicro con esos personajes tan populares, lo hice consciente del p\u00fablico para el que estaba trabajando\u201d, se\u00f1al\u00f3.<\/p>\n<p>Cheddy vivi\u00f3 en carne propia lo que fue el rechazo social por venir de un segmento en donde las oportunidades no existen. \u201cPero siempre me levant\u00e9, cada vez que me criticaban y viv\u00eda situaciones de esta naturaleza encontraba fuerzas en mi interior para levantarme y aceptarme tal cual era, porque yo no manejaba los c\u00f3digos de vestimenta. Llegu\u00e9 al medio siendo una analfabeta en ese sentido. Yo fui aprendiendo a \u2018fuetazos\u2019, pero siempre ayud\u00f3 mucho mi personalidad, porque me acept\u00e9 tal y como soy, y aprend\u00ed a quererme\u201d.<\/p>\n<p>Luego agreg\u00f3: \u201cEn algunos momentos me ca\u00eda, pero yo era un gallito que me dec\u00eda p\u00e1rate de ah\u00ed. Me impuse, y me terminaron aceptando tal y como soy. Me he cuidado de no perder mi esencia y seguir siendo la misma Cheddy para todo el mundo\u201d.<\/p>\n<p><b>La conquista<\/b><br \/>\nVarios son los momentos en que ha estado en el piso, sin trabajo y con muchas deudas. Es precisamente en una de esas situaciones que el cineasta Bladimir Abud la llam\u00f3 para la pel\u00edcula \u201cLa lucha de Ana\u201d y su carrera da un giro de 180 grados.<\/p>\n<p>Ella asegura que esta pel\u00edcula divide su carrera en un antes y un despu\u00e9s. \u201cS\u00ed, porque entonces la gente me tom\u00f3 realmente en serio, porque tuve la oportunidad de demostrar que no solo era una comediante, que hab\u00eda trabajado en Telemicro, con Freddy o en \u2018Perdone la hora\u2019. Mi talento lo pude llevar a otro nivel de la actuaci\u00f3n\u201d.<\/p>\n<p>Con esta cinta Cheddy visit\u00f3 pa\u00edses en donde le ofrecen manejar su carrera como actriz de cine, pero, a la vez, su trabajo en el cine dominicano se coloca en uno de los puntos m\u00e1s altos, hasta que logra conectar con un p\u00fablico clase A al que no hab\u00eda podido llegar.<\/p>\n<p>\u201cNunca fue mi objetivo llegar a un p\u00fablico m\u00e1s selecto. Yo soy una mujer de pueblo, y todos los que me siguen me quieren por lo que soy. No conquist\u00e9 a mi p\u00fablico cambiando mi esencia, ni negando lo que soy. A la gente le encanta el personaje de La Mam\u00e1, que hago en \u2018M\u00e1s Roberto\u2019 (canal 11) y \u2018Bien de bien\u2019 (canal 2) y creo que las redes sociales han sido vitales para esta pegada que tengo ahora\u201d, afirm\u00f3.<\/p>\n<p>Para ella no existe un p\u00fablico popular, selecto o clase A. \u201cNo puede existir diferencia entre ambos p\u00fablicos. Yo hago lo mismo para todo el mundo y lo importante es que a todos les gusta. Soy una emisaria de la alegr\u00eda en mi pa\u00eds\u201d.<\/p>\n<p><span style=\"color: #ffa500;\"><b>(+)<br \/>\nPREPARA SUS 25 A\u00d1OS\u00a0DE CARRERA ART\u00cdSTICA<\/b><\/span><\/p>\n<p><b>Retos:<\/b> Desea continuar conquistando al nuevo p\u00fablico para el que se prepara siempre, utilizando un nuevo lenguaje y estando a la vanguardia con todo lo que acontece.<\/p>\n<p><b>Aniversario: <\/b>Este 2015 celebra 25 a\u00f1os como humorista. Aunque no tiene nada planificado todav\u00eda, espera celebrarlo en grande.<\/p>\n<p><b>Televisi\u00f3n internacional:<\/b>\u00a0Tras el \u00e9xito conquistado, Cheddy est\u00e1 segura de que no tiene nada que buscar en la televisi\u00f3n extranjera. \u201cDe la \u00fanica manera que aceptar\u00eda una propuesta para hacer televisi\u00f3n internacional es que no tenga que dejar definitivamente mi pa\u00eds. Yo podr\u00eda ir a cualquier pa\u00eds a grabar, pero tengo que regresar, porque yo estoy muy bien aqu\u00ed. No creo que podr\u00eda ir a comenzar de cero en otro pa\u00eds, cuando ya he conquistado tanto en mi pa\u00eds\u201d, asegura.<\/p>\n<p><b>Vulgaridad:<\/b> A los humoristas del canal 5 se les calificaba de hacer un humor vulgar. A esto Cheddy responde: \u201cNosotros est\u00e1bamos conscientes para el p\u00fablico que est\u00e1bamos trabajando. Que cometimos errores, es cierto, pero lo fuimos corrigiendo y hoy el humor est\u00e1 en los hombros de ese grupo de muchachos, como Raymond, Miguel, Fausto Mata y yo. Cuando trabaj\u00e9 con Freddy, demostr\u00e9 con \u201cLa Negrita Caridad\u201d que s\u00ed pod\u00eda hacer otro tipo de humor. Hoy ya lo hemos trabajado en el cine haciendo drama\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0Mercedes Jos\u00e9 Garc\u00eda, a quien la conocen \u00a0como Cheddy Garc\u00eda, \u201cLa Mam\u00e1 del Humor\u201d, nunca plane\u00f3 ser humorista ni imagin\u00f3 vivir del arte. De ni\u00f1a fue una excelente estudiante y gracias a sus altas calificaciones logr\u00f3 ser becada en la Universidad Nacional Pedro Henr\u00edquez Ure\u00f1a (UNPHU), en donde inici\u00f3 la carrera de pedagog\u00eda.<\/p>\n","protected":false},"author":12,"featured_media":40918,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-40915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=40915"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40915\/revisions"}],"predecessor-version":[{"id":40919,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40915\/revisions\/40919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/40918"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=40915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=40915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=40915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}