{"id":40991,"date":"2015-04-02T15:30:42","date_gmt":"2015-04-02T19:30:42","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=40991"},"modified":"2015-04-01T22:56:09","modified_gmt":"2015-04-02T02:56:09","slug":"causas-frecuentes-de-los-mareos-y-como-prevenirlos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/causas-frecuentes-de-los-mareos-y-como-prevenirlos\/","title":{"rendered":"Causas frecuentes de los mareos y c\u00f3mo prevenirlos"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/7-Remedios-Naturales-para-el-Mareo.png\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-40993 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/7-Remedios-Naturales-para-el-Mareo-300x200.png\" alt=\"7-Remedios-Naturales-para-el-Mareo\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/7-Remedios-Naturales-para-el-Mareo-300x200.png 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/7-Remedios-Naturales-para-el-Mareo-105x70.png 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/7-Remedios-Naturales-para-el-Mareo.png 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>En la mayor\u00eda de las ocasiones, los s\u00edntomas desaparecen al poco tiempo y no suelen necesitar tratamientos. Es necesario tener <label>cuidado<\/label> cuando los mareos se producen con poca distancia entre s\u00ed, o si permanece la sensaci\u00f3n durante m\u00e1s de una hora.<!--more--><\/p>\n<p>El mareo es una sensaci\u00f3n por la cual la persona cree que va a desmayarse o perder el conocimiento. Existen diferentes grados de mareos y est\u00e1n producidos por variadas causas.<\/p>\n<p><strong>Causas de los mareos: banales y graves<\/strong><br \/>\nDentro de los motivos por los que se producen los mareos, podemos diferenciar dos grandes grupos: los banales y los graves.<\/p>\n<p><strong>El primer grupo est\u00e1 relacionado con la falta de sangre en el cerebro, debido a:<\/strong><\/p>\n<p>Disminuci\u00f3n repentina de la presi\u00f3n arterial.<br \/>\nDeshidrataci\u00f3n (no tener suficiente <label>agua<\/label> en el organismo) por v\u00f3mitos, diarrea, fiebre, no beber l\u00edquidos por un largo per\u00edodo.<br \/>\nLevantarse muy r\u00e1pido de la cama o de una silla (m\u00e1s frecuente en personas mayores).<br \/>\nReducci\u00f3n de los niveles de <label>az\u00facar<\/label> en sangre (hipoglucemia, en pacientes con diabetes, mayormente).<br \/>\nInsolaci\u00f3n y pasar largos per\u00edodos bajo el sol sin <label>protecci\u00f3n<\/label>.<br \/>\nResfriados y gripes o tambi\u00e9n alergias que no permiten consumir mucho l\u00edquido.<br \/>\nEl movimiento en alg\u00fan medio de <label>transporte<\/label> (barco, avi\u00f3n, autom\u00f3vil).<\/p>\n<p><strong>El segundo grupo de causas de los mareos est\u00e1 compuesto por:<\/strong><\/p>\n<p>Problemas card\u00edacos, como puede ser un infarto.<br \/>\nHemorragia interna.<br \/>\nAccidente cerebrovascular.<br \/>\nEmbolia.<br \/>\nShock y ca\u00edda brusca de la presi\u00f3n arterial.<\/p>\n<p>En estos casos, adem\u00e1s de estar embotado, el paciente sufre otros s\u00edntomas tales como taquicardia, dolor tor\u00e1cico, visi\u00f3n nublosa o p\u00e9rdida del habla.<\/p>\n<p><strong>Remedios caseros para tratar los mareos<\/strong><br \/>\nSiempre y cuando los mareos correspondan al primer grupo, existen algunos tratamientos caseros que pueden ayudar a revertir el cuadro. En el caso de deberse al segundo grupo, se debe ir al m\u00e9dico de inmediato.<\/p>\n<p><strong>Comer chocolate<\/strong><br \/>\nEn primer lugar porque tiene az\u00facar y puede elevar la glucosa en sangre. Por otra parte, el hecho de masticar algo dulce sirve para que el cerebro vuelva a recibir sangre. Un pedazo peque\u00f1o es suficiente.<\/p>\n<p><strong>Beber zumo de manzana<\/strong><br \/>\nEsta maravillosa fruta tiene muchas propiedades como, por ejemplo, quitarnos el mareo repentino. Si sientes que el piso se est\u00e1 moviendo, recu\u00e9state y bebe media taza de zumo de manzana. Tambi\u00e9n sirve para aumentar los niveles de az\u00facar en caso de personas diab\u00e9ticas.<\/p>\n<p><strong>Una cucharada de menta con az\u00facar<\/strong><br \/>\nSi tienes una planta de menta, corta algunas hojas y combina con az\u00facar. Come como si fuera una golosina. En 5 minutos, aproximadamente, ya no te sentir\u00e1s m\u00e1s mareado.<\/p>\n<p><strong>Bebe un t\u00e9 con jengibre<\/strong><br \/>\nEste remedio casero est\u00e1 recomendado para personas que se marean cuando viajan. Solo tienes que preparar un t\u00e9 com\u00fan y a\u00f1adir media cucharadita de jengibre rallado. Una infusi\u00f3n ser\u00e1 suficiente.<\/p>\n<p><strong>Tratamiento fr\u00edo-calor<\/strong><br \/>\nSi el mareo est\u00e1 producido por un dolor o contractura en las cervicales, realiza un tratamiento de fr\u00edo-calor en esa zona. Coloca primero unos cubos de hielo (siempre con un pa\u00f1o, o bolsa) y luego date una ducha caliente (tambi\u00e9n puedes colocar una bolsa de agua caliente en la nuca).<\/p>\n<p><strong>\u00bfTe mareas cuando viajas? Presta atenci\u00f3n a estos consejos<\/strong><br \/>\nUna de las causas m\u00e1s frecuentes de mareos banales es el movimiento del transporte en el que nos encontramos. El 80% de los viajeros lo sufren y mucho tienen que ver en el cuadro el estr\u00e9s, la ansiedad, los nervios, la falta de sue\u00f1o y el jet lag.<\/p>\n<p><strong>Si te sueles marear cada vez que viajas y realmente lo pasas mal en el avi\u00f3n, el coche, el barco o el tren, ten en cuenta algunos consejos:<\/strong><\/p>\n<p>Elige las zonas de menor movimiento de cada medio de transporte (la cubierta del barco, los asientos cercanos a las alas del avi\u00f3n, el asiento delantero del autom\u00f3vil o el primer vag\u00f3n del tren).<\/p>\n<p>Al sentarte, inclina la cabeza hacia atr\u00e1s para que apoye completamente en el asiento.<\/p>\n<p>Evita la lectura o cualquier actividad que requiera mantener la vista fija en un lugar como, por ejemplo, hacer crucigramas, escribir, etc.<\/p>\n<p>Mant\u00e9n tu eje de visi\u00f3n en un \u00e1ngulo de 45 grados encima de la l\u00ednea del horizonte. Si viajas en barco, puedes mirar las olas o cualquier objeto que est\u00e9 en movimiento.<\/p>\n<p>Si viajas en crucero, trata de adquirir un camarote con una buena ventilaci\u00f3n y lo m\u00e1s cercano posible a la cubierta, para poder salir a respirar aire fresco cuando sea necesario.<\/p>\n<p>En el coche, evita la calefacci\u00f3n muy alta o estar demasiado abrigado, as\u00ed como tambi\u00e9n los olores fuertes como el del tabaco (adem\u00e1s, el humo del cigarrillo nos quita una buena parte del ox\u00edgeno que respiramos).<\/p>\n<p>No consumas mucho alcohol o comas en demas\u00eda antes de viajar, porque eso aumenta la posibilidad de marearse. Tampoco subas a un medio de transporte con el est\u00f3mago vac\u00edo, porque puede ocurrir lo mismo<\/p>\n<p>Consume durante el trayecto peque\u00f1as cantidades de l\u00edquidos (agua, infusiones o zumos naturales, nada de caf\u00e9, refrescos o bebidas alcoh\u00f3licas).<\/p>\n<p>Si el viaje es corto, trata de no comer nada hasta llegar a tu destino.<\/p>\n<p><strong>M\u00e1s consejos para evitar mareos<\/strong><br \/>\nEvita los cambios de posici\u00f3n o de postura muy bruscos, ya que se desequilibran los l\u00edquidos de los canales internos del o\u00eddo.<br \/>\nSi crees que vas a perder la consciencia, t\u00fambate en el suelo para evitar el golpe en la ca\u00edda.<br \/>\nTen siempre un caramelo en el bolso o bolsillo para comer en cualquier momento que te baje el az\u00facar en sangre.<br \/>\nSi\u00e9ntate en una silla y levanta las piernas mientras respiras lento y pausado<br \/>\nNo cierres los ojos, porque eso te puede marear m\u00e1s todav\u00eda.<\/p>\n<p>Fuente: <a href=\"http:\/\/mejorconsalud.com\/causas-frecuentes-de-los-mareos-y-como-prevenirlos\/\" target=\"_blank\">Mejor con salud<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la mayor\u00eda de las ocasiones, los s\u00edntomas desaparecen al poco tiempo y no suelen necesitar tratamientos. Es necesario tener cuidado cuando los mareos se producen con poca distancia entre s\u00ed, o si permanece la sensaci\u00f3n durante m\u00e1s de una hora.<\/p>\n","protected":false},"author":3,"featured_media":40993,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-40991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=40991"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40991\/revisions"}],"predecessor-version":[{"id":40994,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/40991\/revisions\/40994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/40993"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=40991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=40991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=40991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}