{"id":41186,"date":"2015-04-06T12:19:34","date_gmt":"2015-04-06T16:19:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=41186"},"modified":"2015-06-11T21:00:54","modified_gmt":"2015-06-12T01:00:54","slug":"06-de-abril-dia-nacional-del-psicologo-dominicano","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/06-de-abril-dia-nacional-del-psicologo-dominicano\/","title":{"rendered":"06 de Abril, d\u00eda nacional del Psic\u00f3logo Dominicano"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/buen-ejemplo-de-carta-de-presentacion-de-un-psicologo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-41188  aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/buen-ejemplo-de-carta-de-presentacion-de-un-psicologo.jpg\" alt=\"buen-ejemplo-de-carta-de-presentacion-de-un-psicologo\" width=\"644\" height=\"428\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/buen-ejemplo-de-carta-de-presentacion-de-un-psicologo.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/buen-ejemplo-de-carta-de-presentacion-de-un-psicologo-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/buen-ejemplo-de-carta-de-presentacion-de-un-psicologo-105x70.jpg 105w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/a><\/p>\n<p>Por: Lic. Priscilla Rodr\u00edguez Almonte<\/p>\n<p><strong>Ser Psic\u00f3log@<\/strong><br \/>\nEl devenir de la psicolog\u00eda dominicana ha resurgido dentro de comienzos filos\u00f3ficos sociales y obras del quehacer anal\u00edtico del comportamiento del dominicano. Estas ideas trajeron a relucir y dar paso a una Psicolog\u00eda como ciencia y reconocida como profesi\u00f3n en el pa\u00eds.<!--more--><\/p>\n<p>Seg\u00fan Rodr\u00edguez Arias 2009, en su art\u00edculo una \u201cBreve Rese\u00f1a hist\u00f3rica sobre la Psicolog\u00eda en Rep\u00fablica Dominicana, el 6 de abril de 1975, es fundada la Asociaci\u00f3n Dominicana de\u00a0Psicolog\u00eda\u00a0(ADOPSI), fecha elegida por los colegas dominicanos como el \u00a0D\u00eda Nacional.\u00a0 La formaci\u00f3n profesional en Psicolog\u00eda hab\u00eda empezado en <a href=\"http:\/\/es.wikipedia.org\/wiki\/Rep%C3%BAblica_Dominicana\">Rep\u00fablica Dominicana<\/a>\u00a0algunos a\u00f1os atr\u00e1s, en 1967, cuando, de modo casi simult\u00e1neo, la\u00a0<a href=\"http:\/\/uasd.edu.do\/facultades\/humanidades\/humanidades.htm\">Universidad Aut\u00f3noma de Santo Domingo<\/a>\u00a0(UASD, oficial) y la\u00a0<a href=\"http:\/\/www.unphu.edu.do\/\">Universidad Nacional Pedro Henr\u00edquez Ure\u00f1a\u00a0<\/a>(UNPHU, privada), crearon sendos departamentos de psicolog\u00eda, dentro del ambiente de apertura y crecimiento del sistema educativo superior de este pa\u00eds, posterior al fin de la dictadura de Trujillo. En virtud ,\u00a0 la\u00a0Asociaci\u00f3n Dominicana de\u00a0Psicolog\u00eda\u00a0ha pasado a ser, en virtud de\u00a0la ley No. 22-01 del 1ro. de febrero de 2001, Colegio Dominicano de Psic\u00f3logos (<a href=\"http:\/\/codopsi.tripod.com\/\">CODOPSI<\/a>).<\/p>\n<p>En 1950, el dominicano Enrique Pat\u00edn, Dr. en Derecho y Filosof\u00eda, public\u00f3 un op\u00fasculo que conten\u00eda dos ensayos (Pat\u00edn, 1950).\u00a0 El primero y m\u00e1s extenso trata de los complejos del pensamiento dominicano y el segundo sobre el alma de nuestra plebe.<\/p>\n<p>Rodr\u00edguez Arias hace referencia\u00a0 de Pat\u00edn citando del ensayo de el Pensamiento Dominicano:<\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-41187 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/buen-ejemplo-de-carta-de-presentacion-de-un-psicologo2.jpg\" alt=\"buen-ejemplo-de-carta-de-presentacion-de-un-psicologo2\" width=\"410\" height=\"272\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/buen-ejemplo-de-carta-de-presentacion-de-un-psicologo2.jpg 702w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/buen-ejemplo-de-carta-de-presentacion-de-un-psicologo2-300x199.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/buen-ejemplo-de-carta-de-presentacion-de-un-psicologo2-105x70.jpg 105w\" sizes=\"auto, (max-width: 410px) 100vw, 410px\" \/>\u201cEl pueblo dominicano necesita de una ideolog\u00eda sabia que le d\u00e9 conciencia de su propio valor, que le quite de los ojos la bruma que empa\u00f1a su visi\u00f3n.\u00a0 La carencia que hay en nosotros de hombres de pensamiento dificulta la empresa. Por lo regular la mayor parte de nuestra juventud se inclina al Arte, muy pocos se entregan al cultivo de la Filosof\u00eda o la Ciencia.<\/em><\/p>\n<p><em>Conocer lo que somos; saber lo que fueron nuestros antepasados; valorar certeramente sus actos; apreciar con exactitud lo que valemos, tal es lo que esperamos que nuestros hombres de estudio nos hagan aprender. (Pat\u00edn, op. cit., pp. 28-29).\u201d<\/em><\/p>\n<p>Todo lo anteriormente citado arroja luces de fronteras y desarrollo que a la vez\u00a0 se formulan el quehacer psicol\u00f3gico dominicano. No es menos cierto, que desde sus inicios a la actualidad ha incrementado el auge profesional y quehacer de las \u00e1reas\u00a0 de psicolog\u00eda, pero no es menos cierto que aquellas personas graduadas de psicolog\u00eda son o han sido propiamente dicho. \u00a0El ensayo de Pat\u00edn, y su visi\u00f3n que ya hac\u00eda en los a\u00f1os 1950, a\u00fan prevalecen, y me enfoco en el ejercicio profesional del psic\u00f3logo y la identidad del mismo. El psic\u00f3logo necesita crear de manera m\u00e1s fuerte \u00a0un quehacer cient\u00edfico que propicie una acertada aceptaci\u00f3n social, proyectando confianza y valoraci\u00f3n a la profesi\u00f3n que tanto se necesita en nuestra poblaci\u00f3n. Conocer lo que valemos, qu\u00e9 somos, a d\u00f3nde vamos, qu\u00e9 ofrecemos, cuales son las herramientas te\u00f3ricas-pr\u00e1cticas internacionales aplicables a nuestra poblaci\u00f3n carente.<\/p>\n<p>En las universidades es cada vez mayor el n\u00famero de estudiantes que incursionan en la carrera. Es aqu\u00ed entonces,\u00a0 la pregunta en cuesti\u00f3n \u00bfQu\u00e9 es ser psic\u00f3logo?<\/p>\n<p>Catalina Haitsch, en su obra <em>Identidad del psic\u00f3logo<\/em> se\u00f1ala que cuestionar es el comienzo de la propia experiencia de identidad<\/p>\n<p>Ser Psic\u00f3logo implica m\u00e1s que un proceso universitario de cuatro a cinco a\u00f1os, ser psic\u00f3logo es tener una identidad determinada y congruente con tu persona, ser psic\u00f3logo es conocerte y conocer el humano en sus dimensiones, ser psic\u00f3logo no es adivinar el pasado tu presente o fututo,\u00a0 ser psic\u00f3logo no es dar partido a tus saberes filos\u00f3ficos, ser psic\u00f3logo no es estar a la vanguardia en las redes sociales, ser psic\u00f3logo implica una \u00e9tica personal-profesional arraigada en tu persona desde que escoges estudiarla. Es un proceso que se mantiene vigente y din\u00e1mico al pasar el tiempo.<\/p>\n<p>Tenemos si, se ha logrado mucho en los diferentes campos de la psicolog\u00eda en el pa\u00eds, pero todav\u00eda necesita desarrollarse m\u00e1s. Necesitamos m\u00e1s, m\u00e1s voces de personas como Pat\u00edn, m\u00e1s empe\u00f1o como Tilso Mejia Ricart, pionero del departamento de psicolog\u00eda de la UASD.<\/p>\n<p>Necesitamos m\u00e1s \u201c<em>conciencia de su propio valor, que le quite de los ojos la bruma que empa\u00f1a su visi\u00f3n&#8230;\u00a0 tal es lo que esperamos que nuestros hombres de estudio nos hagan aprender\u201d<\/em><\/p>\n<p>La sociedad no es lo que nos limita a Ser Psic\u00f3logos, somos nosotros, como profesionales de la psicolog\u00eda, nosotros somos los que a nuestros reposa el peso de aquellos que forjaron pensamientos, filosof\u00edas e ideales.<\/p>\n<p>Las personas esperan confiar en nosotros, en nuestros conocimientos cient\u00edficos como ciencia, en nuestra profesi\u00f3n como consciencia profesional, ligado a nuestra personalidad de manera que proyectamos una responsabilidad social. \u00bfQu\u00e9 brindamos nosotros<em>?<\/em><\/p>\n<p>Forjemos todos, desde hoy una Psicolog\u00eda\u00a0 diferente, Un sentido de SER PSICOLOGO. M\u00e1s que palabras, t\u00edtulos, certificados, TU SENTIDO, Psicol\u00f3gico din\u00e1mico, un agente de cambio.<\/p>\n<p>\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1Feliz D\u00eda Nacional del Psic\u00f3logo!!!!!!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Lic. Priscilla Rodr\u00edguez Almonte Ser Psic\u00f3log@ El devenir de la psicolog\u00eda dominicana ha resurgido dentro de comienzos filos\u00f3ficos sociales y obras del quehacer anal\u00edtico del comportamiento del dominicano. Estas ideas trajeron a relucir y dar paso a una Psicolog\u00eda como ciencia y reconocida como profesi\u00f3n en el pa\u00eds.<\/p>\n","protected":false},"author":12,"featured_media":41188,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-41186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/41186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=41186"}],"version-history":[{"count":5,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/41186\/revisions"}],"predecessor-version":[{"id":44520,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/41186\/revisions\/44520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/41188"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=41186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=41186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=41186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}