{"id":41270,"date":"2015-04-07T22:31:50","date_gmt":"2015-04-08T02:31:50","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=41270"},"modified":"2015-04-07T22:35:46","modified_gmt":"2015-04-08T02:35:46","slug":"wwe-hulk-hogan-y-scott-steiner-en-lio-por-presunto-intento-de-asesinato","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/wwe-hulk-hogan-y-scott-steiner-en-lio-por-presunto-intento-de-asesinato\/","title":{"rendered":"WWE: Hulk Hogan y Scott Steiner en l\u00edo por presunto intento de asesinato"},"content":{"rendered":"<div id=\"attachment_41275\" style=\"width: 318px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/1016090.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-41275\" class=\"wp-image-41275 \" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/1016090.jpg\" alt=\"1016090\" width=\"308\" height=\"184\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/1016090.jpg 610w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/1016090-300x179.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/1016090-105x63.jpg 105w\" sizes=\"auto, (max-width: 308px) 100vw, 308px\" \/><\/a><p id=\"caption-attachment-41275\" class=\"wp-caption-text\">Hulk Hogan y Scott Steiner en l\u00edo por presunto intento de asesinato (Foto: TMZ\/Getty)<\/p><\/div>\n<p>A veces, unas simples palabras, dichas quiz\u00e1s sin mala intenci\u00f3n, son suficientes para originar todo un problema. Eso fue lo que pas\u00f3 con Hulk Hogan y Scott Steiner, quienes ahora son protagonistas de la \u00faltima denuncia por un intento de asesinato que est\u00e1 dando que hablar en la far\u00e1ndula estadounidense.<!--more--><\/p>\n<p>Todo comenz\u00f3 el 26 de marzo, cuando Jennifer McDaniel\u2019s, la esposa de Hulk Hogan, lleg\u00f3 en avi\u00f3n a San Jos\u00e9 (San Francisco) para asistir a Wrestlemania y se encontr\u00f3 con Scott Steiner en la zona de equipaje.<\/p>\n<p>Este le dijo que ten\u00eda planeado \u201cmatar a a Terry (Gene Bollea, el verdadero nombre de Hulk Hogan)\u201d, alarmando a la se\u00f1ora, quien no ten\u00eda idea de qui\u00e9n era el hombre que le hab\u00eda dicho tremenda amenaza.<\/p>\n<p>Fue por eso que la tom\u00f3 en serio y, ni bien su esposo lleg\u00f3 a San Jos\u00e9, unas horas despu\u00e9s, lo llev\u00f3 a presentar una denuncia policial a la ma\u00f1ana siguiente.<\/p>\n<p>La p\u00e1gina <a href=\"http:\/\/www.tmz.com\/2015\/04\/07\/scott-steiner-threatened-to-kill-hulk-hogan-police-investigation\">TMZ<\/a> inform\u00f3 que por todo esto se ha abierto una investigaci\u00f3n contra Scott Steiner por el presuntos delito de \u201camenazas terroristas\u201d e, incluso, se est\u00e1 investigando los videos de vigilancia que habr\u00edan registrado el momento en que el luchador habr\u00eda confrontado a Jennifer McDaniel\u2019s.<\/p>\n<p>Cierta o no la amenaza -aunque todo parece haber sido una confusi\u00f3n-, el referido sitio web record\u00f3 que en realidad s\u00ed existen diferencias entre el luchador conocido tambi\u00e9n como \u2018Big Poppa Pumped\u2019 y Hulk Hogan.<\/p>\n<p>Seg\u00fan dicen, Scott Steiner lo culpa por la desaparici\u00f3n de la WCW, compa\u00f1\u00eda de lucha libre que en 2001 fue comprada por la WWE y en la que ambos formaron parte del legendario grupo NWO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A veces, unas simples palabras, dichas quiz\u00e1s sin mala intenci\u00f3n, son suficientes para originar todo un problema. Eso fue lo que pas\u00f3 con Hulk Hogan y Scott Steiner, quienes ahora son protagonistas de la \u00faltima denuncia por un intento de asesinato que est\u00e1 dando que hablar en la far\u00e1ndula estadounidense.<\/p>\n","protected":false},"author":12,"featured_media":41275,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-41270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/41270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=41270"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/41270\/revisions"}],"predecessor-version":[{"id":41276,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/41270\/revisions\/41276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/41275"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=41270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=41270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=41270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}