{"id":41284,"date":"2015-04-08T12:07:58","date_gmt":"2015-04-08T16:07:58","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=41284"},"modified":"2015-04-08T10:20:32","modified_gmt":"2015-04-08T14:20:32","slug":"los-vengadores-secuela-no-tendra-escena-despues-de-los-creditos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-vengadores-secuela-no-tendra-escena-despues-de-los-creditos\/","title":{"rendered":"Los Vengadores: Secuela no tendr\u00e1 escena despu\u00e9s de los cr\u00e9ditos"},"content":{"rendered":"<p><strong><em><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/vengadores-era-ultron.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-41285 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/vengadores-era-ultron.jpg\" alt=\"vengadores-era-ultron\" width=\"611\" height=\"458\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/vengadores-era-ultron.jpg 611w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/vengadores-era-ultron-300x225.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/vengadores-era-ultron-100x75.jpg 100w\" sizes=\"auto, (max-width: 611px) 100vw, 611px\" \/><\/a>Estados Unidos<\/em><\/strong>. Los estudios <strong>Marvel<\/strong> siempre han presentado en todas sus pel\u00edculas una escena extra luego de los cr\u00e9ditos finales. En esta ocasi\u00f3n, la cinta Los Vengadores: La Era de Ultr\u00f3n <strong>no tendr\u00e1 dichas escenas, seg\u00fan el director Joss Whedon<\/strong>.<!--more--><\/p>\n<p>En entrevista con <strong>Entertainment Weekly<\/strong>, Whedon dijo que eso no se har\u00e1 en esta oportunidad<strong>porque no hay manera de superar la escena post cr\u00e9ditos de The Avengers<\/strong>; donde Iron Man, el Incre\u00edble Hulk, Hawkeye, Thor y el Capit\u00e1n Am\u00e9rica comen shawarma tras la batalla de Nueva York.<\/p>\n<p><em>\u201cNo hay nada al final de todo. Y eso no es falso. Queremos que la gente sepa de modo que no tienen que sentarse por 10 minutos y entonces decir \u2018\u00a1hijo de perra! \u00a1los matar\u00e9!\u2018\u201d<\/em>, recalc\u00f3. No obstante, habr\u00e1 un peque\u00f1o ep\u00edlogo poco despu\u00e9s de que inicien los cr\u00e9ditos, como el de Thanos en la cinta del 2012.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estados Unidos. Los estudios Marvel siempre han presentado en todas sus pel\u00edculas una escena extra luego de los cr\u00e9ditos finales. En esta ocasi\u00f3n, la cinta Los Vengadores: La Era de Ultr\u00f3n no tendr\u00e1 dichas escenas, seg\u00fan el director Joss Whedon.<\/p>\n","protected":false},"author":12,"featured_media":41285,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-41284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/41284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=41284"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/41284\/revisions"}],"predecessor-version":[{"id":41286,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/41284\/revisions\/41286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/41285"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=41284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=41284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=41284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}