{"id":41409,"date":"2015-04-11T13:56:03","date_gmt":"2015-04-11T17:56:03","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=41409"},"modified":"2015-04-11T13:56:03","modified_gmt":"2015-04-11T17:56:03","slug":"spurs-frenan-a-harden-y-llegan-a-10-victorias-seguidas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/spurs-frenan-a-harden-y-llegan-a-10-victorias-seguidas\/","title":{"rendered":"Spurs frenan a Harden y llegan a 10 victorias seguidas"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/Los-Spurs.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-41416 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/Los-Spurs.jpg\" alt=\"Los Spurs\" width=\"348\" height=\"232\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/Los-Spurs.jpg 348w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/Los-Spurs-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/Los-Spurs-105x70.jpg 105w\" sizes=\"auto, (max-width: 348px) 100vw, 348px\" \/><\/a>HOUSTON.<\/strong>&#8211; Los Spurs buscaron evitar que el bal\u00f3n cayera en manos de James Harden durante buena parte de la segunda mitad. Y en la \u00faltima ocasi\u00f3n en que el astro de los Rockets tom\u00f3 la pelota, San Antonio impidi\u00f3 que encestara.<!--more--><br \/>\nTim Duncan anot\u00f3 el viernes 29 puntos y bloque\u00f3 la bandeja de Harden a 2,9 segundos del final, para darle a San Antonio su d\u00e9cimo triunfo en fila, por 104-103 sobre Houston.<\/p>\n<p>San Antonio avanz\u00f3 al tercer lugar en la Conferencia del Oeste, mientras que Houston cay\u00f3 del cuarto al sexto sitio.<\/p>\n<p>Los Spurs gozaban una ventaja de cuatro puntos cuando Harden se col\u00f3 para sus primeros tantos de la mitad a falta de menos de 90 segundos.<\/p>\n<p>Duncan fall\u00f3 una bandeja antes de que Harden encestara un triple con 28,9 segundos restantes, para acercar a Houston 104-103. Tony Parker perdi\u00f3 el bal\u00f3n, d\u00e1ndole una \u00faltima oportunidad a Houston.<\/p>\n<p>Pero Duncan bloque\u00f3 el intento de Harden y se qued\u00f3 con el rebote para asegurar el triunfo.<\/p>\n<p>\u00abTengo que definir\u00bb, lament\u00f3 Harden. \u00abTengo que definir estas jugadas\u00bb.<\/p>\n<p>El apretado marcador puso fin a una racha de los Spurs, de nueve triunfos en fila por al menos 12 puntos, lo que hab\u00eda empatado un r\u00e9cord de la NBA.<\/p>\n<p>Pero fue una victoria al fin, y a San Antonio le funcion\u00f3 la estrategia de privar del bal\u00f3n al astro de Houston.<\/p>\n<p>\u00abYo prefiero cualquier cosa antes de darle la pelota a Harden\u00bb, coment\u00f3 el entrenador de los Spurs, Gregg Popovich. \u00abEs algo que da miedo\u00bb.<\/p>\n<p>Por los Spurs, el argentino Manu Gin\u00f3bili termin\u00f3 con seis tantos, dos rebotes y cuatro asistencias en 21 minutos.<\/p>\n<p>Por los Rockets, el argentino Pablo Prigioni tuvo dos unidades, una asistencia y dos robos de bal\u00f3n en 17 minutos.<\/p>\n<p>Con la derrota de los Rockets, los Grizzlies de Memphis se colocaron un juego arriba en la lucha por el t\u00edtulo de la Divisi\u00f3n del Suroeste, al superar 89-88 al Jazz de Utah.<\/p>\n<p><strong>Otros resultados<\/strong><\/p>\n<p>Los Pelicans de Nueva Orle\u00e1ns doblegaron 90-75 a los Suns de Phoenix, y mantuvieron el paso con Oklahoma City en la disputa por el octavo y \u00faltimo puesto a playoffs en la Conferencia del Oeste. El Thunder arroll\u00f3 106-103 a los Kings de Sacramento.<\/p>\n<p>Por su parte, los Bucks de Milwaukee vencieron 99-91 a los Knicks de Nueva York y se colocaron en la antesala de los playoffs. Redujeron a uno su \u00abn\u00famero m\u00e1gico\u00bb para asegurar un sitio en la postemporada.<\/p>\n<p>Los Pacers de Indiana superaron 107-103 a los Pistons de Detroit, para colocarse un juego detr\u00e1s de Brooklyn y Boston en la lucha por los \u00faltimos dos boletos para la postemporada en el Este.<\/p>\n<p>Esos tres equipos ganaron el viernes. Los Celtics derrotaron 99-90 a los Cavaliers de Cleveland y los Nets trituraron 117-80 a los Wizards de Washington.<\/p>\n<p>Adem\u00e1s, los Hawks de Atlanta aplastaron 104-80 a los Hornets de Charlotte, para llegar a 60 victorias por primera vez en la historia de la franquicia; los Raptors de Toronto se impusieron 101-99 al Magic de Orlando; los Mavericks de Dallas superaron 144-143 a los Nuggets de Denver en dos pr\u00f3rrogas, y los Lakers de Los \u00c1ngeles se impusieron 106-98 a los Timberwolves de Minnesota.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>HOUSTON.&#8211; Los Spurs buscaron evitar que el bal\u00f3n cayera en manos de James Harden durante buena parte de la segunda mitad. Y en la \u00faltima ocasi\u00f3n en que el astro de los Rockets tom\u00f3 la pelota, San Antonio impidi\u00f3 que encestara.<\/p>\n","protected":false},"author":12,"featured_media":41416,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-41409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/41409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=41409"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/41409\/revisions"}],"predecessor-version":[{"id":41417,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/41409\/revisions\/41417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/41416"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=41409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=41409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=41409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}