{"id":42089,"date":"2015-04-24T10:12:06","date_gmt":"2015-04-24T14:12:06","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=42089"},"modified":"2015-04-22T06:22:42","modified_gmt":"2015-04-22T10:22:42","slug":"chuletas-de-cerdo-al-grill","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/chuletas-de-cerdo-al-grill\/","title":{"rendered":"chuletas de cerdo al grill"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/IMG_1997.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-42092 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/IMG_1997.jpg\" alt=\"IMG_1997\" width=\"640\" height=\"427\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/IMG_1997.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/IMG_1997-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/IMG_1997-105x70.jpg 105w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><br \/>\nHacer una<strong> chuleta al grill<\/strong> no tiene misterio ninguno pero si es cierto que para que queden tiernas y jugosas debemos de seguir unos consejos b\u00e1sicos. <!--more-->La chuleta debe de tener<strong> un grosor de al menos 2 mm<\/strong> para que no quede seca. El grill lo debemos de poner al fuego, con un poco de aceite bien extendido, al menos 10 minutos para que tenga una temperatura bastante alta antes de poner las chuletas.<\/p>\n<p>Se cocinar\u00e1n <strong>4 minutos por cada lado<\/strong>. Una vez pasado el\u00a0tiempo de la primera cara de la chuleta y le demos la vuelta, es cuando ponemos la sal, antes no porque para que la sal no haga que la carne suelte jugos y se nos cocine en ese jugo, queremos que se haga a la braza, en el grill, no cocinada en su jugo como si la estuvi\u00e9ramos cociendo.<\/p>\n<p><strong>Una vez que saquemos las chuletas del grill,<\/strong> podemos extenderle una capa de salsa barbacoa por una cara, bien extendida con una brocha, le daremos un toque de sabor a barbacoa muy rico. Otra opci\u00f3n es poner especias barbacoa, ya la venden as\u00ed preparada en los supermercados en la zona de tarros de especias. Las especias, en caso de elegirlas, las pondremos en las chuletas unos 10 minutos antes de llevarlas al grill.<\/p>\n<p>\u00bfTe animas a preparar unas ricas<strong> chuletas al grill<\/strong>? Pues toma nota que comenzamos.<\/p>\n<div class=\"easyrecipe\">\n<div class=\"ERSDetails\">\n<h3 class=\"ERSClear\"><\/h3>\n<\/div>\n<div class=\"ERSIngredients\">\n<h3 class=\"ERSIngredientsHeader ERSHeading\">Ingredientes<\/h3>\n<ul>\n<li class=\"ingredient\">8 chuletas de cerdo<\/li>\n<li class=\"ingredient\">Sal<\/li>\n<li class=\"ingredient\">Aceite de oliva virgen extra<\/li>\n<li class=\"ingredient\">Salsa barbacoa o especias para barbacoa<\/li>\n<\/ul>\n<div class=\"ERSClear\"><\/div>\n<\/div>\n<div class=\"ERSInstructions\">\n<h3 class=\"ERSInstructionsHeader ERSHeading\">Instrucciones<\/h3>\n<ol>\n<li class=\"instruction\">Ponemos el grill con un poco de aceite al fuego, dejamos calentar 10 minutos.<\/li>\n<li class=\"instruction\">Si vamos a usar las especias, ahora la espolvoreamos sobre la carne, si no la vamos a usar, dejamos la carne tal cual.<\/li>\n<li class=\"instruction\">Cuando el grill est\u00e9 muy caliente, ponemos las chuletas, de esa manera conseguimos que se marquen las rallitas.<\/li>\n<li class=\"instruction\">Dejamos 4 minutos y damos la vuelta.<\/li>\n<li class=\"instruction\">Ponemos un poco de sal en las chuletas.<\/li>\n<li class=\"instruction\">Dejamos otros 4 minutos y sacamos.<\/li>\n<li class=\"instruction\">Si no hemos puesto especias, ahora ponemos un poco de salsa barbacoa bien extendida con una brocha sobre la superficie de la chuleta reci\u00e9n saca y a\u00fan caliente.<\/li>\n<li class=\"instruction\">Servimos.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hacer una chuleta al grill no tiene misterio ninguno pero si es cierto que para que queden tiernas y jugosas debemos de seguir unos consejos b\u00e1sicos.<\/p>\n","protected":false},"author":12,"featured_media":42092,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-42089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=42089"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42089\/revisions"}],"predecessor-version":[{"id":42093,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42089\/revisions\/42093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/42092"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=42089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=42089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=42089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}