{"id":42097,"date":"2015-04-22T06:34:28","date_gmt":"2015-04-22T10:34:28","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=42097"},"modified":"2015-04-22T06:34:28","modified_gmt":"2015-04-22T10:34:28","slug":"un-fallo-en-ios-deja-a-atacantes-reiniciar-iphones-cercanos-a-redes-wifi","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/un-fallo-en-ios-deja-a-atacantes-reiniciar-iphones-cercanos-a-redes-wifi\/","title":{"rendered":"Un fallo en iOS deja a atacantes reiniciar iPhones cercanos a redes WiFi"},"content":{"rendered":"<p class=\"first-text\" data-textannotation-id=\"1e99aeb9749e109be34ccc6eaff6adaf\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_iPhone-6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-29049 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_iPhone-6.jpg\" alt=\"iPhone-6\" width=\"280\" height=\"233\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_iPhone-6.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_iPhone-6-300x250.jpg 300w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/><\/a>Investigadores en seguridad han destapado una vulnerabilidad en iOS 8 desconocida hasta ahora que, explotada correctamente, podr\u00eda ser bastante peligrosa. El fallo permite a un atacante intervenir una red WiFi y forzar a reiniciar a los iPhones y iPads cercanos, incluso si su due\u00f1o no se ha conectado.<!--more--><\/p>\n<p data-textannotation-id=\"f5491297bd849a070cdbc7c3fc2b2454\">La vulnerabilidad, bautizada como \u201c <em>No iOS Zone<\/em>\u201d por los investigadores que la han descubierto, Adi Sharabani y Yair Amit, de la compa\u00f1\u00eda Skycure, es en realidad unavulnerabilidad de d\u00eda cero, es decir, se desconoc\u00eda su existencia hasta ahora. La compa\u00f1\u00eda ha demostrado su funcionamiento en una conferencia de seguridad aunque no ha publicado detalles t\u00e9cnicos por no haberse encontrado una soluci\u00f3n a la misma. Los investigadores han asegurado a <em>The Register<\/em> que ya trabajan con Apple en solucionarla. \u00bfC\u00f3mo funciona?<\/p>\n<p data-textannotation-id=\"3a12df8934ff2a8f795883a9a34a3507\">B\u00e1sicamente se trata de un ataque de denegaci\u00f3n de servicio que un cibercriminal puede lanzar sobre los equipos iOS cercanos a una red WiFi. La vulnerabilidad se aprovecha de un fallo en iOS 8 que permite manipular los certificados SSL utilizados en casi todas las apps y que se env\u00edan al dispositivo a trav\u00e9s de la red WiFi o celular. De esta forma, el atacante puede reiniciar en remoto el iPhone o iPad cercano. \u201c <em>Imagina el impacto de una posibilidad as\u00ed cerca de Wall Street, o de un aeropuerto, o de una planta el\u00e9ctrica<\/em>\u201d, explican los investigadores. Han publicado varios v\u00eddeos mostrando la vulnerabilidad (mejor quita el sonido porque la m\u00fasica es diab\u00f3lica):<\/p>\n<p class=\"has-media media-640\" data-textannotation-id=\"55ca8f7e1fa3505e6b0a8fb50037f778\"><span class=\"clear-both flex-video widescreen\"><iframe loading=\"lazy\" id=\"youtube-PmgI0LaFYLA\" class=\"youtube\" src=\"http:\/\/www.youtube.com\/embed\/PmgI0LaFYLA?wmode=transparent&amp;rel=0&amp;autohide=1&amp;showinfo=0&amp;enablejsapi=1\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-chomp-id=\"PmgI0LaFYLA\"><\/iframe><\/span><\/p>\n<p class=\"has-media media-640\" data-textannotation-id=\"0dd51463df72e23419fbee0e132d78c9\"><span class=\"clear-both flex-video widescreen\"><iframe loading=\"lazy\" id=\"youtube-NhiTfsWUp30\" class=\"youtube\" src=\"http:\/\/www.youtube.com\/embed\/NhiTfsWUp30?wmode=transparent&amp;rel=0&amp;autohide=1&amp;showinfo=0&amp;enablejsapi=1\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-chomp-id=\"NhiTfsWUp30\"><\/iframe><\/span><\/p>\n<p data-textannotation-id=\"6469e6ec647326617bd3ed0561d549dc\">Lo preocupante es que, para lanzar el ataque, el usuario no necesita haberse conectado por s\u00ed mismo a la red WiFi, simplemente necesita estar cerca de la misma. El atacante, utilizando otra vulnerabilidad conocida como WiFiGate, puede forzar al equipo a conectarse a la red WiFi sin que el usuario siquiera se entere. El cibercriminal tampoco necesita infiltrar una una red WiFi existente, puede crear \u00e9l mismo una, darle un nombre fiable o poco sospechoso, y cazar a los dispositivos iOS cercanos a la misma.<\/p>\n<p data-textannotation-id=\"b5a3b1802b1bfac9638f5f0223e0195f\">Los investigadores aseguran que ni ellos ni Apple tienen conocimiento de que esta vulnerabilidad se haya utilizado, pero la posibilidad existe, de ah\u00ed la no publicaci\u00f3n de los detalles t\u00e9cnicos. Lo bueno: ya trabajan en parchear el fallo. Bien. [ <a href=\"https:\/\/www.skycure.com\/blog\/ios-shield-allows-dos-attacks-on-ios-devices\/\" target=\"_blank\">Skycure <\/a>v\u00eda <a href=\"http:\/\/www.theregister.co.uk\/2015\/04\/22\/apple_no_ios_zone_bug\/\" target=\"_blank\">The Register<\/a>]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Investigadores en seguridad han destapado una vulnerabilidad en iOS 8 desconocida hasta ahora que, explotada correctamente, podr\u00eda ser bastante peligrosa. El fallo permite a un atacante intervenir una red WiFi y forzar a reiniciar a los iPhones y iPads cercanos, incluso si su due\u00f1o no se ha conectado.<\/p>\n","protected":false},"author":12,"featured_media":29049,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-42097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=42097"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42097\/revisions"}],"predecessor-version":[{"id":42099,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42097\/revisions\/42099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29049"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=42097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=42097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=42097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}