{"id":42236,"date":"2015-04-25T16:22:49","date_gmt":"2015-04-25T20:22:49","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=42236"},"modified":"2015-04-25T00:29:59","modified_gmt":"2015-04-25T04:29:59","slug":"salsa-de-ciruelas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/salsa-de-ciruelas\/","title":{"rendered":"Salsa de ciruelas"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/Salsa-de-ciruelas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-42237 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/Salsa-de-ciruelas.jpg\" alt=\"Salsa de ciruelas\" width=\"285\" height=\"320\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/Salsa-de-ciruelas.jpg 530w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/Salsa-de-ciruelas-267x300.jpg 267w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/Salsa-de-ciruelas-67x75.jpg 67w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/a>La salsa de ciruelas pasas es una salsa deliciosa para acompa\u00f1ar al tradicional pavo. Esta salsa tambi\u00e9n es un excelente acompa\u00f1ante para una variedad de carnes, como la de cerdo, pollo y pato. <!--more-->Las ciruelas pasas se remojan durante la noche en vino tinto y vino oporto, luego se los cocina en una salsa con cebolla tipo chalote y vinagre bals\u00e1mico. Hay muchas variaciones de la salsa de ciruelas, algunos tambi\u00e9n le agregan mostaza, salsa de tomate, otros frutos secos y especias.<\/p>\n<div id=\"zlrecipe-container-23\" class=\"zlrecipe-container-border\">\n<div id=\"zlrecipe-container\" class=\"serif zlrecipe\">\n<div id=\"zlrecipe-innerdiv\">\n<div class=\"img-desc-wrap\">\n<div id=\"zlrecipe-summary\">\n<p class=\"summary italic\">Salsa de ciruelas para pavo y carnes, preparada con ciruelas pasas, vino tinto, vino oporto, cebolla chalote y vinagre bals\u00e1mico.<\/p>\n<\/div>\n<\/div>\n<p id=\"zlrecipe-ingredients\" class=\"h-4 strong\">Ingredientes<\/p>\n<ul id=\"zlrecipe-ingredients-list\">\n<li id=\"zlrecipe-ingredient-0\" class=\"ingredient\">1 libra ciruelas pasas, sin semillas<\/li>\n<li id=\"zlrecipe-ingredient-1\" class=\"ingredient\">1 taza de vino tinto<\/li>\n<li id=\"zlrecipe-ingredient-2\" class=\"ingredient\">1 \u00bd tazas vino oporto<\/li>\n<li id=\"zlrecipe-ingredient-3\" class=\"ingredient\">2 cucharadas de mantequilla<\/li>\n<li id=\"zlrecipe-ingredient-4\" class=\"ingredient\">3-4 cebollas tipo chalote, finamente picados<\/li>\n<li id=\"zlrecipe-ingredient-5\" class=\"ingredient\">\u00bd taza de vinagre bals\u00e1mico<\/li>\n<li id=\"zlrecipe-ingredient-6\" class=\"ingredient\">Una pizca de sal<\/li>\n<li id=\"zlrecipe-ingredient-7\" class=\"ingredient\"><\/li>\n<\/ul>\n<p id=\"zlrecipe-instructions\" class=\"h-4 strong\">Preparaci\u00f3n<\/p>\n<ol id=\"zlrecipe-instructions-list\" class=\"instructions\">\n<li id=\"zlrecipe-instruction-0\" class=\"instruction\">Cubra las ciruelas pasas con el vino oporto y el vino tinto, dej\u00e1ndolas en remojo durante la noche.<\/li>\n<li id=\"zlrecipe-instruction-1\" class=\"instruction\">En una cacerola u olla mediana caliente la mantequilla y a\u00f1ada la cebolla picada, cocine hasta est\u00e9n suaves y transparentes, aproximadamente unos 5 minutos.<\/li>\n<li id=\"zlrecipe-instruction-2\" class=\"instruction\">A\u00f1ada las ciruelas pasas remojadas con el l\u00edquido del remojo, el vinagre bals\u00e1mico y una pizca de sal.<\/li>\n<li id=\"zlrecipe-instruction-3\" class=\"instruction\">Haga hervir, reduzca el fuego a medio-bajo y cocine durante 25 a 30 minutos. Revuelva de vez en cuando, pero con cuidado, de modo que las ciruelas mantengan su forma. Retire del fuego y sirva caliente.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2558\" title=\"Remoje las ciruelas con vino tinto y vino oporto\" src=\"http:\/\/laylita.com\/recetas\/wp-content\/uploads\/1-Remoje-las-ciruelas-con-vino-tinto-y-vino-oporto.jpg\" alt=\"1- Remoje las ciruelas con vino tinto y vino oporto\" width=\"320\" height=\"214\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2559\" title=\"Cocine la cebolla o chalotes con la mantequilla\" src=\"http:\/\/laylita.com\/recetas\/wp-content\/uploads\/2-Cocine-la-cebolla-o-chalotes-con-la-mantequilla.jpg\" alt=\"2- Cocine la cebolla o chalotes con la mantequilla\" width=\"320\" height=\"214\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2560\" title=\"Agregue las ciruelas con el vino del remojo, el vinagre balsamico y una pizca de sal\" src=\"http:\/\/laylita.com\/recetas\/wp-content\/uploads\/3-Agregue-las-ciruelas-con-el-vino-del-remojo-el-vinagre-balsamico-y-una-pizca-de-sal.jpg\" alt=\"3- Agregue las ciruelas con el vino del remojo, el vinagre balsamico y una pizca de sal\" width=\"320\" height=\"214\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2561\" title=\"Cocine durante 25 a 30 minutos\" src=\"http:\/\/laylita.com\/recetas\/wp-content\/uploads\/4-Cocine-durante-25-a-30-minutos.jpg\" alt=\"4- Cocine durante 25 a 30 minutos\" width=\"320\" height=\"214\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2562\" title=\"Salsa de ciruelas pasas para pavo\" src=\"http:\/\/laylita.com\/recetas\/wp-content\/uploads\/5-Salsa-de-ciruelas-pasas-para-pavo.jpg\" alt=\"5- Salsa de ciruelas pasas para pavo\" width=\"320\" height=\"214\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2563\" title=\"Salsa de ciruelas con pavo\" src=\"http:\/\/laylita.com\/recetas\/wp-content\/uploads\/6-Salsa-de-ciruelas-con-pavo.jpg\" alt=\"6- Salsa de ciruelas con pavo\" width=\"320\" height=\"214\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La salsa de ciruelas pasas es una salsa deliciosa para acompa\u00f1ar al tradicional pavo. Esta salsa tambi\u00e9n es un excelente acompa\u00f1ante para una variedad de carnes, como la de cerdo, pollo y pato.<\/p>\n","protected":false},"author":12,"featured_media":42237,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-42236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=42236"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42236\/revisions"}],"predecessor-version":[{"id":42238,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42236\/revisions\/42238"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/42237"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=42236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=42236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=42236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}