{"id":42293,"date":"2015-04-26T17:13:53","date_gmt":"2015-04-26T21:13:53","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=42293"},"modified":"2015-04-26T17:13:53","modified_gmt":"2015-04-26T21:13:53","slug":"corte-japonesa-ordena-borrar-resenas-negativas-de-google-maps","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/corte-japonesa-ordena-borrar-resenas-negativas-de-google-maps\/","title":{"rendered":"Corte japonesa ordena borrar rese\u00f1as negativas de Google Maps"},"content":{"rendered":"<p class=\"excerpt ng-binding\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/12496426_f79990a45b_b-960x623.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-42296 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/12496426_f79990a45b_b-960x623.jpg\" alt=\"12496426_f79990a45b_b-960x623\" width=\"735\" height=\"490\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/12496426_f79990a45b_b-960x623.jpg 934w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/12496426_f79990a45b_b-960x623-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/12496426_f79990a45b_b-960x623-105x70.jpg 105w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/><br \/>\n<\/a>La decisi\u00f3n podr\u00eda sentar un precedente sobre las facultades de una corte local hacia el trabajo de Google.<!--more--><\/p>\n<p>La <strong>Corte del Distrito de Chiba<\/strong>, en Jap\u00f3n, ha ordenado a <strong>Google<\/strong> que retire dos rese\u00f1as negativas de una cl\u00ednica sin revelar, informa<em>TechCrunch<\/em>. Las rese\u00f1as, que reflejan una experiencia negativa de los clientes, deber\u00e1n ser retirada de Google Maps debido a una acusaci\u00f3n de difamaci\u00f3n por parte de la instituci\u00f3n m\u00e9dica.<\/p>\n<p>Esto parece una solicitud cualquiera para retirar contenidos, pero el problema es que la corte ha ordenado que no s\u00f3lo se quiten los comentarios en Jap\u00f3n, sino <strong>de manera global<\/strong>. Normalmente, este tipo de peticiones \u00fanicamente tienen una jurisdicci\u00f3n dentro del pa\u00eds, pero esta vez, la corte local ha determinado que el alcance de su decisi\u00f3n sea mundial.<\/p>\n<p>De acuerdo con Google, las opiniones no infringen las pol\u00edticas de contenidos de su servicio, a pesar de lo que se\u00f1alado por la corte. \u00abCreemos que las rese\u00f1as en l\u00ednea son una herramienta cr\u00edtica para que la gente d\u00e9 y lea una retroalimentaci\u00f3n directa sobre los negocios\u00bb, se\u00f1al\u00f3 Google en una declaraci\u00f3n a <em>TechCrunch.<\/em><\/p>\n<p>La situaci\u00f3n abre varios problemas, ya que la retroalimentaci\u00f3n sobre un servicio m\u00e9dico puede ser muy valiosa para futuros pacientes. Si la corte japonesa permite que las cr\u00edticas se retiren por una solicitud de difamaci\u00f3n, esto podr\u00eda sentar un precedente peligroso para borrar contenidos seg\u00fan conveniencia.<\/p>\n<p>As\u00ed mismo, cabe en la discusi\u00f3n preguntarse si una corte local tiene la injerencia para solicitar que se elimine un contenido de manera global. \u00bfTienes esta corte japonesa la facultad de obligar a Google a borrar algo para cualquier acceso en el mundo? Por supuesto, Google va a pelear esta decisi\u00f3n en los tribunales. Habr\u00e1 que estar atentos a la decisi\u00f3n final, ya que puede afectar la discusi\u00f3n actual sobre el alcance de estas medidas y el acceso a la informaci\u00f3n en la red.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La decisi\u00f3n podr\u00eda sentar un precedente sobre las facultades de una corte local hacia el trabajo de Google.<\/p>\n","protected":false},"author":12,"featured_media":42296,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-42293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=42293"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42293\/revisions"}],"predecessor-version":[{"id":42297,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42293\/revisions\/42297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/42296"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=42293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=42293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=42293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}