{"id":42310,"date":"2015-05-09T09:34:43","date_gmt":"2015-05-09T13:34:43","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=42310"},"modified":"2015-05-01T16:51:01","modified_gmt":"2015-05-01T20:51:01","slug":"pescado-a-la-parrilla-con-salsa-de-mariscos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/pescado-a-la-parrilla-con-salsa-de-mariscos\/","title":{"rendered":"Pescado a la parrilla con salsa de mariscos"},"content":{"rendered":"<div id=\"zlrecipe-container-52\" class=\"zlrecipe-container-border\">\n<div id=\"zlrecipe-container\" class=\"serif zlrecipe\">\n<div id=\"zlrecipe-innerdiv\">\n<div class=\"img-desc-wrap\">\n<div id=\"zlrecipe-summary\">\n<p class=\"summary italic\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/pesacado-al-vapor.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-42318 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/pesacado-al-vapor.jpg\" alt=\"pesacado-al-vapor\" width=\"640\" height=\"427\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/pesacado-al-vapor.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/pesacado-al-vapor-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/pesacado-al-vapor-105x70.jpg 105w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><br \/>\nPescado asado o pescado a la parrilla en salsa de mariscos al ajillo preparada con camarones o gambas, calamar, vieiras, ajo, cebolla, vino blanco y crema.<!--more--><\/p>\n<\/div>\n<\/div>\n<p id=\"zlrecipe-ingredients\" class=\"h-4 strong\">Ingredientes<\/p>\n<ul>\n<li id=\"zlrecipe-ingredient-0\" class=\"ingredient\">2 libras de filete de pescado<\/li>\n<li id=\"zlrecipe-ingredient-1\" class=\"ingredient\">\u00bd libra de camarones crudos, pelado y sin venitas<\/li>\n<li id=\"zlrecipe-ingredient-2\" class=\"ingredient\">\u00bd libra de calamar, cortado en pedazos peque\u00f1os<\/li>\n<li id=\"zlrecipe-ingredient-3\" class=\"ingredient\">\u00bd libra de vieiras o conchitas de abanico peque\u00f1as<\/li>\n<li id=\"zlrecipe-ingredient-4\" class=\"ingredient\">2 cucharadas de mantequilla<\/li>\n<li id=\"zlrecipe-ingredient-5\" class=\"ingredient\">2 cucharadas de cebolla blanca, picada finamente<\/li>\n<li id=\"zlrecipe-ingredient-6\" class=\"ingredient\">6 dientes de ajo, picados finamente<\/li>\n<li id=\"zlrecipe-ingredient-7\" class=\"ingredient\">\u00bc taza de vino blanco<\/li>\n<li id=\"zlrecipe-ingredient-8\" class=\"ingredient\">\u00bd taza de crema de leche<\/li>\n<li id=\"zlrecipe-ingredient-9\" class=\"ingredient\">Sal y pimienta al gusto<\/li>\n<\/ul>\n<div id=\"zlrecipe-ingredient-10\" class=\"ingredient-label\">Para acompa\u00f1ar:<\/div>\n<ul id=\"zlrecipe-ingredients-list\">\n<li id=\"zlrecipe-ingredient-11\" class=\"ingredient\">Papitas al perejil<\/li>\n<li id=\"zlrecipe-ingredient-12\" class=\"ingredient\">Verduras al vapor o a la parrilla<\/li>\n<li id=\"zlrecipe-ingredient-13\" class=\"ingredient\">Arroz o quinua<\/li>\n<li id=\"zlrecipe-ingredient-14\" class=\"ingredient\">Pan<\/li>\n<li id=\"zlrecipe-ingredient-15\" class=\"ingredient\"><\/li>\n<\/ul>\n<p id=\"zlrecipe-instructions\" class=\"h-4 strong\">Preparaci\u00f3n<\/p>\n<ol id=\"zlrecipe-instructions-list\" class=\"instructions\">\n<li id=\"zlrecipe-instruction-0\" class=\"instruction\">Sazone el pescado con sal y pimienta negra. Caliente la parrilla y ase el pescado justamente cuando la salsa de mariscos este casi terminada para que se puedan servir calientes.<\/li>\n<li id=\"zlrecipe-instruction-1\" class=\"instruction\">Derrita la mantequilla a temperatura media en un sart\u00e9n de buen tama\u00f1o, a\u00f1ada la cebolla y el ajo, cocine por unos dos minutos.<\/li>\n<li id=\"zlrecipe-instruction-2\" class=\"instruction\">A\u00f1ada los camarones o gambas y cocine por dos minutos m\u00e1s.<\/li>\n<li id=\"zlrecipe-instruction-3\" class=\"instruction\">A\u00f1ada el vino blanco, mezcle bien y cocine por dos minutos m\u00e1s.<\/li>\n<li id=\"zlrecipe-instruction-4\" class=\"instruction\">A\u00f1ada la crema y cocine hasta que los camarones est\u00e9n casi listos.<\/li>\n<li id=\"zlrecipe-instruction-5\" class=\"instruction\">A\u00f1ada el calamar y las vieiras o conchitas de abanico, cocine por solo uno a dos minutos y retire del fuego,<\/li>\n<li id=\"zlrecipe-instruction-6\" class=\"instruction\">Sirva la salsa de mariscos al lado o encima del pescado a la parilla, espolvoree con el perejil picado.<\/li>\n<li id=\"zlrecipe-instruction-7\" class=\"instruction\">Acompa\u00f1e el pescado y la salsa de mariscos con una tajada de lim\u00f3n, papas al perejil, verduras al vapor y pan.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" id=\"image103\" src=\"http:\/\/laylita.com\/recetas\/wp-content\/uploads\/2008\/02\/Seafood%20sauce.JPG\" alt=\"Salsa de mariscos\" \/> <img decoding=\"async\" id=\"image101\" src=\"http:\/\/laylita.com\/recetas\/wp-content\/uploads\/2008\/02\/grilled%20ling%20cod%20with%20seafood%20sauce14.JPG\" alt=\"pescado a la parrilla\" \/><br \/>\n<img decoding=\"async\" id=\"image102\" src=\"http:\/\/laylita.com\/recetas\/wp-content\/uploads\/2008\/02\/grilled%20ling%20cod%20with%20seafood%20sauce15.JPG\" alt=\"Pescado con salsa de mariscos y papas al perejil\" \/> <img decoding=\"async\" id=\"image97\" src=\"http:\/\/laylita.com\/recetas\/wp-content\/uploads\/2008\/02\/grilled%20ling%20cod%20with%20seafood%20sauce1.JPG\" alt=\"pescado a la parrilla con salsa de mariscos\" \/><br \/>\n<img decoding=\"async\" id=\"image100\" src=\"http:\/\/laylita.com\/recetas\/wp-content\/uploads\/2008\/02\/grilled%20ling%20cod%20with%20seafood%20sauce13.JPG\" alt=\"pescado a la parrilla y salsa de mariscos\" \/> <img decoding=\"async\" id=\"image104\" src=\"http:\/\/laylita.com\/recetas\/wp-content\/uploads\/2008\/02\/DSC06322.JPG\" alt=\"Pescado en salsa de mariscos\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" id=\"image98\" title=\"Pescado a la parrilla con salsa de mariscos\" src=\"http:\/\/laylita.com\/recetas\/wp-content\/uploads\/2008\/02\/grilled%20ling%20cod%20with%20seafood%20sauce2.JPG\" alt=\"Pescado a la parrilla con salsa de mariscos\" width=\"320\" height=\"214\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" id=\"image95\" title=\"Pescado a la parrilla con salsa de mariscos\" src=\"http:\/\/laylita.com\/recetas\/wp-content\/uploads\/2008\/02\/grilled%20ling%20cod%20with%20seafood%20sauce.JPG\" alt=\"Pescado a la parrilla con salsa de mariscos\" width=\"320\" height=\"214\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pescado asado o pescado a la parrilla en salsa de mariscos al ajillo preparada con camarones o gambas, calamar, vieiras, ajo, cebolla, vino blanco y crema.<\/p>\n","protected":false},"author":12,"featured_media":42318,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-42310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=42310"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42310\/revisions"}],"predecessor-version":[{"id":42330,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42310\/revisions\/42330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/42318"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=42310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=42310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=42310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}