{"id":42505,"date":"2015-04-29T07:04:34","date_gmt":"2015-04-29T11:04:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=42505"},"modified":"2015-04-29T07:04:34","modified_gmt":"2015-04-29T11:04:34","slug":"lista-de-peliculas-de-superheroes-que-producira-marvel","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/lista-de-peliculas-de-superheroes-que-producira-marvel\/","title":{"rendered":"Lista de pel\u00edculas de superh\u00e9roes que producir\u00e1 Marvel"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/Lista-de-pel\u00edculas-de-superh\u00e9roes-que-producir\u00e1-Marvel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-42506 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/Lista-de-pel\u00edculas-de-superh\u00e9roes-que-producir\u00e1-Marvel.jpg\" alt=\"Lista-de-pel\u00edculas-de-superh\u00e9roes-que-producir\u00e1-Marvel\" width=\"660\" height=\"350\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/Lista-de-pel\u00edculas-de-superh\u00e9roes-que-producir\u00e1-Marvel.jpg 660w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/Lista-de-pel\u00edculas-de-superh\u00e9roes-que-producir\u00e1-Marvel-300x159.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/Lista-de-pel\u00edculas-de-superh\u00e9roes-que-producir\u00e1-Marvel-105x56.jpg 105w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/a>Marvel <\/strong>anunci\u00f3 un listado de todas las<strong> pel\u00edculas que producir\u00e1 en los pr\u00f3ximos a\u00f1os<\/strong>, esto incluye las continuaciones de las pel\u00edculas m\u00e1s exitosas de este a\u00f1o.<!--more--><\/p>\n<p>Todas las pel\u00edculas fueron anunciadas junto a su <strong>fecha de estreno <\/strong>y lo mejor de todo, todas son de los superh\u00e9roes m\u00e1s famosos.<\/p>\n<p>\u00a1Conoce aqu\u00ed el <strong>listado<\/strong>!<\/p>\n<ul>\n<li>Capit\u00e1n Am\u00e9rica: Guerra Civil &#8211; 6 de mayo de 2016<\/li>\n<li>Guardianes de la Galaxia 2 &#8211; 5 de mayo de 2017<\/li>\n<li>Pantera Negra &#8211; 3 de noviembre de 2017<\/li>\n<li>Capit\u00e1n Marvel &#8211; 6 de julio de 2018<\/li>\n<li>Doctor Strange &#8211; 7 de noviembre de 2016<\/li>\n<li>Thor 3: Ragnarok &#8211; 8 de julio de 2017<\/li>\n<li>Inhumano &#8211; 2 de noviembre de 2018<\/li>\n<li>Avengers: Infinity War parte I &#8211; mayo 2018<\/li>\n<li>Avengers: Infinity War parte II &#8211; mayo 2019<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Marvel anunci\u00f3 un listado de todas las pel\u00edculas que producir\u00e1 en los pr\u00f3ximos a\u00f1os, esto incluye las continuaciones de las pel\u00edculas m\u00e1s exitosas de este a\u00f1o.<\/p>\n","protected":false},"author":12,"featured_media":42506,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-42505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=42505"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42505\/revisions"}],"predecessor-version":[{"id":42507,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42505\/revisions\/42507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/42506"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=42505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=42505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=42505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}