{"id":42510,"date":"2015-04-29T07:36:22","date_gmt":"2015-04-29T11:36:22","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=42510"},"modified":"2015-04-29T07:36:22","modified_gmt":"2015-04-29T11:36:22","slug":"una-madre-saca-a-golpes-a-su-hijo-de-las-protestas-en-baltimore-video","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/una-madre-saca-a-golpes-a-su-hijo-de-las-protestas-en-baltimore-video\/","title":{"rendered":"Una madre saca a golpes a su hijo de las protestas en Baltimore (VIDEO)"},"content":{"rendered":"<p><b class=\"fuente\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/wmar-madre-golpes-hijo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-42512 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/wmar-madre-golpes-hijo.jpg\" alt=\"wmar-madre-golpes-hijo\" width=\"624\" height=\"344\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/wmar-madre-golpes-hijo.jpg 624w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/wmar-madre-golpes-hijo-300x165.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/wmar-madre-golpes-hijo-105x58.jpg 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/wmar-madre-golpes-hijo-400x220.jpg 400w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><\/a><br \/>\n(CNN) \u2014 <\/b>Toya Graham es una madre soltera que ha sido dura con sus seis hijos y siempre velando por su bienestar.<!--more--><\/p>\n<p>Como le dijo a CNN una de sus hijas, Graham es la mujer en un video de los disturbios de la ciudad estadounidense de Baltimore que se ha convertido en un hecho muy comentado en internet.<\/p>\n<p>En el video\u00a0capturado por la estaci\u00f3n WMAR, filial de CNN, la mujer se ve jaloneando a su hijo enmascarado lejos de la multitud, le da golpes en la cabeza en repetidas ocasiones, y le grita.<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/slgqDr-PCDQ\" width=\"630\" height=\"410\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\nMientras \u00e9l trata de alejarse, ella lo sigue, gritando, \u00ab\u00a1l\u00e1rgate de aqu\u00ed!\u201d.<\/p>\n<p>Eventualmente, \u00e9l se vuelve hacia ella, y su rostro ya no est\u00e1 cubierto. El joven est\u00e1 vestido con pantalones oscuros y una sudadera con capucha negra, con una mochila negra encima.<\/p>\n<p>WMAR inform\u00f3 que la mujer vio a su hijo en la televisi\u00f3n lanzando piedras a la polic\u00eda.<\/p>\n<p>Graham dijo a CBS News que ella y su hijo vieron al joven y que la madre ni siquiera pens\u00f3 en que hab\u00eda c\u00e1maras de televisi\u00f3n cuando fue por su chico.<\/p>\n<p>\u00abEs mi \u00fanico hijo (var\u00f3n) y al final del d\u00eda no quiero que sea un Freddie Gray\u00bb, dijo a la cadena CBS, en referencia al joven negro que muri\u00f3 por un presunto abuso policial en una detenci\u00f3n, lo que motiv\u00f3 las protestas en Baltimore.<\/p>\n<p>Tameka Brown, una de las cinco hijas de Graham, dijo a CNN este martes que no era dif\u00edcil para su madre saber que se trataba de su hijo de 16 a\u00f1os.<\/p>\n<p>\u00abConoce a su hijo y lo tom\u00f3. Incluso con la m\u00e1scara puesta lo sab\u00eda\u00bb, dijo Brown.<\/p>\n<p>Su hermano est\u00e1 realmente agradecido de que su madre vino a buscarlo, dijo. \u00c9l entiende que Graham lo hizo porque quiere mantenerlo vivo.<\/p>\n<p>\u00abElla siempre ha sido dura y sabe d\u00f3nde estamos\u00bb, dijo Brown.<\/p>\n<p>El comisionado de Polic\u00eda, Anthony Batts, le dio las gracias en declaraciones a los medios de comunicaci\u00f3n.<\/p>\n<p>\u00abSi ves en una escena est\u00e1 una madre que tom\u00f3 a su hijo que ten\u00eda una capucha en la cabeza y empez\u00f3 a pegarle en la cabeza porque estaba muy avergonzada\u00bb, dijo el lunes.<\/p>\n<p>\u00abMe gustar\u00eda tener m\u00e1s padres que se hicieran cargo de sus hijos por ah\u00ed esta noche\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2014 Toya Graham es una madre soltera que ha sido dura con sus seis hijos y siempre velando por su bienestar.<\/p>\n","protected":false},"author":12,"featured_media":42512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-42510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=42510"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42510\/revisions"}],"predecessor-version":[{"id":42513,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42510\/revisions\/42513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/42512"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=42510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=42510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=42510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}