{"id":42693,"date":"2015-05-01T15:00:07","date_gmt":"2015-05-01T19:00:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=42693"},"modified":"2015-05-01T12:02:25","modified_gmt":"2015-05-01T16:02:25","slug":"ministerio-de-salud-exhorta-poblacion-usar-ropa-ligera-tomar-agua-y-jugos-naturales","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ministerio-de-salud-exhorta-poblacion-usar-ropa-ligera-tomar-agua-y-jugos-naturales\/","title":{"rendered":"Ministerio de Salud exhorta poblaci\u00f3n usar ropa ligera, tomar agua y jugos naturales"},"content":{"rendered":"<div class=\"not-pspace\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/857669C1-5A69-4D2E-B905-3CC46F90348B.jpg__270__200__CROPz0x270y200.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-42694 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/857669C1-5A69-4D2E-B905-3CC46F90348B.jpg__270__200__CROPz0x270y200.jpg\" alt=\"857669C1-5A69-4D2E-B905-3CC46F90348B.jpg__270__200__CROPz0x270y200\" width=\"270\" height=\"115\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/857669C1-5A69-4D2E-B905-3CC46F90348B.jpg__270__200__CROPz0x270y200.jpg 270w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/857669C1-5A69-4D2E-B905-3CC46F90348B.jpg__270__200__CROPz0x270y200-105x45.jpg 105w\" sizes=\"auto, (max-width: 270px) 100vw, 270px\" \/><\/a>SANTO DOMINGO.- Ante el evidente aumento de las temperaturas, debido al viento c\u00e1lido que llega desde el Mar Caribe y\u00a0 el Polvo del S\u00e1hara, proveniente de \u00c1frica, la Ministra de Salud,\u00a0<a name=\"more\"><\/a>doctora Altagracia Guzm\u00e1n Marcelino exhort\u00f3 a la poblaci\u00f3n a tomar abundante agua y otros l\u00edquidos, usar ropa ligera, consumir frutas y vegetales y evitar situaciones que contribuyan a sofocarse.<\/div>\n<p><!--more--><\/p>\n<div class=\"not-pspace\"><\/div>\n<div class=\"not-pspace\">El aviso se hace atendiendo a una alerta de la Oficina Nacional de Meteorolog\u00eda que pronostica que las temperaturas podr\u00edan subir a 40 grados y\u00a0 provocar intensas olas de calor en gran parte del pa\u00eds.<\/div>\n<div class=\"not-pspace\"><\/div>\n<div class=\"not-pspace\">Guzm\u00e1n Marcelino dijo que ante estas condiciones las personas deben permanecer calmadas, evitar el consumo abundante de sal, azucares, alimentos grasos, bebidas alcoh\u00f3licas y escoger ropas de colores claros y telas adecuadas a las altas temperaturas, principalmente cuando se trata de personas con ciertas condiciones que los hacen vulnerables.<\/div>\n<div class=\"not-pspace\"><\/div>\n<div class=\"not-pspace\">Estas medidas deben ser extremas y especialmente a las personas en condiciones vulnerables de salud, como enfermos cr\u00f3nicos, ni\u00f1os y ni\u00f1as, sobre todo si son reci\u00e9n nacidos, adultos mayores, mujeres embarazadas, personas con alguna forma de discapacidad, entre otros grupos, con los cuales se debe tener especial cuidado\u201d, expres\u00f3.<\/div>\n<div class=\"not-pspace\"><\/div>\n<div class=\"not-pspace\">Adem\u00e1s, llam\u00f3 a la ciudadan\u00eda a no exponerse directamente a los rayos solares en horas de las 11:00 de la ma\u00f1ana hasta las 4:00 de la tarde, evitar los ejercicios f\u00edsicos extremos, las discusiones y los lugares muy frecuentados, salvo que se estrictamente necesario.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- Ante el evidente aumento de las temperaturas, debido al viento c\u00e1lido que llega desde el Mar Caribe y\u00a0 el Polvo del S\u00e1hara, proveniente de \u00c1frica, la Ministra de Salud,\u00a0doctora Altagracia Guzm\u00e1n Marcelino exhort\u00f3 a la poblaci\u00f3n a tomar abundante agua y otros l\u00edquidos, usar ropa ligera, consumir frutas y vegetales y evitar situaciones que contribuyan a sofocarse.<\/p>\n","protected":false},"author":3,"featured_media":42694,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-42693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=42693"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42693\/revisions"}],"predecessor-version":[{"id":42695,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42693\/revisions\/42695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/42694"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=42693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=42693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=42693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}