{"id":42765,"date":"2015-05-02T09:19:07","date_gmt":"2015-05-02T13:19:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=42765"},"modified":"2015-05-02T09:19:07","modified_gmt":"2015-05-02T13:19:07","slug":"onamet-continuara-el-calor-se-aproxima-una-vaguada","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/onamet-continuara-el-calor-se-aproxima-una-vaguada\/","title":{"rendered":"Onamet: \u00abContinuar\u00e1 el calor, se aproxima una vaguada\u00bb"},"content":{"rendered":"<p class=\"post-title entry-title\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_Calor-4574783546hhggfrthy.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-17444 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_Calor-4574783546hhggfrthy.jpeg\" alt=\"Calor-4574783546hhggfrthy\" width=\"285\" height=\"177\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_Calor-4574783546hhggfrthy.jpeg 285w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_Calor-4574783546hhggfrthy-400x250.jpeg 400w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/a>Este s\u00e1bado se registrar\u00e1n incrementos nubosos,\u00a0probabilidad de aguaceros aislados y temperaturas calurosas debido a la proximidad de una vaguada, inform\u00f3 la Oficina Nacional de Meteorolog\u00eda (Onamet).<!--more--><\/p>\n<div id=\"post-body-1351978762493104549\" class=\"post-body entry-content\">\n<p>A\u00f1adi\u00f3 que la circulaci\u00f3n anticl\u00f3nica de la atm\u00f3sfera seguir\u00e1 generando condiciones clim\u00e1ticas de escasa humedad.<\/p>\n<p>La entidad subray\u00f3 que existen posibilidades de lluvias en las regiones Noroeste y la Cordillera Central.<\/p>\n<p>Onamet mantiene su recomendaci\u00f3n a la ciudadan\u00eda a que no se exponga a los rayos solares de 11:00 de la ma\u00f1ana a 4:00 de la tarde.<\/p>\n<p>&nbsp;<\/p>\n<p>Exhort\u00f3 a las autoridades forestales a poner atenci\u00f3n las zonas de bosques, debido al bajo contenido de humedad y las altas temperaturas.<\/p>\n<p>Meteorolog\u00eda recomend\u00f3 a la\u00a0ciudadan\u00eda a utilizar el agua de manera racial por el d\u00e9ficit pluviom\u00e9trico.<\/p>\n<p><strong>Pron\u00f3stico focalizado<\/strong><\/p>\n<p>Distrito Nacional: Nubes dispersas a despejado en ocasiones.<\/p>\n<p>Santo Domingo\u00a0Norte:\u00a0Nubes dispersas. Condiciones secas y calurosas para ma\u00f1ana<\/p>\n<p>Santo Domingo Oeste: Mezcla de nubes y sol.<\/p>\n<p>Santo Domingo Este: Mayormente despejado.<\/p>\n<p>Gran Santo Domingo:\u00a0La temperatura m\u00e1xima estar\u00e1 entre\u00a033\u00baC y 34\u00baC\u00a0y la m\u00ednima entre 23\u00baC y 24\u00baC.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este s\u00e1bado se registrar\u00e1n incrementos nubosos,\u00a0probabilidad de aguaceros aislados y temperaturas calurosas debido a la proximidad de una vaguada, inform\u00f3 la Oficina Nacional de Meteorolog\u00eda (Onamet).<\/p>\n","protected":false},"author":12,"featured_media":17444,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-42765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=42765"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42765\/revisions"}],"predecessor-version":[{"id":42766,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42765\/revisions\/42766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/17444"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=42765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=42765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=42765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}