{"id":42768,"date":"2015-05-02T09:26:00","date_gmt":"2015-05-02T13:26:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=42768"},"modified":"2015-05-02T09:26:00","modified_gmt":"2015-05-02T13:26:00","slug":"perdida-total-de-memoria-cientificos-revelan-que-pasara-con-el-cerebro-de-los-astronautas-en-marte","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/perdida-total-de-memoria-cientificos-revelan-que-pasara-con-el-cerebro-de-los-astronautas-en-marte\/","title":{"rendered":"\u00bfP\u00e9rdida total de memoria? Cient\u00edficos revelan qu\u00e9 pasar\u00e1 con el cerebro de los astronautas en Marte"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/astranautas-en-martes.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-42770 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/astranautas-en-martes.jpg\" alt=\"astranautas en martes\" width=\"451\" height=\"254\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/astranautas-en-martes.jpg 748w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/astranautas-en-martes-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/astranautas-en-martes-105x59.jpg 105w\" sizes=\"auto, (max-width: 451px) 100vw, 451px\" \/><\/a>La NASA se prepara ya para la primera misi\u00f3n espacial tripulada a Marte, sin embargo, un estudio advierte que la exposici\u00f3n prolongada de los astronautas a rayos c\u00f3smicos gal\u00e1cticos puede afectar su capacidad cognitiva para toda la vida.<!--more--><\/p>\n<p>La exposici\u00f3n a part\u00edculas cargadas altamente energ\u00e9ticas -muy parecidas a las que se encuentran en los rayos c\u00f3smicos que bombardean a los astronautas durante los vuelos espaciales prolongados- causan da\u00f1os significativos en el sistema nervioso central, lo que genera un deterioro cognitivo, seg\u00fan un estudio publicado en la revista &#8216;<a href=\"http:\/\/advances.sciencemag.org\/content\/1\/4\/e1400256\" target=\"_blank\">Science Advances<\/a>&#8216;.<\/p>\n<p>De acuerdo con los autores de la investigaci\u00f3n, la exposici\u00f3n prolongada en el tiempo a estas part\u00edculas provoca disminuciones del rendimiento, <strong>d\u00e9ficit de memoria<\/strong>, p\u00e9rdida de conciencia y atenci\u00f3n. Esos problemas adem\u00e1s \u00abpueden afectar a las actividades fundamentales de la misi\u00f3n\u00bb. Esa situaci\u00f3n \u00abpuede tener <strong>consecuencias negativas<\/strong> a largo plazo para la cognici\u00f3n durante toda la vida\u00bb.<\/p>\n<p>Aunque los efectos tardar\u00edan meses en manifestarse, el tiempo necesario para realizar una\u00a0misi\u00f3n a Marte\u00a0es suficiente para que este tipo de problemas se desarrollen. Tambi\u00e9n se\u00f1alan que esas part\u00edculas altamente energ\u00e9ticas atravesar\u00e1n incluso una nave espacial blindada y \u00abrealmente <strong>no hay forma de escapar<\/strong> de ellas\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La NASA se prepara ya para la primera misi\u00f3n espacial tripulada a Marte, sin embargo, un estudio advierte que la exposici\u00f3n prolongada de los astronautas a rayos c\u00f3smicos gal\u00e1cticos puede afectar su capacidad cognitiva para toda la vida.<\/p>\n","protected":false},"author":12,"featured_media":42770,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-42768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=42768"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42768\/revisions"}],"predecessor-version":[{"id":42771,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42768\/revisions\/42771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/42770"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=42768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=42768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=42768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}