{"id":42897,"date":"2015-05-04T17:00:11","date_gmt":"2015-05-04T21:00:11","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=42897"},"modified":"2015-05-04T15:05:10","modified_gmt":"2015-05-04T19:05:10","slug":"cuantos-anos-tienes-microsoft-lo-adivina-mirando-tus-fotos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cuantos-anos-tienes-microsoft-lo-adivina-mirando-tus-fotos\/","title":{"rendered":"\u00bfCu\u00e1ntos a\u00f1os tienes? Microsoft lo adivina mirando tus fotos"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/74cce5ae2bfd478e9ed5b0d48f7a3a75_620x350.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-42898 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/74cce5ae2bfd478e9ed5b0d48f7a3a75_620x350-300x200.jpg\" alt=\"74cce5ae2bfd478e9ed5b0d48f7a3a75_620x350\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/74cce5ae2bfd478e9ed5b0d48f7a3a75_620x350-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/74cce5ae2bfd478e9ed5b0d48f7a3a75_620x350-105x70.jpg 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/74cce5ae2bfd478e9ed5b0d48f7a3a75_620x350.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\u00bfNuevos memes a la vista? How Old Do I <label>Look<\/label> es una nueva herramienta experimental de<label>Microsoft<\/label> que calcula, algunas veces mejor que otras, la edad de cualquier persona analizando una <label>foto<\/label> suya.<!--more--><\/p>\n<p>En el segundo <label>d\u00eda<\/label> de actividades en Build 2015, Microsoft present\u00f3 una herramienta experimental bastante divertida: <a href=\"http:\/\/www.how-old.net\/\" target=\"_blank\">How Old Do I Look?<\/a><\/p>\n<p>Como su nombre lo indica, es un sitio experimental que se plantea el reto de adivinar la edad de cualquier persona examinando una foto suya. Esto mediante una <label>tecnolog\u00eda<\/label> que se ha desarrollado estudiando las caras de millones de fotos que circulan en la red.<\/p>\n<p>Ah\u00ed mismo podemos ver varios ejemplos de im\u00e1genes ya precargadas, pero lo m\u00e1s interesante y divertido es la posibilidad de subir nuestra propia foto, o la de nuestros amigos y familia, y ver qu\u00e9 tan eficaz es la herramienta.<\/p>\n<p>En nuestra experiencia y lo que han reportado diversos usuarios en redes sociales, la precisi\u00f3n de How Old Do I Look es bastante variable: a veces acertada, a veces no tanto. Microsoft aclara que siguen trabajando para que los resultados seran cada vez m\u00e1s certeros.<\/p>\n<p>Por supuesto, esta herramienta nos ha hecho el d\u00eda a muchos, y sospechamos que Microsoft acaba de crear una nueva clase de \u00abmemes\u00bb. Para muestra, estos ejemplos.<\/p>\n<p><iframe id=\"twitter-widget-2\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Cronolog\u00eda de Twitter\" width=\"300\" height=\"543\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><iframe id=\"twitter-widget-3\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Cronolog\u00eda de Twitter\" width=\"300\" height=\"736\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><iframe id=\"twitter-widget-4\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Cronolog\u00eda de Twitter\" width=\"300\" height=\"673\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><iframe id=\"twitter-widget-5\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Cronolog\u00eda de Twitter\" width=\"300\" height=\"612\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: <a href=\"http:\/\/www.sdpnoticias.com\/tecnologia\/2015\/04\/30\/cuantos-anos-tienes-microsoft-lo-adivina-mirando-tus-fotos\" target=\"_blank\">SDP<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfNuevos memes a la vista? How Old Do I Look es una nueva herramienta experimental deMicrosoft que calcula, algunas veces mejor que otras, la edad de cualquier persona analizando una foto suya.<\/p>\n","protected":false},"author":3,"featured_media":42898,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-42897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=42897"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42897\/revisions"}],"predecessor-version":[{"id":42899,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42897\/revisions\/42899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/42898"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=42897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=42897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=42897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}