{"id":42903,"date":"2015-05-04T18:10:31","date_gmt":"2015-05-04T22:10:31","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=42903"},"modified":"2015-05-04T15:16:33","modified_gmt":"2015-05-04T19:16:33","slug":"10-datos-curiosos-de-canada-que-no-debes-ignorar","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/10-datos-curiosos-de-canada-que-no-debes-ignorar\/","title":{"rendered":"10 Datos Curiosos de Canad\u00e1 que no debes ignorar"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/9179411817_949aae008d_b.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-42904 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/9179411817_949aae008d_b-300x200.jpg\" alt=\"9179411817_949aae008d_b\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/9179411817_949aae008d_b-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/9179411817_949aae008d_b.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/9179411817_949aae008d_b-105x70.jpg 105w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ya hemos hablado en Planeta Curioso algunos datos curiosos de <a title=\"Fot\u00f3grafa ciega gana concurso nacional de fotograf\u00eda en Canad\u00e1\" href=\"http:\/\/www.planetacurioso.com\/2012\/01\/03\/fotografa-ciega-gana-concurso-nacional-de-fotografia-en-canada\/\">Canad\u00e1<\/a>, por ejemplo, muchos han le\u00eddo que <a href=\"http:\/\/www.planetacurioso.com\/2007\/01\/26\/los-10-paises-mas-grandes-del-mundo\/\">Canad\u00e1 es el segundo pa\u00eds m\u00e1s grande del mundo<\/a>. Tambi\u00e9n hemos hablado del Hotel de Glace en Quebec, que cada a\u00f1o es reconstruido de hielo y nieve, en el post: <a href=\"http:\/\/www.planetacurioso.com\/2015\/01\/18\/8-increibles-hoteles-de-hielo-alrededor-del-mundo\/\">8 Incre\u00edbles hoteles alrededor del mundo<\/a>.<!--more--><\/p>\n<p>Hoy les queremos hablar de otras curiosidades de Canad\u00e1.<br \/>\n<span id=\"more-44338\"><\/span><\/p>\n<p>1. <strong>El guante de b\u00e9isbol fue inventado en Canad\u00e1 en 1883<\/strong>. Han hecho un gran aporte al b\u00e9isbol mundial.<\/p>\n<p><a title=\"glove by Jeff Archer, on Flickr\" href=\"https:\/\/www.flickr.com\/photos\/jarcher\/514864000\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/farm1.staticflickr.com\/237\/514864000_634a340d4a_b.jpg\" alt=\"glove\" width=\"1024\" height=\"768\" \/><\/a><\/p>\n<p>2. Canad\u00e1 tiene una <strong>poblaci\u00f3n m\u00e1s peque\u00f1a que la del estado de California<\/strong>.<\/p>\n<p>3. <strong>Es el segundo pa\u00eds con el aire m\u00e1s puro del mundo<\/strong>. \u00a1Que privilegiados son los canadienses no crees?<\/p>\n<p><a title=\"canada by Jesus Martin, on Flickr\" href=\"https:\/\/www.flickr.com\/photos\/8368962@N07\/504631518\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/farm1.staticflickr.com\/215\/504631518_78d8e45e91_b.jpg\" alt=\"canada\" width=\"1024\" height=\"681\" \/><\/a><\/p>\n<p>4. Canad\u00e1 tiene <strong>el litoral m\u00e1s extenso del mundo<\/strong>, 202.080 km de extensi\u00f3n.<\/p>\n<p>5. Dentro de las <strong>comidas t\u00edpicas de Canad\u00e1, encontramos la Poutine<\/strong> (papas fritas con queso especial y salsa), tambi\u00e9n es popular el Salm\u00f3n ahumado con jarabe de Maple.<\/p>\n<p><a title=\"Poivree a l'ancienne poutine by mila0506, on Flickr\" href=\"https:\/\/www.flickr.com\/photos\/mila0506\/9894734463\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/farm3.staticflickr.com\/2805\/9894734463_7bb3f06a64_b.jpg\" alt=\"Poivree a l'ancienne poutine\" width=\"675\" height=\"450\" \/><\/a><\/p>\n<p>6. <strong>Maple Syrup, es el jarabe tradicional de Canad\u00e1<\/strong> m\u00e1s famoso del mundo. El 77% del jarabe vendido en el mundo se produce en Quebec, as\u00ed que si has comido Maple es muy seguro que hayas comido uno producido en Quebec. \u00a1Que rico!<\/p>\n<p><a title=\"Pancakes with maple syrup &amp; pecan by Jane, on Flickr\" href=\"https:\/\/www.flickr.com\/photos\/choco_jane\/7277292772\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/farm8.staticflickr.com\/7090\/7277292772_1b93389d71_b.jpg\" alt=\"Pancakes with maple syrup &amp; pecan\" width=\"1024\" height=\"768\" \/><\/a><\/p>\n<p>7. <strong>En Canad\u00e1 hay m\u00e1s de 200 or\u00edgenes \u00e9tnicos<\/strong>. Y es que por decenas de miles de a\u00f1os, Canad\u00e1 fue habitado por pueblos abor\u00edgenes de una variedad de culturas diferentes y de varios grupos ling\u00fc\u00edsticas.<\/p>\n<p><a title=\"Canada Day 2014 by Jonny White, on Flickr\" href=\"https:\/\/www.flickr.com\/photos\/jonnywhitephoto\/14722320540\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/farm6.staticflickr.com\/5585\/14722320540_a0ef2bfcdb_h.jpg\" alt=\"Canada Day 2014\" width=\"1065\" height=\"1600\" \/><\/a><\/p>\n<p>8. 15.500 de los 25.000 osos polares blancos existente del mundo viven en Canad\u00e1.<\/p>\n<p><a title=\"Polar bear family by Drew Hamilton, on Flickr\" href=\"https:\/\/www.flickr.com\/photos\/13736715@N04\/10034742193\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/farm4.staticflickr.com\/3713\/10034742193_5e18c0b72a_h.jpg\" alt=\"Polar bear family\" width=\"1600\" height=\"1067\" \/><\/a><\/p>\n<p>9. <strong>En Canad\u00e1 hay 1 profesor por cada 12 alumnos<\/strong>. El 79.1% de los canadienses est\u00e1 satisfechos con la educaci\u00f3n de su pa\u00eds. En tu pa\u00eds, \u00bfcuantos alumnos atiende un solo profesor?<\/p>\n<p>10.<strong> Canad\u00e1 ha sido sede de los Juegos Ol\u00edmpicos de 3 veces<\/strong>; 1976 en Montreal, 1988 en Calgary y 2010 en Vancouver.<\/p>\n<p><a title=\"Guess what's coming? by Kenny Louie, on Flickr\" href=\"https:\/\/www.flickr.com\/photos\/kwl\/4236276358\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/farm3.staticflickr.com\/2554\/4236276358_23fff07bb7_b.jpg\" alt=\"Guess what's coming?\" width=\"1024\" height=\"680\" \/><\/a><\/p>\n<p><strong>\u00bfQue te han parecido estos breves datos curiosos sobre Canad\u00e1<\/strong><\/p>\n<p>Fuente: Planetacurioso.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya hemos hablado en Planeta Curioso algunos datos curiosos de Canad\u00e1, por ejemplo, muchos han le\u00eddo que Canad\u00e1 es el segundo pa\u00eds m\u00e1s grande del mundo. Tambi\u00e9n hemos hablado del Hotel de Glace en Quebec, que cada a\u00f1o es reconstruido de hielo y nieve, en el post: 8 Incre\u00edbles hoteles alrededor del mundo.<\/p>\n","protected":false},"author":3,"featured_media":42904,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-42903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=42903"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42903\/revisions"}],"predecessor-version":[{"id":42905,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42903\/revisions\/42905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/42904"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=42903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=42903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=42903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}