{"id":42990,"date":"2015-05-05T10:15:21","date_gmt":"2015-05-05T14:15:21","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=42990"},"modified":"2015-05-05T09:55:09","modified_gmt":"2015-05-05T13:55:09","slug":"7-cosas-que-deberia-estar-prohibido-regalar-el-dia-de-la-madre","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/7-cosas-que-deberia-estar-prohibido-regalar-el-dia-de-la-madre\/","title":{"rendered":"7 cosas que deber\u00eda estar prohibido regalar el D\u00eda de la Madre"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/perfume-para-dia-de-la-madre.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-42991 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/perfume-para-dia-de-la-madre-300x200.jpg\" alt=\"perfume-para-dia-de-la-madre\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/perfume-para-dia-de-la-madre-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/perfume-para-dia-de-la-madre-105x70.jpg 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/perfume-para-dia-de-la-madre.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Llega el <label>D\u00eda<\/label> de la <label>Madre<\/label> y los <label>regalos<\/label> de \u00edndole culinario suele ser un \u00abresuelve\u00bb. Sin embargo, regalar cosas para la <label>cocina<\/label> es tambi\u00e9n muy delicado, y podemos acabar metiendo la pata catastr\u00f3ficamente.<!--more--><\/p>\n<p>Hoy vamos a ver siete cosas que deber\u00eda estar prohibido regalar el D\u00eda de la Madre, porque son regalos capaces de estropear un d\u00eda que reconoce la labor y el esfuerzo de nuestras progenitoras. Para compensar, tambi\u00e9n veremos regalos equivalentes que s\u00ed son m\u00e1s adecuados.<\/p>\n<p><strong>Un <label>juego<\/label> de sartenes:<\/strong> No hay nada m\u00e1s triste que un juego de sartenes. S\u00ed, es cierto que unas buenas sartenes se agradecen al cocinar, pero corremos un serio riesgo de que las estrene d\u00e1ndonos un merecido sartenazo. Otra cosa ser\u00eda si se tratara de sartenes especiales para hacer algo concreto que entusiasmara a la madre en cuesti\u00f3n: como una sart\u00e9n para hacer tortitas o una especial para hacer cr\u00eapess. Eso s\u00ed, conviene que vayan acompa\u00f1adas de un desayuno a juego preparada con ellas.<\/p>\n<p><strong>Una olla expr\u00e9s: <\/strong>Compitiendo en tristeza con las sartenes est\u00e1 el regalo en forma de olla expr\u00e9s. No es que con ella no se puedan hacer recetas deliciosas como estas costillas a la barbacoa en cinco minutos, pero es que no es un regalo, sino parte del hogar. Si no regalar\u00edas un juego de pomos para la puerta o unos interruptores, \u00bfpor qu\u00e9 ibas a regalar una olla expr\u00e9s? Una alternativa viable, siempre y cuando a la madre en cuesti\u00f3n le guste experimentar con nuevas t\u00e9cnicas de cocci\u00f3n, ser\u00eda regalar una olla tipo crockpot para introducirse en la moda del slowcooking.<\/p>\n<p><strong>Una batidora: <\/strong>Regalar una batidora el D\u00eda de la Madre es un deporte de riesgo. Poner en manos de una madre enfadada un arma de tal calibre es una inconsciencia en toda regla, am\u00e9n de un regalo penoso. Si es que me las imagino abriendo el paquete y pensando: \u00abmmmm, qu\u00e9 bien me lo voy a pasar triturando verduras, ligando mayonesa y montando nata. Esta casa va a ser una fiesta\u00bb. No. Si se tiene que regalar algo relacionado con el amasado, que sea una Kitchenaid o similar, especialmente para madres amantes de la reposter\u00eda.<\/p>\n<p><strong>Un set de tuppers:<\/strong> Da igual que sean de \u00faltima generaci\u00f3n, de vidrio irrompible, con cierre herm\u00e9tico y v\u00e1lvula de vac\u00edo, como si tienen temporizador sincr\u00f3nico de apertura o un GPS integrado para localizar qu\u00e9 hijo es el que no se los devuelve nunca; un tupper no es un regalo para tu madre, es un regalo para ti, que es el que va a disfrutar de lo que vaya dentro. Es el equivalente televisivo a cuando Homer Simpson le regala una bola de bolos a Marge. Si tenemos presupuesto ajustado, no hay problema, existen infinidad de moldes curiosos para regalar, algunos perfectos para el d\u00eda de la madre como este con forma de beb\u00e9 para decorar cupcakes y tartas.<\/p>\n<p><strong>Un juego de cuchillos:<\/strong> \u00bfQu\u00e9 hemos hablado de los regalos inadecuados que son arma en potencia? Efectivamente: una mala idea. B\u00e1sicamente, hay que evitar cualquier cosa que sea remotamente pr\u00e1ctica, salvo petici\u00f3n expresa. Podr\u00eda valer un set especial para cocteler\u00eda, o mejor a\u00fan, de mojitos, que es algo mucho m\u00e1s festivo, especialmente si incluye un barman atento que le prepare unos c\u00f3cteles especiales para el D\u00eda de la Madre.<\/p>\n<p><strong>Una tostadora: <\/strong>subiendo en la escala de regalos poco acertados est\u00e1 la siempre socorrida tostadora. Que s\u00ed, que el pan tostado est\u00e1 muy bueno por la ma\u00f1ana y es posible que la que ten\u00eda estaba muy vieja, pero no hay nada apasionante que se puede hacer con ella. Si la cuesti\u00f3n es regalar un peque\u00f1o electrodom\u00e9stico que caliente cosas, mejor algo original como una m\u00e1quina para hacer churros o la m\u00e1s cl\u00e1sica para hacer cupcakes.<\/p>\n<p><strong>Un desayuno en la cama&#8230; dejando la cocina echa unos zorros:<\/strong> El desayuno en la cama es una buena idea, pero no si al levantarse descubre que la cocina parece el escenario de una pel\u00edcula de zombies. Mejor dejarla que se despierte tranquilamente y la llevas a disfrutar de un buen brunch de domingo, que es lo que se lleva ahora.<\/p>\n<p>En definitiva, al regalar el D\u00eda de la Madre hay que huir de los regalos pr\u00e1cticos. Incluso si nuestra madre lleva tiempo quej\u00e1ndose de que se le pega la tortilla a la sart\u00e9n, que los cuchillos no cortan o que los tuppers se le abren en el congelador: eso son cosas para la casa, y estamos celebrando el D\u00eda de la Madre, no el d\u00eda del ama (o amo) de casa, que ese se celebra el 1 de diciembre, y ah\u00ed tal vez s\u00ed tendr\u00eda sentido regalarle todo lo que le hiciera falta para que su trabajo fuera m\u00e1s f\u00e1cil.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.directoalpaladar.com\/utensilios\/siete-cosas-que-deberia-estar-prohibido-regalar-el-dia-de-la-madre\" target=\"_blank\">Directo al paladar<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llega el D\u00eda de la Madre y los regalos de \u00edndole culinario suele ser un \u00abresuelve\u00bb. Sin embargo, regalar cosas para la cocina es tambi\u00e9n muy delicado, y podemos acabar metiendo la pata catastr\u00f3ficamente.<\/p>\n","protected":false},"author":3,"featured_media":42991,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-42990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=42990"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42990\/revisions"}],"predecessor-version":[{"id":42992,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42990\/revisions\/42992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/42991"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=42990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=42990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=42990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}