{"id":42993,"date":"2015-05-05T12:00:52","date_gmt":"2015-05-05T16:00:52","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=42993"},"modified":"2015-05-05T10:00:41","modified_gmt":"2015-05-05T14:00:41","slug":"en-este-concurso-gana-la-que-abra-mas-las-piernas-video","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/en-este-concurso-gana-la-que-abra-mas-las-piernas-video\/","title":{"rendered":"En este concurso gana&#8230; \u00a1la que abra m\u00e1s las piernas! (Video)"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/8416b2744b11404b85006073c3b2e079_620x350.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-42994 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/8416b2744b11404b85006073c3b2e079_620x350-300x200.jpg\" alt=\"8416b2744b11404b85006073c3b2e079_620x350\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/8416b2744b11404b85006073c3b2e079_620x350-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/8416b2744b11404b85006073c3b2e079_620x350-105x70.jpg 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/8416b2744b11404b85006073c3b2e079_620x350.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Las muchachas se sientan en una m\u00e1quina que funciona cuando una de sus compa\u00f1eras le da vuelta a una <label>rueda<\/label>, seg\u00fan el n\u00famero de giros que indique la ruleta.<!--more--><\/p>\n<p>Ten\u00edan que ser los japonenes&#8230; anteriormente te presentamos un <a href=\"http:\/\/informe21.com\/actualidad\/polemico-programa-que-masturba-a-sus-concursantes-al-cantar\" target=\"_blank\">pol\u00e9mico concurso en donde los varones cantan al ritmo que los toquen.<\/a> S\u00ed, unas guapas enfermeras les acarician el miembro mientros ellos terminan una canci\u00f3n completa.<\/p>\n<p>Pero las <label>mujeres<\/label> no se quisieron quedar atr\u00e1s&#8230; <label>adolescentes<\/label> participan en un reality donde gana, \u00a1la que abra m\u00e1s las piernas! Literal.<\/p>\n<p>Las muchachas se sientan en una m\u00e1quina que funciona cuando una de sus compa\u00f1eras le da vuelta a una rueda, seg\u00fan el n\u00famero de giros que indique la ruleta. Al parecer, se trata de una pr\u00e1ctica bastante dolorosa ya que una de las participantes lanz\u00f3 gritos de dolor, cual <label>mujer<\/label> a <label>punto<\/label> de parir.<\/p>\n<p>\u00bfQiuieres ver?<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/-66Ot5babpU\" width=\"600\" height=\"338\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Fuente: <a href=\"http:\/\/www.sdpnoticias.com\/sorprendente\/2015\/04\/30\/en-este-concurso-gana-la-que-abra-mas-las-piernas-video\" target=\"_blank\">SDP noticias<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las muchachas se sientan en una m\u00e1quina que funciona cuando una de sus compa\u00f1eras le da vuelta a una rueda, seg\u00fan el n\u00famero de giros que indique la ruleta.<\/p>\n","protected":false},"author":3,"featured_media":42994,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-42993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=42993"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42993\/revisions"}],"predecessor-version":[{"id":42995,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42993\/revisions\/42995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/42994"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=42993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=42993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=42993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}