{"id":42996,"date":"2015-05-05T14:02:00","date_gmt":"2015-05-05T18:02:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=42996"},"modified":"2015-05-05T10:03:49","modified_gmt":"2015-05-05T14:03:49","slug":"conoce-a-baron-el-perro-mas-educado-del-mundo-videos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/conoce-a-baron-el-perro-mas-educado-del-mundo-videos\/","title":{"rendered":"Conoce a Baron, el perro m\u00e1s educado del mundo (Videos)"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/base_image_29.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-42997 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/base_image_29-300x200.jpg\" alt=\"base_image_29\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/base_image_29-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/base_image_29-105x70.jpg 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/base_image_29.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Baron es un pastor alem\u00e1n de cinco meses que sorprendi\u00f3 a todos los <label>usuarios<\/label> de<label>YouTube<\/label> con su educado comportamiento cuando quiere orinar. Sin que su due\u00f1o lo ayude, el can levanta <label>solo<\/label> la tapa del inodoro, se coloca en posici\u00f3n y al terminar baja la tapa y jala de la <label>palanca<\/label>.<!--more--><\/p>\n<p>Una de las cosas m\u00e1s importantes al adquirir una mascota es educarlo para ir al <label>ba\u00f1o<\/label>. Un video en YouTube muestra los resultados positivos que se obtienen cuando se les amaestra bien.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/0cX8xqGFoqQ\" width=\"600\" height=\"338\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>El clip de YouTube solo dura 26 segundos pero en pocos d\u00edas ha logrado cerca de 200 mil reproducciones.<\/p>\n<p>Hill Country comparti\u00f3 este video en su canal de YouTube en el que tambi\u00e9n hay otros cortos en los que Baron colabora con las faenas del hogar.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/jll53ameZP0\" width=\"600\" height=\"338\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/TGpqkZOw0r4\" width=\"600\" height=\"338\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Fuente: <a href=\"http:\/\/elcomercio.pe\/redes-sociales\/youtube\/youtube-pastor-aleman-aprende-ir-al-bano-video-noticia-1808169\" target=\"_blank\">El comercio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Baron es un pastor alem\u00e1n de cinco meses que sorprendi\u00f3 a todos los usuarios deYouTube con su educado comportamiento cuando quiere orinar. Sin que su due\u00f1o lo ayude, el can levanta solo la tapa del inodoro, se coloca en posici\u00f3n y al terminar baja la tapa y jala de la palanca.<\/p>\n","protected":false},"author":3,"featured_media":42997,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-42996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=42996"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42996\/revisions"}],"predecessor-version":[{"id":42998,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/42996\/revisions\/42998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/42997"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=42996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=42996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=42996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}