{"id":43025,"date":"2015-05-05T15:56:20","date_gmt":"2015-05-05T19:56:20","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=43025"},"modified":"2015-05-05T22:23:04","modified_gmt":"2015-05-06T02:23:04","slug":"expareja-asesina-joven-de-varios-disparos-en-sosua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/expareja-asesina-joven-de-varios-disparos-en-sosua\/","title":{"rendered":"Expareja asesina joven de varios disparos en Sos\u00faa"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/997078_656676457766384_167151588981913819_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-43032 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/997078_656676457766384_167151588981913819_n.jpg\" alt=\"997078_656676457766384_167151588981913819_n\" width=\"540\" height=\"540\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/997078_656676457766384_167151588981913819_n.jpg 540w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/997078_656676457766384_167151588981913819_n-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/997078_656676457766384_167151588981913819_n-300x300.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/997078_656676457766384_167151588981913819_n-75x75.jpg 75w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/997078_656676457766384_167151588981913819_n-120x120.jpg 120w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a><br \/>\nSos\u00faa.- Porque se neg\u00f3 a reconciliarse con \u00e9l, un taxista ultim\u00f3 de cuatro balazos a su expareja mientras se encontraba en su residencia del sector Villa Bethania, del municipio de Sos\u00faa, de esta provincia.<!--more--><\/p>\n<p>Claritza Reyes, de 32 a\u00f1os de edad, falleci\u00f3 en una cl\u00ednica privada donde fue llevada por vecinos, tras recibir las heridas que le ocasion\u00f3 su expareja, el taxista Oliver de las Mercedes Rivera Victoria, de 33 a\u00f1os.<\/p>\n<p>La mujer cay\u00f3 en el ba\u00f1o, \u00a0adonde huy\u00f3 tratando de defenderse.<\/p>\n<p>Tan pronto cometi\u00f3 el hecho emprendi\u00f3 la huida, siendo detenido frente a Playa Dorada por unidades policiales de la zona.<\/p>\n<p>La Polic\u00eda de esta ciudad inform\u00f3 que proceder\u00e1 a someter en las pr\u00f3ximas horas al asesino de la joven mujer, con la cual no procre\u00f3 hijos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa.- Porque se neg\u00f3 a reconciliarse con \u00e9l, un taxista ultim\u00f3 de cuatro balazos a su expareja mientras se encontraba en su residencia del sector Villa Bethania, del municipio de Sos\u00faa, de esta provincia.<\/p>\n","protected":false},"author":12,"featured_media":43032,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-43025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=43025"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43025\/revisions"}],"predecessor-version":[{"id":43033,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43025\/revisions\/43033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/43032"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=43025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=43025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=43025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}