{"id":43056,"date":"2015-05-07T01:14:26","date_gmt":"2015-05-07T05:14:26","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=43056"},"modified":"2015-05-07T01:14:26","modified_gmt":"2015-05-07T05:14:26","slug":"bandera-dominicana-entre-las-diez-mas-bonitas-del-mundo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/bandera-dominicana-entre-las-diez-mas-bonitas-del-mundo\/","title":{"rendered":"Bandera Dominicana entre las diez m\u00e1s bonitas del Mundo"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/Bandera_Dominicana_CDN.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-43059 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/Bandera_Dominicana_CDN.jpg\" alt=\"Bandera_Dominicana_CDN\" width=\"320\" height=\"180\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/Bandera_Dominicana_CDN.jpg 320w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/Bandera_Dominicana_CDN-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/Bandera_Dominicana_CDN-105x59.jpg 105w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a>El <strong>diario espa\u00f1ol<\/strong> 20 Minutos realiz\u00f3 a trav\u00e9s de internet, un concurso para elegir a \u201cLa bandera m\u00e1s bella del mundo\u201d resultando ganador absoluto La bandera de<strong>M\u00e9xico,<\/strong> mientras los l\u00e1baros patrios de<strong> Per\u00fa<\/strong> y\u00a0<strong>Guatemala<\/strong> lograron el segundo y tercer sitio respectivamente.<!--more--><\/p>\n<p>El simb\u00f3lico concurso comenz\u00f3 la votaci\u00f3n con las banderas de 104 pa\u00edses de todo el mundo, y ped\u00eda a los cibernautas votar por su bandera favorita tomando en cuenta \u201csus colores, lo que representa o porque les gusta, con una puntuaci\u00f3n de entre uno y cinco puntos.<\/p>\n<p>Los resultados finales colocaron a la bandera mexicana en primer lugar con 901 mil 627 puntos, una diferencia de 560 mil 726 votos respecto a la Per\u00fa que obtuvo 340 mil 901, en tanto la de Guatemala logr\u00f3 272 mil 541 puntos.<\/p>\n<p>Adem\u00e1s de esos tres l\u00e1baros patrios, en orden descendente quedaron las banderas de\u00a0<strong>Rep\u00fablica Dominicana,<\/strong><strong>Brasil,<\/strong> <strong>Espa\u00f1a,<\/strong> <strong>Uruguay,<\/strong> <strong>Argentina,<\/strong> <strong>Canad\u00e1<\/strong> y <strong>Puerto Rico<\/strong>.<\/p>\n<p>Desde que inici\u00f3 la etapa final la ventaja de M\u00e9xico sobre Per\u00fa se fue incrementando en alrededor de 100 mil puntos diarios.<\/p>\n<p>De acuerdo con el sitio del diario espa\u00f1ol, durante los 48 d\u00edas de concurso, m\u00e1s de siete millones y medio de votos fueron emitidos y se recibieron m\u00e1s de 25 mil comentarios.<\/p>\n<p>\u201cEmpezamos con 104 banderas de todo el mundo, cada dos d\u00edas elimin\u00e1bamos las cinco banderas menos votadas, hasta hoy que termin\u00f3 el concurso con las 10 banderas m\u00e1s votadas\u201d, precis\u00f3 el sitio.Estas son las 10 banderas ganadoras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El diario espa\u00f1ol 20 Minutos realiz\u00f3 a trav\u00e9s de internet, un concurso para elegir a \u201cLa bandera m\u00e1s bella del mundo\u201d resultando ganador absoluto La bandera deM\u00e9xico, mientras los l\u00e1baros patrios de Per\u00fa y\u00a0Guatemala lograron el segundo y tercer sitio respectivamente.<\/p>\n","protected":false},"author":12,"featured_media":43059,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-43056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=43056"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43056\/revisions"}],"predecessor-version":[{"id":43061,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43056\/revisions\/43061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/43059"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=43056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=43056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=43056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}