{"id":43256,"date":"2015-05-11T22:21:07","date_gmt":"2015-05-12T02:21:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=43256"},"modified":"2015-05-11T22:21:07","modified_gmt":"2015-05-12T02:21:07","slug":"google-cierra-temporalmente-editor-de-mapas-tras-broma-del-logo-de-apple","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/google-cierra-temporalmente-editor-de-mapas-tras-broma-del-logo-de-apple\/","title":{"rendered":"Google cierra temporalmente editor de mapas tras broma del logo de Apple"},"content":{"rendered":"<p class=\"excerpt ng-binding\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/mapa-de-google.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-43257 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/mapa-de-google.jpg\" alt=\"mapa de google\" width=\"725\" height=\"465\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/mapa-de-google.jpg 960w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/mapa-de-google-300x192.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/mapa-de-google-105x67.jpg 105w\" sizes=\"auto, (max-width: 725px) 100vw, 725px\" \/><br \/>\n<\/a>La empresa de Mountain View analizar\u00e1 su proceso de aprobaci\u00f3n de modificaciones a Google Maps.<!--more--><\/p>\n<div class=\"body-text\">\n<div class=\"ng-binding\">\n<p>Hace unas tres semanas atr\u00e1s hubo una gran pol\u00e9mica luego de que se encontr\u00f3 una imagen en Google Maps, en Pakist\u00e1n, que mostraba la mascota de Android orinando sobre el logo de Apple, la que fue realizada por un usuario an\u00f3nimo sin la autorizaci\u00f3n de la empresa de Mountain View gracias a que cualquiera puede modificar mapas de Google Maps en\u00a0Map Maker.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-721193\" src=\"https:\/\/static.betazeta.com\/www.fayerwayer.com\/up\/2015\/05\/Captura-de-pantalla-2015-04-24-a-las-12.08.06-660x595.jpg\" alt=\"Captura-de-pantalla-2015-04-24-a-las-12.08.06\" width=\"660\" height=\"328\" \/><\/p>\n<p>Tras la broma, Google anunci\u00f3 que cerrar\u00e1 temporalmente a partir de ma\u00f1ana su editor de mapas en l\u00ednea, para as\u00ed analizar c\u00f3mo ser\u00e1 el proceso de aprobaci\u00f3n de modificaciones a los mapas de Google Maps.<\/p>\n<p>Acorde a\u00a0Pavithra Kanakarajan del equipo de <a href=\"http:\/\/www.google.cl\/mapmaker\">Google Maps Map Maker<\/a>, \u00ab<em>el proceso de aprobaci\u00f3n de\u00a0todas las ediciones actualmente est\u00e1n siendo realizadas de forma manual<\/em>\u00ab, y se\u00f1al\u00f3 que el cierre temporal mientras habilitan los cambios es para que \u00ab<em>nuestros usuarios no pierdan el tiempo editando<\/em>\u00ab.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.betazeta.com\/www.fayerwayer.com\/up\/2015\/05\/google-maps-660x595.jpg\" alt=\"google maps\" width=\"660\" height=\"321\" \/><\/p>\n<p>Quiz\u00e1 Map Maker ha pasado desapercibido para la mayor\u00eda de los usuarios de los mapas de Google, pero sin duda es una herramienta important\u00edsima. Por ejemplo, desde el 2009 que una enorme cantidad de voluntarios han estado colaborando en Google Maps <a href=\"https:\/\/www.fayerwayer.com\/2013\/02\/corea-del-norte-el-reto-final-para-google-maps\/\">para cartografiar a Corea del Norte<\/a>.<\/p>\n<\/div>\n<\/div>\n<div class=\"body-text\">\n<ul class=\"iop tags ng-scope\" style=\"box-sizing: inherit; margin: 1.5em 0.5em; padding: 0px; border: 0px; font-weight: 400; font-style: normal; font-size: 16px; line-height: 1; font-family: inherit; text-align: left; list-style: none; display: block; clear: both; overflow: visible; position: relative;\">\n<li class=\"ng-scope\"><a class=\"ng-binding\" href=\"https:\/\/www.fayerwayer.com\/tag\/google-map-maker\/\">GOOGLE MAP MAKER<\/a><\/li>\n<li class=\"ng-scope\"><a class=\"ng-binding\" href=\"https:\/\/www.fayerwayer.com\/tag\/google-maps\/\">GOOGLE MAPS<\/a><\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La empresa de Mountain View analizar\u00e1 su proceso de aprobaci\u00f3n de modificaciones a Google Maps.<\/p>\n","protected":false},"author":12,"featured_media":43257,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-43256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=43256"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43256\/revisions"}],"predecessor-version":[{"id":43258,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43256\/revisions\/43258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/43257"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=43256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=43256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=43256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}