{"id":43787,"date":"2015-05-22T13:43:22","date_gmt":"2015-05-22T17:43:22","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=43787"},"modified":"2015-05-22T13:45:11","modified_gmt":"2015-05-22T17:45:11","slug":"boletin-i-huracanes-del-atlantico","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/boletin-i-huracanes-del-atlantico\/","title":{"rendered":"BOLET\u00cdN I &#8211; Huracanes del Atl\u00e1ntico"},"content":{"rendered":"<h1 class=\"sCaption\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/huracanes.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-43517 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/huracanes-300x151.jpg\" alt=\"huracanes\" width=\"300\" height=\"151\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/huracanes-300x151.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/huracanes-105x53.jpg 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/huracanes-400x200.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/huracanes.jpg 533w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>BOLET\u00cdN I<br \/>\nEl equipo de los Huracanes del Atl\u00e1ntico recibe esta noche a los Indios de San Francisco en el Palacio de los Deportes Fabio Rafael Gonz\u00e1lez, en su primer partido de la temporada 2015 de la Liga Nacional de Baloncesto Copa Banreservas, dedicado al profesor Fernando Teruel.<\/h1>\n<h1 class=\"sCaption\">\nHURACANES DEL ATLANTICO VS INDIOS DE SAN FRANCISCO TEMPORADA 2014.<br \/>\nLos Huracanes del Atl\u00e1ntico dominaron la serie particular 3-1 ante los Indios de San Francisco en la temporada pasada. Primer juego 84-70 (Huracanes), segundo juego 82-75 (Huracanes), tercer juego 91-89 (Indios) y cuarto juego 78-71 (Huracanes)<\/h1>\n<h1 class=\"sCaption\">\nDIRIGENTE RICARDO BENITEZ.<br \/>\nBen\u00edtez es director de \u201cBen\u00edtez International Academy\u201d, una organizaci\u00f3n radicada en Florida, Estados Unidos, que se dedica a desarrollar y apoyar j\u00f3venes con talento para el baloncesto, que adem\u00e1s observen un comportamiento ejemplar dentro y fuera de la cancha.<\/h1>\n<h1 class=\"sCaption\">\nALEJO RODRIGUEZ NOVATO DEL A\u00d1O.<br \/>\nEl jugador Alejo Rodr\u00edguez fue nombrado Novato del a\u00f1o de la temporada pasada, promediando 10.5 puntos, 8.4 rebotes y 1.6 bloqueos.<\/h1>\n<h1 class=\"sCaption\">\nNUEVOS HURACANES.<br \/>\nLos jugadores Alexis Mont\u00e1s, Rub\u00e9n Guillandeaux, Luis Jacobo y Damien Mc Swine llegaron a los Huracanes, para formar parte del plantel de nativos del equipo.<\/h1>\n<h1 class=\"sCaption\">\nREFUERZOS DE HURACANES.<br \/>\nLos norteamericanos O&#8217;Darien Bassett y Khyle Marshall son los refuerzos de los Huracanes para esta temporada, Bassett es un Combo Guard de 6&#8217;3 de estatura, con experiencia en las ligas de Alemania, Romania y Francia y Marshall milit\u00f3 en laD-League con el equipo Austin Spurs, sucursal de San Antonio Spurs.<\/h1>\n<h1 class=\"sCaption\">\nROSTER PARA ESTA NOCHE.<br \/>\nAlejo Rodr\u00edguez, Antoine Broxsie, Bernardo Polanco, Oliver Gonz\u00e1lez, Rafael Cris\u00f3stomo, Henry Valdez, Rub\u00e9n Guillandeaux, Luis Jacobo, Damien Mc Swine, Juan Pichardo, y los refuerzos O&#8217;Darien Bassett y Khyle Marshall.<\/h1>\n<h1 class=\"sCaption\">CUERPO TECNICO<br \/>\nRicardo Ben\u00edtez (Dirigente), Ronald Acosta, Ram\u00f3n Cabrera y Ezequ\u00edas Cordero (Asistentes), Ariel de la Cruz (Fisioterapeuta) y Emmanuel Guti\u00e9rrez (Abastecedor).<\/h1>\n<h1 class=\"sCaption\">TRANSMISI\u00d3N DE HURACANES DEL ATL\u00c1NTICO.<br \/>\nLa transmisi\u00f3n por televisi\u00f3n del equipo Huracanes del Atl\u00e1ntico como due\u00f1os de casa, se realizan a trav\u00e9s del canal 13 de Telecentro.<\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOLET\u00cdN I El equipo de los Huracanes del Atl\u00e1ntico recibe esta noche a los Indios de San Francisco en el Palacio de los Deportes Fabio Rafael Gonz\u00e1lez, en su primer partido de la temporada 2015 de la Liga Nacional de Baloncesto Copa Banreservas, dedicado al profesor Fernando Teruel. HURACANES DEL ATLANTICO VS INDIOS DE SAN FRANCISCO TEMPORADA 2014. Los Huracanes del Atl\u00e1ntico dominaron la serie particular 3-1 ante los Indios de San Francisco en la temporada pasada. Primer juego 84-70 (Huracanes), segundo juego 82-75 (Huracanes), tercer juego 91-89 (Indios) y cuarto juego 78-71 (Huracanes) DIRIGENTE RICARDO BENITEZ. Ben\u00edtez es director de \u201cBen\u00edtez International Academy\u201d, una organizaci\u00f3n radicada en Florida, Estados Unidos, que se dedica a desarrollar y apoyar j\u00f3venes con talento para el baloncesto, que adem\u00e1s observen un comportamiento ejemplar dentro y fuera de la cancha. ALEJO RODRIGUEZ NOVATO DEL A\u00d1O. El jugador Alejo Rodr\u00edguez fue nombrado Novato del a\u00f1o de la temporada pasada, promediando 10.5 puntos, 8.4 rebotes y 1.6 bloqueos. NUEVOS HURACANES. Los jugadores Alexis Mont\u00e1s, Rub\u00e9n Guillandeaux, Luis Jacobo y Damien Mc Swine llegaron a los Huracanes, para formar parte del plantel de nativos del equipo. REFUERZOS DE HURACANES. Los norteamericanos O&#8217;Darien Bassett y Khyle Marshall son los refuerzos de los Huracanes para esta temporada, Bassett es un Combo Guard de 6&#8217;3 de estatura, con experiencia en las ligas de Alemania, Romania y Francia y Marshall milit\u00f3 en laD-League con el equipo Austin Spurs, sucursal de San Antonio Spurs. ROSTER PARA ESTA NOCHE. Alejo Rodr\u00edguez, Antoine Broxsie, Bernardo Polanco, Oliver Gonz\u00e1lez, Rafael Cris\u00f3stomo, Henry Valdez, Rub\u00e9n Guillandeaux, Luis Jacobo, Damien Mc Swine, Juan Pichardo, y los refuerzos O&#8217;Darien Bassett y Khyle Marshall. CUERPO TECNICO Ricardo Ben\u00edtez (Dirigente), Ronald Acosta, Ram\u00f3n Cabrera y Ezequ\u00edas Cordero (Asistentes), Ariel de la Cruz (Fisioterapeuta) y Emmanuel Guti\u00e9rrez (Abastecedor). TRANSMISI\u00d3N DE HURACANES DEL ATL\u00c1NTICO. La transmisi\u00f3n por televisi\u00f3n del equipo Huracanes del Atl\u00e1ntico como due\u00f1os de casa, se realizan a trav\u00e9s del canal 13 de Telecentro. &nbsp; &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":43518,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-43787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=43787"}],"version-history":[{"count":3,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43787\/revisions"}],"predecessor-version":[{"id":43790,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43787\/revisions\/43790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/43518"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=43787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=43787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=43787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}