{"id":43813,"date":"2015-05-25T22:30:40","date_gmt":"2015-05-26T02:30:40","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=43813"},"modified":"2015-09-23T20:39:13","modified_gmt":"2015-09-24T00:39:13","slug":"frank-perozo-dejo-la-solteria-se-caso-el-sabado","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/frank-perozo-dejo-la-solteria-se-caso-el-sabado\/","title":{"rendered":"Frank Perozo dej\u00f3 la solter\u00eda; se cas\u00f3 el s\u00e1bado"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/519970035_640.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43814\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/519970035_640.jpg\" alt=\"519970035_640\" width=\"640\" height=\"360\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/519970035_640.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/519970035_640-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/519970035_640-105x59.jpg 105w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>El actor dominicano Frank Perozo se cas\u00f3 el s\u00e1bado en Bayahibe, La Romana, con la joven Dominique Colussi. El protagonista de las pel\u00edculas \u201c\u00bfQui\u00e9n manda?\u201d y \u201cAl sur de la inocencia\u201d, entre otras, era uno de los solteros m\u00e1s codiciados del medio art\u00edstico nacional.<\/p>\n<p>La ya esposa de Perozo es hija del presidente de los hoteles Dominicus, un italiano radicado en el Este de Rep\u00fablica Dominicana. La pareja se cas\u00f3 frente a la playa de Bayahibe durante una ceremonia a la que solo fueron invitados algunos familiares y escasos amigos cercanos de ambos. Del noviazgo de Perozo y Colussi se sab\u00eda poco, mantuvieron su relaci\u00f3n discretamente, fuera de comentarios y rumores.<\/p>\n<p>Para la boda Perozo visti\u00f3 un traje color crema que combinaba con los tenis, en tanto Colussi exhibi\u00f3 un vestido en encaje tambi\u00e9n color crema.<\/p>\n<p>Fuente: www.hoy.com.do<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El actor dominicano Frank Perozo se cas\u00f3 el s\u00e1bado en Bayahibe, La Romana, con la joven Dominique Colussi. El protagonista de las pel\u00edculas \u201c\u00bfQui\u00e9n manda?\u201d y \u201cAl sur de la inocencia\u201d, entre otras, era uno de los solteros m\u00e1s codiciados del medio art\u00edstico nacional. La ya esposa de Perozo es hija del presidente de los hoteles Dominicus, un italiano radicado en el Este de Rep\u00fablica Dominicana. La pareja se cas\u00f3 frente a la playa de Bayahibe durante una ceremonia a la que solo fueron invitados algunos familiares y escasos amigos cercanos de ambos. Del noviazgo de Perozo y Colussi se sab\u00eda poco, mantuvieron su relaci\u00f3n discretamente, fuera de comentarios y rumores. Para la boda Perozo visti\u00f3 un traje color crema que combinaba con los tenis, en tanto Colussi exhibi\u00f3 un vestido en encaje tambi\u00e9n color crema. Fuente: www.hoy.com.do &nbsp;<\/p>\n","protected":false},"author":12,"featured_media":43814,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-43813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=43813"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43813\/revisions"}],"predecessor-version":[{"id":43815,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43813\/revisions\/43815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/43814"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=43813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=43813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=43813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}