{"id":43816,"date":"2015-05-25T22:35:15","date_gmt":"2015-05-26T02:35:15","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=43816"},"modified":"2015-09-23T20:39:01","modified_gmt":"2015-09-24T00:39:01","slug":"lg-desvela-una-pantalla-oled-para-televisores-que-se-puede-adherir-a-la-pared","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/lg-desvela-una-pantalla-oled-para-televisores-que-se-puede-adherir-a-la-pared\/","title":{"rendered":"LG desvela una pantalla OLED para televisores que se puede adherir a la pared"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/lgdisplay-644x362.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43818\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/lgdisplay-644x362.jpg\" alt=\"lgdisplay--644x362\" width=\"644\" height=\"362\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/lgdisplay-644x362.jpg 644w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/lgdisplay-644x362-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/lgdisplay-644x362-105x59.jpg 105w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/a><\/p>\n<p>LG sigue con su apuesta por el mercado de las televisiones, uno de los electrodom\u00e9sticos que desde hace varios a\u00f1os vive su particular reinvenci\u00f3n con nuevos formatos, materiales y resoluciones. La empresa surcoreana ha mostrado esta semana un panel tecnolog\u00eda OLED, de un solo mil\u00edmetro de grosor, capaz de adherirse a la pared como si se tratase de una l\u00e1mina autoadhesiva.<\/p>\n<p>Seg\u00fan ha desvelado \u00abThe Korea Times\u00bb, el nuevo televisor del fabricante coreano, a\u00fan en fase de pruebas, es desmontable y se pega directamente en la pared, demostrando as\u00ed su firme compromiso por las pantallas de gama alta como motor de crecimiento econ\u00f3mico.<\/p>\n<p>De hecho, seg\u00fan reconoci\u00f3 Yeo Sang-GDeO, jefe de la divisi\u00f3n de LG Display, asegur\u00f3 que la empresa aumentar\u00e1 la producci\u00f3n de OLED a partir del tercer trimestre de este a\u00f1o. \u00abDebemos ser capaces de suministrar un volumen satisfactorio a nuestros clientes a partir de julio o agosto, lo que significa que estamos esperando a apretarnos el cintur\u00f3n de producci\u00f3n\u00bb, dijo en rueda de prensa.<\/p>\n<p>Este panel, a\u00fan en fase de pruebas, tiene 55 pulgadas y su dise\u00f1o es su principal atractivo: un peso de solo 1.9 kilogramos y solo 0.97 mil\u00edmetros de grosor. Lo novedoso de este ingenio es que se puede pegar a una pared mediante una alfombra magn\u00e9tica. Esta pantalla es mucho m\u00e1s delgada si se compara con el buque insignia actual (4.3 mil\u00edmetros de espesor).<\/p>\n<p>La divisi\u00f3n de LG encargada de la fabricaci\u00f3n de pantallas tambi\u00e9n present\u00f3 una pantalla org\u00e1nico OLED convexa que se utiliza principalmente para la se\u00f1alizaci\u00f3n digital al aire libre. Este movimiento responde al inter\u00e9s, cada vez mayor, por las pantallas grandes. La firma, en ese sentido, asegura que lanzar\u00e1n nuevas pantallas OLED de monstruosas dimensiones de 99 pulgadas en un a\u00f1o y ha anticipado la investigaci\u00f3n en paneles transparentes y enrollables.<\/p>\n<p>Fuente: www.abc.com<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LG sigue con su apuesta por el mercado de las televisiones, uno de los electrodom\u00e9sticos que desde hace varios a\u00f1os vive su particular reinvenci\u00f3n con nuevos formatos, materiales y resoluciones. La empresa surcoreana ha mostrado esta semana un panel tecnolog\u00eda OLED, de un solo mil\u00edmetro de grosor, capaz de adherirse a la pared como si se tratase de una l\u00e1mina autoadhesiva. Seg\u00fan ha desvelado \u00abThe Korea Times\u00bb, el nuevo televisor del fabricante coreano, a\u00fan en fase de pruebas, es desmontable y se pega directamente en la pared, demostrando as\u00ed su firme compromiso por las pantallas de gama alta como motor de crecimiento econ\u00f3mico. De hecho, seg\u00fan reconoci\u00f3 Yeo Sang-GDeO, jefe de la divisi\u00f3n de LG Display, asegur\u00f3 que la empresa aumentar\u00e1 la producci\u00f3n de OLED a partir del tercer trimestre de este a\u00f1o. \u00abDebemos ser capaces de suministrar un volumen satisfactorio a nuestros clientes a partir de julio o agosto, lo que significa que estamos esperando a apretarnos el cintur\u00f3n de producci\u00f3n\u00bb, dijo en rueda de prensa. Este panel, a\u00fan en fase de pruebas, tiene 55 pulgadas y su dise\u00f1o es su principal atractivo: un peso de solo 1.9 kilogramos y solo 0.97 mil\u00edmetros de grosor. Lo novedoso de este ingenio es que se puede pegar a una pared mediante una alfombra magn\u00e9tica. Esta pantalla es mucho m\u00e1s delgada si se compara con el buque insignia actual (4.3 mil\u00edmetros de espesor). La divisi\u00f3n de LG encargada de la fabricaci\u00f3n de pantallas tambi\u00e9n present\u00f3 una pantalla org\u00e1nico OLED convexa que se utiliza principalmente para la se\u00f1alizaci\u00f3n digital al aire libre. Este movimiento responde al inter\u00e9s, cada vez mayor, por las pantallas grandes. La firma, en ese sentido, asegura que lanzar\u00e1n nuevas pantallas OLED de monstruosas dimensiones de 99 pulgadas en un a\u00f1o y ha anticipado la investigaci\u00f3n en paneles transparentes y enrollables. Fuente: www.abc.com &nbsp;<\/p>\n","protected":false},"author":12,"featured_media":43818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,311],"tags":[],"class_list":["post-43816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=43816"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43816\/revisions"}],"predecessor-version":[{"id":43819,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43816\/revisions\/43819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/43818"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=43816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=43816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=43816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}