{"id":43843,"date":"2015-05-26T00:19:07","date_gmt":"2015-05-26T04:19:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=43843"},"modified":"2015-05-26T00:19:07","modified_gmt":"2015-05-26T04:19:07","slug":"10-senales-para-entender-el-lenguaje-corporal-de-tu-pareja","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/10-senales-para-entender-el-lenguaje-corporal-de-tu-pareja\/","title":{"rendered":"10 se\u00f1ales para entender el lenguaje corporal de tu pareja"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-long field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/lenguaje-corporal-femeninov.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-43851 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/lenguaje-corporal-femeninov.jpg\" alt=\"lenguaje-corporal-femeninov\" width=\"636\" height=\"415\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/lenguaje-corporal-femeninov.jpg 636w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/lenguaje-corporal-femeninov-300x196.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/lenguaje-corporal-femeninov-105x69.jpg 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/lenguaje-corporal-femeninov-400x260.jpg 400w\" sizes=\"auto, (max-width: 636px) 100vw, 636px\" \/><\/a>Se le llama kin\u00e9sica o cin\u00e9sica a la rama que estudia el lenguaje corporal, el significado expresivo, apelativo o comunicativo de los movimientos corporales y de los gestos aprendidos no orales, de percepci\u00f3n visual, auditiva o t\u00e1ctil, solos o en relaci\u00f3n con la estructura ling\u00fc\u00edstica y paraling\u00fc\u00edstica y con la situaci\u00f3n comunicativa. Tambi\u00e9n es conocida con el nombre de comportamiento kin\u00e9sico o lenguaje corporal.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"content\">\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Los movimientos corporales que aportan significados especiales a la palabra oral, durante un evento comunicativo, a veces pueden tener una intenci\u00f3n o no tenerla. Estos movimientos son estudiados por la kin\u00e9sica o quin\u00e9sica.<\/p>\n<p>A veces usamos un texto en lugar de una palabra o de un enunciado, o dibujamos algo con las manos para complementar lo que decimos oralmente, y eso es m\u00e1s complicado de entender de lo que pareciera.<\/p>\n<p><strong>1.La sonrisa<\/strong><\/p>\n<p>Alguien que se siente c\u00f3modo contigo est\u00e1 receptivo a tu humor, si se r\u00ede quiere decir que desea una relaci\u00f3n ya sea plat\u00f3nica o rom\u00e1ntica.<\/p>\n<p><strong>2. Las cejas<\/strong><\/p>\n<p>Si levanta las cejas puede indicar un signo de inconformidad, sorpresa, preocupaci\u00f3n. Si alguien halaga tu vestuario, pero levanta las cejas puede ser que no est\u00e9 siendo honesto.<\/p>\n<p><strong>3. Tono de voz<\/strong><\/p>\n<p>Si elevan o disminuyen el tono de voz significa que la persona est\u00e1 interesada, el rango vocal, por ejemplo de una mujer tiende a levantar la voz, mientras que el hombre usa un tono m\u00e1s grave.<\/p>\n<p><strong>4. Contacto visual<\/strong><\/p>\n<p>Demuestra inter\u00e9s de manera positiva o negativa. Si miras a tu pareja puede generar amor, la de un extra\u00f1o, miedo.<\/p>\n<p><strong>5. Los ojos del mentiroso<\/strong><\/p>\n<p>Cuando alguien te ve durante demasiado tiempo a los ojos es posible que est\u00e9 mintiendo, esto para evitar cambiar la mirada por una furtiva, lo hacen para ponerte inc\u00f3modo.<\/p>\n<p><strong>6. Cruzar las piernas<\/strong><\/p>\n<p>Es una muestra de resistencia a una idea, de baja receptividad. Una persona que cierra las piernas est\u00e1 cerrada mental, emocional y f\u00edsicamente; no van a negociar.<\/p>\n<p><strong>7. La simetr\u00eda<\/strong><\/p>\n<p>Cuando alguien usa el reflejo mientras platica con otra persona significa que se est\u00e1n entendiendo bien, est\u00e1n conectados.<\/p>\n<p><strong>8. La sonrisa falsa<\/strong><\/p>\n<p>La mejor forma de darte cuenta es ver las expresiones alrededor de los ojos si se arrugan las \u201cpatas de gallo\u201d significa que la sonrisa es sincera, si no est\u00e1 fingiendo.<\/p>\n<p><strong>9. Posturas expansivas y autoritarias muestra liderazgo<\/strong><\/p>\n<p>Un l\u00edder muestra erguido y camina como si tuviera un prop\u00f3sito, junta las manos y usa posturas abiertas.<\/p>\n<p><strong>10. Pierna inestable<\/strong><\/p>\n<p>Una pierna temblorosa puede ser se\u00f1al de ansiedad e irritaci\u00f3n.<\/p>\n<p><strong>Fuente:<\/strong> <a href=\"http:\/\/de10.com.mx\/parejas\/2015\/05\/25\/10-senales-para-entender-el-lenguaje-corporal-de-tu-pareja\" target=\"_blank\">De10<\/a> \/ AM<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se le llama kin\u00e9sica o cin\u00e9sica a la rama que estudia el lenguaje corporal, el significado expresivo, apelativo o comunicativo de los movimientos corporales y de los gestos aprendidos no orales, de percepci\u00f3n visual, auditiva o t\u00e1ctil, solos o en relaci\u00f3n con la estructura ling\u00fc\u00edstica y paraling\u00fc\u00edstica y con la situaci\u00f3n comunicativa. Tambi\u00e9n es conocida con el nombre de comportamiento kin\u00e9sico o lenguaje corporal.<\/p>\n","protected":false},"author":12,"featured_media":43851,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-43843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=43843"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43843\/revisions"}],"predecessor-version":[{"id":43852,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43843\/revisions\/43852"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/43851"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=43843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=43843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=43843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}