{"id":43875,"date":"2015-05-25T21:31:33","date_gmt":"2015-05-26T01:31:33","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=43875"},"modified":"2015-05-26T07:34:30","modified_gmt":"2015-05-26T11:34:30","slug":"con-jonron-del-dominicano-peralta-cardenales-se-imponen-en-10-innings","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/con-jonron-del-dominicano-peralta-cardenales-se-imponen-en-10-innings\/","title":{"rendered":"Con jonr\u00f3n del dominicano Peralta, Cardenales se imponen en 10 innings"},"content":{"rendered":"<div id=\"attachment_43877\" style=\"width: 358px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/Jhonny-Peralta.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-43877\" class=\"size-full wp-image-43877\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/Jhonny-Peralta.jpg\" alt=\"Jhonny Peralta\" width=\"348\" height=\"232\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/Jhonny-Peralta.jpg 348w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/Jhonny-Peralta-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/Jhonny-Peralta-105x70.jpg 105w\" sizes=\"auto, (max-width: 348px) 100vw, 348px\" \/><\/a><p id=\"caption-attachment-43877\" class=\"wp-caption-text\">Jhonny Peralta<\/p><\/div>\n<p>Jhonny Peralta puso fin al encuentro, al conectar un jonr\u00f3n en el d\u00e9cimo episodio, y los Cardenales de San Luis superaron el lunes 3-2 a los Diamondbacks de Arizona.<!--more--><br \/>\nEl garrotazo del dominicano Peralta abri\u00f3 el d\u00e9cimo cap\u00edtulo y lleg\u00f3 con cuenta de 1-2, frente al nicarag\u00fcense Juan Carlos Ram\u00edrez (1-1). Es la cuarta ocasi\u00f3n en su carrera que Peralta finiquita un duelo con un jonr\u00f3n.<\/p>\n<p>Los Cardenales mejoraron a una foja de 4-1 en cinco encuentros que se han dirimido mediante extra innings en casa durante mayo, incluida una barrida sobre los Piratas al comienzo del mes.<\/p>\n<p>Mark Trumbo peg\u00f3 un vuelacerca de dos carreras, que empat\u00f3 la pizarra en el octavo inning por Arizona, peo los Diamondbacks dejaron varados a cinco corredores en los \u00faltimos dos episodios.<\/p>\n<p>Los Cardenales desperdiciaron dos hits en la apertura del noveno inning, cuando Ram\u00edrez ponch\u00f3 a Matt Carpenter, Matt Holliday y Matt Adams.<\/p>\n<p>El dominicano Carlos Mart\u00ednez igual\u00f3 la mejor cifra de su vida, con ocho ponches durante siete innings en blanco por San Luis. Trevor Rosenthal (1-0) retir\u00f3 a Michael Owings y Tuffy Gosewisch con la casa llena para resolver el d\u00e9cimo inning y agenciarse la victoria.<\/p>\n<p>Por los Diamondbacks, los venezolanos Ender Inciarte de 5-2 con una anotada, David Peralta de 2-0. El cubano Yasmany Tom\u00e1s de 5-3.<\/p>\n<p>Por los Cardenales, los dominicanos Peralta de 4-2 con una anotada y una producida, Mart\u00ednez de 3-1. El boricua Yadier Molina de 4-0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jhonny Peralta puso fin al encuentro, al conectar un jonr\u00f3n en el d\u00e9cimo episodio, y los Cardenales de San Luis superaron el lunes 3-2 a los Diamondbacks de Arizona.<\/p>\n","protected":false},"author":12,"featured_media":43877,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-43875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=43875"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43875\/revisions"}],"predecessor-version":[{"id":43878,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43875\/revisions\/43878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/43877"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=43875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=43875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=43875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}