{"id":43896,"date":"2015-05-26T12:00:52","date_gmt":"2015-05-26T16:00:52","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=43896"},"modified":"2015-05-26T08:27:19","modified_gmt":"2015-05-26T12:27:19","slug":"que-regalar-en-una-boda-bautizo-o-comunion-para-no-quedar-mal","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/que-regalar-en-una-boda-bautizo-o-comunion-para-no-quedar-mal\/","title":{"rendered":"\u00bfQu\u00e9 regalar en una boda, bautizo o comuni\u00f3n para no quedar mal?"},"content":{"rendered":"<p id=\"story-texto\" class=\"p\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/boda-regalos-dinero-644x362.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-43897 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/boda-regalos-dinero-644x362.jpg\" alt=\"boda-regalos-dinero--644x362\" width=\"644\" height=\"362\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/boda-regalos-dinero-644x362.jpg 644w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/boda-regalos-dinero-644x362-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/boda-regalos-dinero-644x362-105x59.jpg 105w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/a>Llega el buen tiempo y con \u00e9l, las celebraciones. Es esta una fecha perfecta para que las parejas se unan, los j\u00f3venes hagan su primera Comuni\u00f3n y los ni\u00f1os sean bautizados.<!--more--><\/p>\n<p id=\"U1621123068513bXF\" class=\"p\">Las fiestas siempre son bienvenidas y hasta el agobio de saber qu\u00e9 nos pondremos para estar guapos se vuelve una tarea divertida.<\/p>\n<p id=\"U16211230685134AI\" class=\"p\">Pero, \u00bfqu\u00e9 pasa a la hora de decidir el regalo? Las opciones ya no se limitan a comprar alg\u00fan obsequio como anta\u00f1o, porque \u00abahora se ha puesto muy de moda dar dinero, los novios, por ejemplo, ponen su n\u00famero de cuenta en las invitaciones\u00bb, explica Mar\u00eda Salas, wedding planner de \u00abSi t\u00fa me dices&#8230;ven\u00bb<\/p>\n<p id=\"U1621123068513JLB\" class=\"p\">En este sentido, si tienes que abrir la cartera en una boda, Salas recuerda, en primer lugar, que la cantidad econ\u00f3mica no depende del tipo de boda, ni de si la fiesta es humilde o lujosa sino \u00abdel nivel de afectividad que tienes con quien te invita\u00bb, se\u00f1ala Salas.<\/p>\n<p id=\"U1621123068513ApH\" class=\"p\">\u00abEl regalo normalmente var\u00eda en funci\u00f3n de la relaci\u00f3n de los novios con los invitados. Es algo muy complicado de elegir y sobre todo acertar porque los gustos y las necesidades de los novios son muy distintas\u00bb, coindicen desde BodaM\u00e1s, del Corte Ingl\u00e9s.<\/p>\n<h4 class=\"ladillo\">Bautizos y comuniones<\/h4>\n<p id=\"U16211230685136NB\" class=\"p\">Sin embargo, y \u00abhablando en plata\u00bb, y por tener una idea aproximada, Salas recomienda dar \u00abentre 150 y 200 euros en el caso de ser amigos y de 500 en el caso de los familiares muy muy cercanos. Si se trata de parientes lejanos, se podr\u00edan dar entre 200 y 300\u00bb. En resumen, la idea es no dar \u00abmenos de 100\u00bb.<\/p>\n<p id=\"U1621123068513Wz\" class=\"p\">Desde BodaM\u00e1s, aseguran, que aparte de la aportaci\u00f3n econ\u00f3mica, tambi\u00e9n se sigue usando la lista de boda, sobre todo \u00abporque a\u00fan hay muchos novios que no les gusta dar su cuenta del banco o recibir dinero en met\u00e1lico\u00bb.<\/p>\n<p id=\"U1621123068513G6E\" class=\"p\">Otro mundo se da en el caso de los <a class=\"a\" title=\"bautizos y comuniones\">bautizos y comuniones<\/a>. \u00abEn el caso de los bautizos se est\u00e1 optando menos por los regalos y m\u00e1s por el dinero. Por ejemplo, por pareja se regalan unos 150 euros. A nivel individual podr\u00edan darse unos 50\u00bb, recomienda Salas.<\/p>\n<p class=\"p\">En el caso de las comuniones, al tratarse de ni\u00f1os m\u00e1s mayores, s\u00ed que el regalo suele ser una opci\u00f3n \u00fatil. Aunque si se opta, una vez m\u00e1s, por el dinero, podr\u00eda optarse por unos 80 o 90 euros por persona.\u00abHay muchas comuniones en las que los padres prefieren dinero porque el ni\u00f1o \u00abtiene de todo\u00bb, pero siempre les hace ilusi\u00f3n abrir paquetes\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llega el buen tiempo y con \u00e9l, las celebraciones. Es esta una fecha perfecta para que las parejas se unan, los j\u00f3venes hagan su primera Comuni\u00f3n y los ni\u00f1os sean bautizados.<\/p>\n","protected":false},"author":12,"featured_media":43897,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-43896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=43896"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43896\/revisions"}],"predecessor-version":[{"id":43898,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43896\/revisions\/43898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/43897"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=43896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=43896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=43896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}