{"id":43967,"date":"2015-05-27T12:00:51","date_gmt":"2015-05-27T16:00:51","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=43967"},"modified":"2015-05-27T10:06:26","modified_gmt":"2015-05-27T14:06:26","slug":"instituciones-unen-esfuerzos-para-llevar-el-mensaje-sonrie-eres-puerto-plata-a-los-residentes-del-municipio-sosua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/instituciones-unen-esfuerzos-para-llevar-el-mensaje-sonrie-eres-puerto-plata-a-los-residentes-del-municipio-sosua\/","title":{"rendered":"Instituciones unen esfuerzos para llevar el mensaje \u201cSonr\u00ede Eres Puerto Plata\u201d a los residentes del municipio Sos\u00faa"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/26-26-12-13-55-4585697.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-43968 size-full aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/26-26-12-13-55-4585697.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/26-26-12-13-55-4585697.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/26-26-12-13-55-4585697-300x225.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/26-26-12-13-55-4585697-100x75.jpg 100w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>Con el objetivo de lograr un mayor alcance con la campa\u00f1a de concientizaci\u00f3n tur\u00edstica \u201cSonr\u00ede Eres Puerto Plata\u201d, la Asociaci\u00f3n de Hoteles, Restaurantes y Empresas Tur\u00edsticas del Norte (ASHONORTE) y la Asociaci\u00f3n de Desarrollo Sostenible de Sos\u00faa (ADSS), aunaron esfuerzos para garantizar el desarrollo Tur\u00edstico Sostenible del Destino Puerto Plata.<!--more--><\/p>\n<p>En este sentido, el equipo t\u00e9cnico de ASHONORTE, en compa\u00f1\u00eda del Cl\u00faster Tur\u00edstico del Destino Puerto Plata, realiz\u00f3 la primera de una serie de charlas de concienciaci\u00f3n a la Asociaci\u00f3n de Vendedores de Playa Sos\u00faa y la Asociaci\u00f3n de Artesanos Unidos por Cabarete y Sos\u00faa, la cual fue convocada por Carmen Mariela Parra, Directora Ejecutiva de ADSS.<\/p>\n<p>Seg\u00fan una nota enviada a la redacci\u00f3n de este medio informativo, da cuenta que estas asociaciones, tanto la de Playa Sos\u00faa como la de Artesanos, mostraron gran inter\u00e9s en esta capacitaci\u00f3n, ya que entienden la importancia que tiene el tema de cultura tur\u00edstica para la sostenibilidad de sus negocios.<\/p>\n<p>La directora ejecutiva de la Asociaci\u00f3n de Hoteles, Restaurantes y Empresas Tur\u00edsticas del Norte (ASHONORTE); licenciada Ambra Attus, al dirigirse a los presentes expres\u00f3 su agradecimiento a la Asociaci\u00f3n de Desarrollo Sostenible de Sos\u00faa (ADSS) por el apoyo que est\u00e1 brindando a dicha campa\u00f1a, permitiendo as\u00ed que llegue el mensaje a este grupo tan importante que es quien da la cara al turista d\u00eda tras d\u00eda.<\/p>\n<p>De su lado, la directora ejecutiva de la Asociaci\u00f3n de Desarrollo Sostenible de Sos\u00faa (ADSS); Carmen Mariela Parra, hizo \u00e9nfasis en el compromiso por parte de la entidad que representa y asegur\u00f3 que ese apoyo se seguir\u00e1 incrementando.<\/p>\n<p><a href=\"http:\/\/puertoplatadigital.com\/verNoticia.aspx?Id=18791\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el objetivo de lograr un mayor alcance con la campa\u00f1a de concientizaci\u00f3n tur\u00edstica \u201cSonr\u00ede Eres Puerto Plata\u201d, la Asociaci\u00f3n de Hoteles, Restaurantes y Empresas Tur\u00edsticas del Norte (ASHONORTE) y la Asociaci\u00f3n de Desarrollo Sostenible de Sos\u00faa (ADSS), aunaron esfuerzos para garantizar el desarrollo Tur\u00edstico Sostenible del Destino Puerto Plata.<\/p>\n","protected":false},"author":12,"featured_media":43968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-43967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=43967"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43967\/revisions"}],"predecessor-version":[{"id":43969,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/43967\/revisions\/43969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/43968"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=43967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=43967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=43967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}