{"id":44024,"date":"2015-05-29T05:22:37","date_gmt":"2015-05-29T09:22:37","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=44024"},"modified":"2015-05-29T05:22:37","modified_gmt":"2015-05-29T09:22:37","slug":"tener-sexo-dos-veces-por-semana-te-alarga-la-vida","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/tener-sexo-dos-veces-por-semana-te-alarga-la-vida\/","title":{"rendered":"Tener sexo dos veces por semana te alarga la vida"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-long field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/fileaccesshandler_11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-44025 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/fileaccesshandler_11.jpg\" alt=\"fileaccesshandler_11\" width=\"472\" height=\"308\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/fileaccesshandler_11.jpg 636w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/fileaccesshandler_11-300x196.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/fileaccesshandler_11-105x69.jpg 105w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/fileaccesshandler_11-400x260.jpg 400w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/a>Una investigaci\u00f3n realizada en el Reino Unido arroj\u00f3 como resultado que, los hombres que tienen relaciones sexuales con frecuencia tienen una esperanza de vida de hasta diez a\u00f1os mayor que aquellos que no lo hacen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"content\">\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>El seguimiento de los sujetos sometidos al estudio, comprendidos en un rango de edad de entre 45 y 59 a\u00f1os, permitieron comprobar el riesgo de muerte para las hombres que tienen orgasmos con regularidad es de 50 por ciento menos que en otros varones que no llevan una vida sexual tan activa, destaca el sitio unosantafe.com.ar.<\/p>\n<p>\u00abTener sexo al menos dos veces a la semana puede hacer que la edad biol\u00f3gica de una persona sea 1.6 a\u00f1os m\u00e1s joven, en comparaci\u00f3n con una persona que tiene sexo s\u00f3lo una vez a la semana. Esto significa que el sexo podr\u00eda mantener tu cuerpo m\u00e1s joven, independientemente de tu edad cronol\u00f3gica\u00bb, se\u00f1al\u00f3 David Weeks, l\u00edder de la investigaci\u00f3n que trabaja en el Royal Hospital of Edimburgh.<\/p>\n<p>Weeks revel\u00f3 que las cinco principales conclusiones de la investigaci\u00f3n son las siguientes:<\/p>\n<p>1. Las personas que luc\u00edan m\u00e1s j\u00f3venes expresaron tener en promedio un 50 por ciento m\u00e1s de sexo que las personas que luc\u00edan mayores, es decir, 3 veces a la semana en vez de 2 veces.<\/p>\n<p>2. Estas personas pod\u00edan lucir entre 5 y 7 a\u00f1os m\u00e1s j\u00f3venes que las personas de su misma edad cronol\u00f3gica que ten\u00edan menos sexo.<\/p>\n<p>3. El sexo con regularidad puede reducir los riesgos de morir a edad temprana.<\/p>\n<p>4. Tener sexo tres o m\u00e1s veces a la semana puede alargar la vida de una persona en diez a\u00f1os m\u00e1s.<\/p>\n<p>5. Tener relaciones \u00edntimas al menos dos veces a la semana puede reducir la edad biolog\u00edca de un hombre 1,6 a\u00f1os.<\/p>\n<p><strong>Fuente:<\/strong> <a href=\"http:\/\/www.cronica.com.ar\/article\/details\/33170\/tener-sexo-2-veces-por-semana-te-alarga-la-vida\" target=\"_blank\">Cr\u00f3nica<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Una investigaci\u00f3n realizada en el Reino Unido arroj\u00f3 como resultado que, los hombres que tienen relaciones sexuales con frecuencia tienen una esperanza de vida de hasta diez a\u00f1os mayor que aquellos que no lo hacen.<\/p>\n","protected":false},"author":12,"featured_media":44025,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-44024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=44024"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44024\/revisions"}],"predecessor-version":[{"id":44026,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/44024\/revisions\/44026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/44025"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=44024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=44024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=44024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}